{"id":145657,"date":"2025-04-24T16:22:27","date_gmt":"2025-04-24T14:22:27","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?post_type=event-multi&#038;p=145657"},"modified":"2025-08-26T17:30:18","modified_gmt":"2025-08-26T15:30:18","slug":"durchlueften-2025","status":"publish","type":"event-multi","link":"https:\/\/www.humboldtforum.org\/de\/programm\/event\/festival\/durchlueften-2025-145657\/","title":{"rendered":"DURCHL\u00dcFTEN 2025"},"content":{"rendered":"<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><h3>DURCHL\u00dcFTEN 2025 \u2013 ein transkulturelles Sounderlebnis<\/h3>\n<p>Umsonst und drau\u00dfen unter freiem Berliner Himmel tanzen und genie\u00dfen: Zum f\u00fcnften Mal verwandelt DURCHL\u00dcFTEN den Schl\u00fcterhof in ein gro\u00dfes Musikfestival. An vier Wochenenden feiern Berliner K\u00fcnstler*innen und internationale G\u00e4ste die Vielfalt globaler Musikkulturen, von der rohen Energie des mexikanischen Cumbia-Punks \u00fcber den hypnotischen Puls des kenianischen Dodo Blues, von souligem Jazz bis hin zu Hip-Hop und japanischem Folk mit karibischem Einfluss. Unter dem Motto \u201eKultur f\u00fcr alle\u201c bleibt DURCHL\u00dcFTEN kostenlos und offen f\u00fcr alle \u2013 ein genre\u00fcbergreifendes Fest f\u00fcr Musik, Tanz und kulinarische Entdeckungen, kuratiert von der Musikexpertin Melissa Perales.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><h4>17. JULI \u2013 9. AUGUST 2025 | DONNERSTAG BIS SAMSTAG | ab 19:00<\/h4>\n<p>Das Festival wird am <strong>17. Juli 2025 um 18:30<\/strong> Uhr von Melissa Perales, Kuratorin des Festivals und Hartmut Dorgerloh, Generalintendant des Humboldt Forums er\u00f6ffnet.\u00a0Im Anschluss wird<strong>\u00a0<\/strong>Logan February, \u201ePoet in Residence\u201c aus Nigeria, ein Gedicht pr\u00e4sentieren.<\/p>\n<p>Mit insgesamt 24 Live-Acts und 12 DJs ist jeder der 12 Abende eine Reise durch vielf\u00e4ltige musikalische Landschaften \u2013 durch die belebten Stra\u00dfen von Mexiko-Stadt, in die W\u00fcstenn\u00e4chte von Niger, zu den pulsierenden Beats von Nairobi oder den verborgenen Grooves von Tokio \u2013 bevor es zur\u00fcck ins Herz der sich st\u00e4ndig weiterentwickelnden Berliner Clubkultur geht.<\/p>\n<p>DURCHL\u00dcFTEN ist mehr als nur ein Festival. Es schafft einen offenen, gemeinschaftlichen Raum, in dem Musik zu einer Sprache der Verbindung wird. Das Festival findet an einem Ort statt, der tief in die vielschichtige Geschichte Berlins verwoben ist und an dem Cultural Belongings aus vielen Kulturen der Welt gesammelt sind. Es l\u00e4dt zum Nachdenken \u00fcber Bewegung ein \u2013 von Menschen, Kl\u00e4ngen und Erz\u00e4hlungen. So wird der Schl\u00fcterhof zu einer B\u00fchne, auf der globale Stimmen zusammenkommen, um kulturelle R\u00e4ume durch Klang zur\u00fcckzugewinnen und neu zu gestalten.<\/p>\n<p>Und das Beste daran? DURCHL\u00dcFTEN ist kostenlos, im Freien und f\u00fcr alle da. Ob zum Tanzen, zum Entdecken neuer Kl\u00e4nge oder einfach zum Genie\u00dfen eines warmen Berliner Abends &#8211; alle sind willkommen!<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h4\">Line-Up<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Ahmedou Ahmed Lowla (Mauretanien) | Charif Megarbane (Beirut) | Caf\u00e9 Chocolat mit Batila &amp; The DreamBus und G\u00e4sten (Berlin) | Ekowmania &amp; The Rhythmers (Ghana, Berlin) | Etran de L&#8217;A\u00efr (Niger) | Florence Adooni (Ghana) | Gotopo (Venezuela, Berlin) | Ibelisse Guardia Ferragutti &amp; Frank Rosaly (Bolivien, Brasilien, Puerto Rico, Amsterdam) | Jaliya (Berlin) | Jeano Elong &amp; Not OK Jazz (Kamerun, Hamburg) | Kabeaush\u00e9 (Berlin, Nairobi) | Kasiva Mutua (Nairobi) | Lollise (Botswana, USA) | Minyo Crusaders (Japan) | Mourning [A] BLKstar (USA) | Natalie Gre\ufb00el (Mosambik, D\u00e4nemark, Berlin) | ODD OKODDO feat. Ogoya Nengo (Kenia, Deutschland) | Otis Mensah (She\ufb03eld, Berlin) | Sera Kalo\u2019s eX.II (Berlin, USA) | Sophye Soliveau (Frankreich) | Son Rompe Pera (Mexiko) | Sorvina (USA, Berlin) | Tosh\u00edn (Irland, Nigeria, Berlin) &amp; Er\u00f6ffnung und Abschluss des Festivals mit den Poet*innen Logan February (Nigeria) <span data-olk-copy-source=\"MessageBody\">&amp; Regina Riveros (Venezuela, Berlin)<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h4\">DJs<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>ASA Collect (Berlin) | Ben Olayinka (Berlin, Nigeria) | Booty Carrell (M\u00fcnchen) | Chi aka Robert Machiri (Simbabwe, S\u00fcdafrika) | Shiru (Berlin) | Femdelic (Berlin) | In Living Color (Kenia, Nigeria, Berlin) | KILLA (Berlin) | mokeyanju (Berlin) | Radio Hobo (Venezuela, Berlin) | Sebcat (Rebel Up) (Br\u00fcssel) | Selektor Bony (Mexiko, Berlin)<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-header\" >\n\t<block-header inline-template>\n\t\t<figure role=\"group\" aria-labelledby=\"desc_m_6a040071586f1\">\n\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes_d\" : {\"medium\":{\"file\":\"SHF_eb00228319-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23543},\"large\":{\"file\":\"SHF_eb00228319-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":178794},\"thumbnail\":{\"file\":\"SHF_eb00228319-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":10011},\"medium_large\":{\"file\":\"SHF_eb00228319-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":114391},\"small\":{\"file\":\"SHF_eb00228319-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":45658},\"semi\":{\"file\":\"SHF_eb00228319-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":72854},\"mobile\":{\"file\":\"SHF_eb00228319-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":102801},\"original\":{\"file\":\"SHF_eb00228319.jpg\",\"width\":1280,\"height\":853}},\n\t\t\t\t\"alt_d\" : \"Tanzende Besucher*innen beim Festival DURCHL\\u00dcFTEN\",\n\t\t\t\t\"path_d\" : \"\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/\",\n\t\t\t\t\"autoplay_d\" : null,\n\t\t\t\t\"crop_d\" : {\"top\":\"58.54\",\"left\":\"49.70\"},\n\t\t\t\t\"background_d\" : true,\n\t\t\t\t\"scale_d\" : 2,\n\n\t\t\t\t\"sizes_m\" : [],\n\t\t\t\t\"alt_m\" : null,\n\t\t\t\t\"path_m\" : null,\n\t\t\t\t\"autoplay_m\" : null,\n\t\t\t\t\"crop_m\" : null,\n\t\t\t\t\"background_m\" : true,\n\t\t\t\t\"scale_m\" : 1,\n\n\t\t\t\t\"has_mobile_format\" : false,\n\t\t\t\t\"has_ad\" : false,\n\t\t\t\t\"audio_description_yt\" : null\t\t\t\t}\n\t\t\t<\/script>\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.640625%;\" v-if=\"sizes\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t<lazy-media :inline=\"true\" :scale=\"scale\" :alt=\"alt\" :sizes=\"sizes\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_m_6a040071586f1\"><\/lazy-media>\n\t\t\t\t<button class=\"autoplay-audio-description-btn icon-background icon-audio-describtions\" @click=\"audioDescriptionPlay\" v-if=\"hasAudioDescription\" aria-label=\"Audiodeskription aufrufen\"><\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny insignificant\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_m_6a040071586f1\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t<div>Durchl&uuml;ften &ndash; Open Air im Schl&uuml;terhof im Humboldt Forum im Berliner Schloss am 18. Juli 2024.\nUstad Noor Bakhsh (Belutschistan \/ Pakistan)<\/div>\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Foto: Stefanie Loos<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t<\/block-header>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h5\">Ein pers\u00f6nliches Wort von der Kuratorin, Melissa Perales<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row margin-bottom-sixth\">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>&#8222;Die Mission von DURCHL\u00dcFTEN ist es, nicht nur eine gro\u00dfartige Veranstaltung auf die Beine zu stellen, sondern kulturelle Br\u00fccken zu bauen, um damit K\u00fcnstler*innen aus allen Teilen der Welt, lokale Talente und Mitglieder der europ\u00e4ischen Diaspora zusammenzubringen. Ihren Geschichten, Sprachen und musikalischen Traditionen geben wir jenseits des herk\u00f6mmlichen Museums Raum. Wir wollen Kultur im Moment erfahrbar machen und diesen mit anderen teilen. Die K\u00fcnstler*innen haben in der Mitte Berlins die M\u00f6glichkeit, Verbindungen zu neuen Publikumsgruppen aufzubauen und mit ihnen ihre Kunst au\u00dferhalb kommerzieller Kontexte zu teilen. So entsteht ein globaler und zugleich lokaler Dialog durch Musik.<\/p>\n<p>Mein Ziel als Kuratorin ist es dieses Jahr, kraftvolle K\u00fcnstler*innen aus Afrika, S\u00fcdamerika, Asien und dar\u00fcber hinaus in den Fokus zu r\u00fccken und gleichzeitig zu untersuchen, wie einige dieser K\u00fcnstler*innen ihre Traditionen in neue Heimaten mitbringen, sie neu interpretieren und in neue musikalische Identit\u00e4ten einweben, ohne dabei das Wesen ihrer klanglichen Herkunft zu verlieren. Hybridit\u00e4t in der Musik ist das Thema 2025. Das Festival ehrt die Wurzeln dieser Kl\u00e4nge und nimmt zugleich ihre Weiterentwicklung an, indem es zeigt, wie Musik Grenzen \u00fcberwindet und zu unserer gemeinsamen menschlichen Erfahrung spricht.<\/p>\n<p>In einer Welt, die immer kleiner wird, wird zunehmend deutlich, wie eng wir alle miteinander verbunden sind \u2013 und wie sehr die Geschichten einer jeden Kultur auf der globalen B\u00fchne nachhallen.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"row margin-bottom-sixth\">\n\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<read-more inline-template>\n\t\t\t\t\t\t\t<div class=\"copy margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t<div ref=\"body\" style=\"height:0;overflow: hidden;display: none;\">\n\t\t\t\t\t\t\t\t\t<div class=\"margin-bottom-sixth\"><p>Eine pers\u00f6nliche Anmerkung: Als mexikanisch-amerikanische Kuratorin, die in Deutschland lebt, ist es mir sehr wichtig, mich f\u00fcr Inklusivit\u00e4t in der Kunst einzusetzen. Seit 2021 verschreibt sich DURCHL\u00dcFTEN der Freude an musikalischer Erkundung \u2013 das Festival vereint Kl\u00e4nge und Geschichten \u00fcber Grenzen hinweg und feiert die lebendige Vielfalt, die uns umgibt. Mein Ziel ist es, einen Raum zu schaffen, in dem sich K\u00fcnstler*innen und G\u00e4ste wirklich verbunden f\u00fchlen \u2013 einen Ort, an dem jede*r die eigene Geschichte beitragen kann. Ebenso wichtig ist mir, dass DURCHL\u00dcFTEN seinem Anspruch auf Zug\u00e4nglichkeit treu bleibt: ein niedrigschwelliger Kulturraum, offen und einladend f\u00fcr alle. In diesen unsicheren Zeiten ist es entscheidend, Wege zu finden, gemeinsam wieder ins Gleichgewicht zu kommen und sich eine Welt vorzustellen, in der wir gemeinsam leben m\u00f6chten. Zuh\u00f6ren und Raum miteinander zu teilen ist aus meiner Sicht der erste Schritt auf diesem Weg.<\/p>\n<p>Es ist mir eine gro\u00dfe Ehre, das diesj\u00e4hrige Programm zu kuratieren und so viele au\u00dfergew\u00f6hnliche Geschichtenerz\u00e4hler*innen von Berliner und internationalen B\u00fchnen zusammenzubringen. Diese einmonatige Reise feiert die Musik in all ihren Facetten \u2013 zw\u00f6lf Sommerabende, an denen wir zuh\u00f6ren, einander begegnen, l\u00e4cheln und nat\u00fcrlich tanzen. F\u00fcr alle Musikliebhaber*innen und Plattensammler*innen haben wir ein tolles Programm zusammengestellt \u2013 bringen Sie Freund*innen und Familie mit, und lassen Sie uns gemeinsam neue Samen f\u00fcr Verbindung und Lebensfreude s\u00e4en.<br \/>\nIch freue mich darauf, mit Ihnen zu feiern! \u2014&#8220;<\/p>\n<p>Melissa Perales, Kuratorin<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a ref=\"toggleButton\" class=\"Button\" @click=\"toggle\">\n\t\t\t\t\t\t\t\t\t<span v-if=\"!active\">mehr lesen<\/span>\n\t\t\t\t\t\t\t\t\t<span v-else>weniger lesen<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/read-mode>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-header\" >\n\t<block-header inline-template>\n\t\t<figure role=\"group\" aria-labelledby=\"desc_m_6a0400715c84e\">\n\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes_d\" : {\"medium\":{\"file\":\"SHF_eb00201762-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":13252},\"large\":{\"file\":\"SHF_eb00201762-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":82855},\"thumbnail\":{\"file\":\"SHF_eb00201762-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6477},\"medium_large\":{\"file\":\"SHF_eb00201762-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":53120},\"small\":{\"file\":\"SHF_eb00201762-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23370},\"semi\":{\"file\":\"SHF_eb00201762-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35550},\"mobile\":{\"file\":\"SHF_eb00201762-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":48133},\"hd\":{\"file\":\"SHF_eb00201762-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\",\"filesize\":117211},\"full\":{\"file\":\"SHF_eb00201762-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":235206},\"1536x1536\":{\"file\":\"SHF_eb00201762-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":158650},\"2048x2048\":{\"file\":\"SHF_eb00201762-2048x1366.jpg\",\"width\":2048,\"height\":1366,\"mime-type\":\"image\\\/jpeg\",\"filesize\":266230},\"original\":{\"file\":\"SHF_eb00201762.jpg\",\"width\":4048,\"height\":2699}},\n\t\t\t\t\"alt_d\" : \"GOTOPO beim Performen auf der B\\u00fchne\",\n\t\t\t\t\"path_d\" : \"\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/\",\n\t\t\t\t\"autoplay_d\" : null,\n\t\t\t\t\"crop_d\" : {\"top\":\"38.27\",\"left\":\"26.44\"},\n\t\t\t\t\"background_d\" : true,\n\t\t\t\t\"scale_d\" : 2,\n\n\t\t\t\t\"sizes_m\" : [],\n\t\t\t\t\"alt_m\" : null,\n\t\t\t\t\"path_m\" : null,\n\t\t\t\t\"autoplay_m\" : null,\n\t\t\t\t\"crop_m\" : null,\n\t\t\t\t\"background_m\" : true,\n\t\t\t\t\"scale_m\" : 1,\n\n\t\t\t\t\"has_mobile_format\" : false,\n\t\t\t\t\"has_ad\" : false,\n\t\t\t\t\"audio_description_yt\" : null\t\t\t\t}\n\t\t\t<\/script>\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.674901185771%;\" v-if=\"sizes\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t<lazy-media :inline=\"true\" :scale=\"scale\" :alt=\"alt\" :sizes=\"sizes\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_m_6a0400715c84e\"><\/lazy-media>\n\t\t\t\t<button class=\"autoplay-audio-description-btn icon-background icon-audio-describtions\" @click=\"audioDescriptionPlay\" v-if=\"hasAudioDescription\" aria-label=\"Audiodeskription aufrufen\"><\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny insignificant\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_m_6a0400715c84e\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t<div>GOTOPO bei Durchl&uuml;ften 2023 im Schl&uuml;terhof des Humboldt Forums<\/div>\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss, Foto: Frank Sperling<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t<\/block-header>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h4\">Festival-Highlights<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row margin-bottom-sixth\">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Dieses Jahr setzen wir unsere Partnerschaften mit au\u00dfergew\u00f6hnlichen Veranstaltungen wie dem renommierten Festival in Sansibar Sauti Za Busara und Berlins international gefeiertem XJAZZ-Festival fort. Diese Kollaborationen helfen uns, nachhaltige Netzwerke aufzubauen, die K\u00fcnstler*innen und Fans aus aller Welt miteinander verbinden.<\/p>\n<p>Zu den vielen K\u00fcnstler*innen, die Grenzen \u00fcberschreiten und Kl\u00e4nge miteinander verschmelzen, geh\u00f6rt\u00a0<strong>ODD OKODDO<\/strong>, ein kenianisch-deutsches Duo mit Olith Ratego und Sven Kacirek. Ratego, der im souligen Dodo-Stil vom Viktoriasee singt, nennt seine Musik \u201eDodo Blues\u201c, w\u00e4hrend Kacireks Produktionsexpertise eine einzigartige Mischung aus kenianischen und deutschen Einfl\u00fcssen schafft. W\u00e4hrend ihrer Europatour 2025 werden sie von der legend\u00e4ren\u00a0<strong>Ogoya Nengo<\/strong> begleitet, der K\u00f6nigin der Luo-Musik, deren kraftvolle Stimme traditionelle Luo-Zeremonien seit Jahrzehnten gepr\u00e4gt hat. Mit 80 Jahren bringt Ogoya eine elektrisierende Energie auf die B\u00fchne.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"row margin-bottom-sixth\">\n\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<read-more inline-template>\n\t\t\t\t\t\t\t<div class=\"copy margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t<div ref=\"body\" style=\"height:0;overflow: hidden;display: none;\">\n\t\t\t\t\t\t\t\t\t<div class=\"margin-bottom-sixth\"><p>Wir freuen uns auch, <strong>Jeano Elong &amp; Not OK Jazz<\/strong> zu pr\u00e4sentieren, einen S\u00e4nger aus Kamerun, der inzwischen in Hamburg lebt. Nach einer lebensver\u00e4ndernden Reise von Kamerun nach Libyen und seiner Teilnahme an den Lampedusa-Protesten in Hamburg vermittelt Jeanos Musik eine kraftvolle Botschaft von Einheit und Frieden. Sein Deb\u00fctalbum Mkoum besingt in seiner Muttersprache Bakaka Br\u00fcderlichkeit und Solidarit\u00e4t.<\/p>\n<p>Der Er\u00f6ffnungsact des Festivals in diesem Jahr: <strong>Minyo Crusaders<\/strong>, eine zehnk\u00f6pfige Band aus Tokio, die traditionelle japanische Volkslieder mit kolumbianischen Cumbia-Rhythmen verbindet. Ihre Zusammenarbeit mit <strong>Frente Cumbiero<\/strong> vereint alte Kl\u00e4nge aus Japan und Kolumbien zu einem unvergesslichen musikalischen Erlebnis.<\/p>\n<p>Weitere spannende Acts umfassen den Multiinstrumentalisten <strong>Charif Megarbane<\/strong> (Libanon), der Soul, Funk, Afrobeats und italienische Vintage-Filmmusik zu einem hypnotischen Mix verschmilzt, sowie das Amsterdamer Duo <strong>Ibelisse Guardia Ferragutti<\/strong> und <strong>Frank Rosaly<\/strong>, die ihre Wurzeln durch eine Mischung aus lateinamerikanischer Folklore, Avant-Jazz und Punk erforschen.<\/p>\n<p>H\u00f6ren Sie au\u00dferdem von <strong>Etran de L\u2019A\u00efr<\/strong>, einer Sahara-Rockband aus Agadez, der Hauptstadt der W\u00fcsten-Gitarrenmusik, die seit \u00fcber 25 Jahren mit ihren hypnotischen W\u00fcstenmelodien das Publikum begeistert.<\/p>\n<p>Schlie\u00dflich sollten Sie <strong>Logan February<\/strong> nicht verpassen, eine*n in Berlin lebende*n nigerianische*n Dichter*in und Performer*in. Februarys multidisziplin\u00e4re Arbeit erforscht die afro-queere diasporische Identit\u00e4t und die Yoruba-Mythologie. Au\u00dferdem die Band <strong>Mourning [A] BLKstar<\/strong>, eine multi-generationale, gender-nonkonforme Gruppe, die kraftvolle Geschichten und Lieder aus Amerikas sich entfaltender Apokalypse pr\u00e4sentiert.<\/p>\n<p>Zum Abschluss des Festivals begr\u00fc\u00dfen wir <strong>Son Rompe Pera<\/strong>, eine Band aus Mexiko-Stadt, die die Grenzen der traditionellen mexikanischen Marimba sprengt. Mit Punk- und Psychobilly-Einfl\u00fcssen haben sie die Marimba neu definiert und ihr eine moderne Note verliehen.<\/p>\n<p>Das sind nur einige der gro\u00dfartigen K\u00fcnstler*innen, die wir in diesem Sommer auf die B\u00fchne bringen. Gemeinsam werden sie ein wundersch\u00f6nes Mosaik aus Kultur, Musik und Geist weben. Verpassen Sie nicht diese unvergessliche Feier des Klangs.<\/p>\n<p>Wir k\u00f6nnen es kaum erwarten, mit Ihnen zu feiern! H\u00f6ren Sie rein:<\/p>\n<p><a href=\"https:\/\/open.spotify.com\/playlist\/0daBQZGErusEMHLWJ94NFA?si=bM97elDVTQ6qrJHtAEuB8Q&amp;pi=WE5X9kHcRf6PG\">Durchl\u00fcften 2025 Soundtrack<\/a><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a ref=\"toggleButton\" class=\"Button\" @click=\"toggle\">\n\t\t\t\t\t\t\t\t\t<span v-if=\"!active\">mehr lesen<\/span>\n\t\t\t\t\t\t\t\t\t<span v-else>weniger lesen<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/read-mode>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-standard-two-images \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-4\">\n\t\t\t\t<div class=\"box first-image\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-20,20]}}'>\n\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a040071629a4\" aria-labelledby=\"desc_media_6a040071629a4\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00246254-236x300.jpg\",\"width\":236,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":13205},\"large\":{\"file\":\"SHF_eb00246254-804x1024.jpg\",\"width\":804,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":112731},\"thumbnail\":{\"file\":\"SHF_eb00246254-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":5651},\"medium_large\":{\"file\":\"SHF_eb00246254-768x978.jpg\",\"width\":768,\"height\":978,\"mime-type\":\"image\\\/jpeg\",\"filesize\":104273},\"small\":{\"file\":\"SHF_eb00246254-346x440.jpg\",\"width\":346,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":24840},\"semi\":{\"file\":\"SHF_eb00246254-456x580.jpg\",\"width\":456,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":40601},\"mobile\":{\"file\":\"SHF_eb00246254-566x720.jpg\",\"width\":566,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":59283},\"hd\":{\"file\":\"SHF_eb00246254-1005x1280.jpg\",\"width\":1005,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":169190},\"full\":{\"file\":\"SHF_eb00246254-1508x1920.jpg\",\"width\":1508,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":348623},\"1536x1536\":{\"file\":\"SHF_eb00246254-1207x1536.jpg\",\"width\":1207,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":235299},\"original\":{\"file\":\"SHF_eb00246254.jpg\",\"width\":1571,\"height\":2000}},\n\t\t\t\t\"alt\" : \"Seitliches Profil von Kasiva Mutua\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"55.50\",\"left\":\"74.63\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:127.30744748568%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a040071629a4\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_media_6a040071629a4\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Die kenianische Musikerin Kasiva Mutua<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Ellie Obati<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"copy\">\n\t\t\t\t\t<p class=\"Moderation\"><\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-md-8 second-image\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a04007162af2\" aria-labelledby=\"desc_media_6a04007162af2\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00247107-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":11332},\"large\":{\"file\":\"SHF_eb00247107-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":80310},\"thumbnail\":{\"file\":\"SHF_eb00247107-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6922},\"medium_large\":{\"file\":\"SHF_eb00247107-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":50249},\"small\":{\"file\":\"SHF_eb00247107-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":20875},\"semi\":{\"file\":\"SHF_eb00247107-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":32543},\"mobile\":{\"file\":\"SHF_eb00247107-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":45021},\"hd\":{\"file\":\"SHF_eb00247107-1280x854.jpg\",\"width\":1280,\"height\":854,\"mime-type\":\"image\\\/jpeg\",\"filesize\":114866},\"1536x1536\":{\"file\":\"SHF_eb00247107-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":152426},\"original\":{\"file\":\"SHF_eb00247107.jpg\",\"width\":1600,\"height\":1067}},\n\t\t\t\t\"alt\" : \"Mitglieder der Band Minyo Crusaders mit Gitarre beim Auftritt\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"50.00\",\"left\":\"50.00\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.6875%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a04007162af2\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_media_6a04007162af2\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Die japanische Band Minyo Crusaders beim World Music Festival Taiwan<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Eric van Nieuwland<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-teaser  col-lane16\" style=\"\">\n\t<upcoming-filtered from=\"20250717\" to=\"20250719\" genre=\"\" belongsto=\"145657\" lang=\"de\" inline-template>\n\t\t<div ref=\"heightReference\">\n\t\t<teaser-lane-with-buttons inline-template ref=\"lane\" tracking-label=\"Upcoming events\" v-if=\"weeks.length\">\n\t\t\t<div class=\"teaser-lane-with-buttons\">\n\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-10 margin-bottom-sixth\">\n\t\t\t\t\t\t\t<h3><\/h3>\n\t\t\t\t\t\t\t<div class=\"toggle_menu\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<template v-if=\"$parent.weeks.length ===1\">\n\t\t\t\t\t\t\t\t\t<button :data-week=\"99\" class=\"h5 active\"><span class=\"button-label-line bigger\">\n\t\t\t\t\t\t\t\t\t\t<week :start=\"$parent.from\" :end=\"$parent.to\" :from-this-week=\"99\"><\/week>\n\t\t\t\t\t\t\t\t\t<\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t\t<template v-else v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t\t\t<button v-if=\"week.events.length\" :class=\"{'active' : $parent.currentWeek==index}\" :data-week=\"index\" @click.prevent=\"$parent.setWeek(index)\" class=\"h5\"><span class=\"button-label-line bigger\"><week :start=\"week.start\" :end=\"week.end\" :from-this-week=\"week.fromThisWeek\"><\/week><\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-2 start-xs end-md margin-bottom-sixth teaser-lane-buttons-wrapper teaser-lane-buttons-wrapper-with-tax\">\n\t\t\t\t\t\t\t<teaser-lane-buttons :visible_prev=\"visible_prev\" :visible_next=\"visible_next\" @prev=\"prev\" @next=\"next\"><\/teaser-lane-buttons>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"teaser-lane-wrapper\" v-if=\"$parent.events\">\n\t\t\t\t\t<ul class=\"teaser-lane\"  v-if=\"!$parent.loading\">\n\t\t\t\t\t\t<template v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t<template v-if=\"index === $parent.currentWeek\" v-for=\"item in week.events\">\n\t\t\t\t\t\t\t\t<calendarteaser :force-date=\"item.date | formatDateAndTimeShort\" v-bind:key=\"item.ID+' '+item.TS\" :rawitem=\"item.event\" cols=\"lane16\"><\/calendarteaser>\n\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t<\/template>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div v-else-if=\"$parent.loading\" class=\"teaser-lane-empty\"><div style=\"min-height: 100px\" class=\" jumpingdots\"><\/div><\/div>\n\t\t\t\t\t<div v-else class=\"teaser-lane-empty\">\n\t\t\t\t\t\t<div class=\"hideBeforeLoaded\">\n\n\t\t\t\t\t\t\t<a :href=\"'https:\/\/www.humboldtforum.org\/de\/programm\/?start='+$parent.today+'&amp;end='+$parent.in2Weeks\" class=\"small \" role=\"button\">Zum Kalender<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/teaser-lane-with-buttons>\n\t\t<\/div>\n\t<\/upcoming-filtered>\n<\/section>\n\n\n\n<section class=\"block block-teaser  col-lane16\" style=\"\">\n\t<upcoming-filtered from=\"20250724\" to=\"20250726\" genre=\"\" belongsto=\"145657\" lang=\"de\" inline-template>\n\t\t<div ref=\"heightReference\">\n\t\t<teaser-lane-with-buttons inline-template ref=\"lane\" tracking-label=\"Upcoming events\" v-if=\"weeks.length\">\n\t\t\t<div class=\"teaser-lane-with-buttons\">\n\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-10 margin-bottom-sixth\">\n\t\t\t\t\t\t\t<h3><\/h3>\n\t\t\t\t\t\t\t<div class=\"toggle_menu\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<template v-if=\"$parent.weeks.length ===1\">\n\t\t\t\t\t\t\t\t\t<button :data-week=\"99\" class=\"h5 active\"><span class=\"button-label-line bigger\">\n\t\t\t\t\t\t\t\t\t\t<week :start=\"$parent.from\" :end=\"$parent.to\" :from-this-week=\"99\"><\/week>\n\t\t\t\t\t\t\t\t\t<\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t\t<template v-else v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t\t\t<button v-if=\"week.events.length\" :class=\"{'active' : $parent.currentWeek==index}\" :data-week=\"index\" @click.prevent=\"$parent.setWeek(index)\" class=\"h5\"><span class=\"button-label-line bigger\"><week :start=\"week.start\" :end=\"week.end\" :from-this-week=\"week.fromThisWeek\"><\/week><\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-2 start-xs end-md margin-bottom-sixth teaser-lane-buttons-wrapper teaser-lane-buttons-wrapper-with-tax\">\n\t\t\t\t\t\t\t<teaser-lane-buttons :visible_prev=\"visible_prev\" :visible_next=\"visible_next\" @prev=\"prev\" @next=\"next\"><\/teaser-lane-buttons>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"teaser-lane-wrapper\" v-if=\"$parent.events\">\n\t\t\t\t\t<ul class=\"teaser-lane\"  v-if=\"!$parent.loading\">\n\t\t\t\t\t\t<template v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t<template v-if=\"index === $parent.currentWeek\" v-for=\"item in week.events\">\n\t\t\t\t\t\t\t\t<calendarteaser :force-date=\"item.date | formatDateAndTimeShort\" v-bind:key=\"item.ID+' '+item.TS\" :rawitem=\"item.event\" cols=\"lane16\"><\/calendarteaser>\n\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t<\/template>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div v-else-if=\"$parent.loading\" class=\"teaser-lane-empty\"><div style=\"min-height: 100px\" class=\" jumpingdots\"><\/div><\/div>\n\t\t\t\t\t<div v-else class=\"teaser-lane-empty\">\n\t\t\t\t\t\t<div class=\"hideBeforeLoaded\">\n\n\t\t\t\t\t\t\t<a :href=\"'https:\/\/www.humboldtforum.org\/de\/programm\/?start='+$parent.today+'&amp;end='+$parent.in2Weeks\" class=\"small \" role=\"button\">Zum Kalender<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/teaser-lane-with-buttons>\n\t\t<\/div>\n\t<\/upcoming-filtered>\n<\/section>\n\n\n\n<section class=\"block block-teaser  col-lane16\" style=\"\">\n\t<upcoming-filtered from=\"20250731\" to=\"20250802\" genre=\"\" belongsto=\"145657\" lang=\"de\" inline-template>\n\t\t<div ref=\"heightReference\">\n\t\t<teaser-lane-with-buttons inline-template ref=\"lane\" tracking-label=\"Upcoming events\" v-if=\"weeks.length\">\n\t\t\t<div class=\"teaser-lane-with-buttons\">\n\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-10 margin-bottom-sixth\">\n\t\t\t\t\t\t\t<h3><\/h3>\n\t\t\t\t\t\t\t<div class=\"toggle_menu\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<template v-if=\"$parent.weeks.length ===1\">\n\t\t\t\t\t\t\t\t\t<button :data-week=\"99\" class=\"h5 active\"><span class=\"button-label-line bigger\">\n\t\t\t\t\t\t\t\t\t\t<week :start=\"$parent.from\" :end=\"$parent.to\" :from-this-week=\"99\"><\/week>\n\t\t\t\t\t\t\t\t\t<\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t\t<template v-else v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t\t\t<button v-if=\"week.events.length\" :class=\"{'active' : $parent.currentWeek==index}\" :data-week=\"index\" @click.prevent=\"$parent.setWeek(index)\" class=\"h5\"><span class=\"button-label-line bigger\"><week :start=\"week.start\" :end=\"week.end\" :from-this-week=\"week.fromThisWeek\"><\/week><\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-2 start-xs end-md margin-bottom-sixth teaser-lane-buttons-wrapper teaser-lane-buttons-wrapper-with-tax\">\n\t\t\t\t\t\t\t<teaser-lane-buttons :visible_prev=\"visible_prev\" :visible_next=\"visible_next\" @prev=\"prev\" @next=\"next\"><\/teaser-lane-buttons>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"teaser-lane-wrapper\" v-if=\"$parent.events\">\n\t\t\t\t\t<ul class=\"teaser-lane\"  v-if=\"!$parent.loading\">\n\t\t\t\t\t\t<template v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t<template v-if=\"index === $parent.currentWeek\" v-for=\"item in week.events\">\n\t\t\t\t\t\t\t\t<calendarteaser :force-date=\"item.date | formatDateAndTimeShort\" v-bind:key=\"item.ID+' '+item.TS\" :rawitem=\"item.event\" cols=\"lane16\"><\/calendarteaser>\n\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t<\/template>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div v-else-if=\"$parent.loading\" class=\"teaser-lane-empty\"><div style=\"min-height: 100px\" class=\" jumpingdots\"><\/div><\/div>\n\t\t\t\t\t<div v-else class=\"teaser-lane-empty\">\n\t\t\t\t\t\t<div class=\"hideBeforeLoaded\">\n\n\t\t\t\t\t\t\t<a :href=\"'https:\/\/www.humboldtforum.org\/de\/programm\/?start='+$parent.today+'&amp;end='+$parent.in2Weeks\" class=\"small \" role=\"button\">Zum Kalender<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/teaser-lane-with-buttons>\n\t\t<\/div>\n\t<\/upcoming-filtered>\n<\/section>\n\n\n\n<section class=\"block block-teaser  col-lane16\" style=\"\">\n\t<upcoming-filtered from=\"20250807\" to=\"20250809\" genre=\"\" belongsto=\"145657\" lang=\"de\" inline-template>\n\t\t<div ref=\"heightReference\">\n\t\t<teaser-lane-with-buttons inline-template ref=\"lane\" tracking-label=\"Upcoming events\" v-if=\"weeks.length\">\n\t\t\t<div class=\"teaser-lane-with-buttons\">\n\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-10 margin-bottom-sixth\">\n\t\t\t\t\t\t\t<h3><\/h3>\n\t\t\t\t\t\t\t<div class=\"toggle_menu\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<template v-if=\"$parent.weeks.length ===1\">\n\t\t\t\t\t\t\t\t\t<button :data-week=\"99\" class=\"h5 active\"><span class=\"button-label-line bigger\">\n\t\t\t\t\t\t\t\t\t\t<week :start=\"$parent.from\" :end=\"$parent.to\" :from-this-week=\"99\"><\/week>\n\t\t\t\t\t\t\t\t\t<\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t\t<template v-else v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t\t\t<button v-if=\"week.events.length\" :class=\"{'active' : $parent.currentWeek==index}\" :data-week=\"index\" @click.prevent=\"$parent.setWeek(index)\" class=\"h5\"><span class=\"button-label-line bigger\"><week :start=\"week.start\" :end=\"week.end\" :from-this-week=\"week.fromThisWeek\"><\/week><\/span><\/button>\n\t\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-xs-12 col-md-2 start-xs end-md margin-bottom-sixth teaser-lane-buttons-wrapper teaser-lane-buttons-wrapper-with-tax\">\n\t\t\t\t\t\t\t<teaser-lane-buttons :visible_prev=\"visible_prev\" :visible_next=\"visible_next\" @prev=\"prev\" @next=\"next\"><\/teaser-lane-buttons>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"teaser-lane-wrapper\" v-if=\"$parent.events\">\n\t\t\t\t\t<ul class=\"teaser-lane\"  v-if=\"!$parent.loading\">\n\t\t\t\t\t\t<template v-for=\"(week, index) in $parent.weeks\">\n\t\t\t\t\t\t\t<template v-if=\"index === $parent.currentWeek\" v-for=\"item in week.events\">\n\t\t\t\t\t\t\t\t<calendarteaser :force-date=\"item.date | formatDateAndTimeShort\" v-bind:key=\"item.ID+' '+item.TS\" :rawitem=\"item.event\" cols=\"lane16\"><\/calendarteaser>\n\t\t\t\t\t\t\t<\/template>\n\t\t\t\t\t\t<\/template>\n\t\t\t\t\t<\/ul>\n\t\t\t\t\t<div v-else-if=\"$parent.loading\" class=\"teaser-lane-empty\"><div style=\"min-height: 100px\" class=\" jumpingdots\"><\/div><\/div>\n\t\t\t\t\t<div v-else class=\"teaser-lane-empty\">\n\t\t\t\t\t\t<div class=\"hideBeforeLoaded\">\n\n\t\t\t\t\t\t\t<a :href=\"'https:\/\/www.humboldtforum.org\/de\/programm\/?start='+$parent.today+'&amp;end='+$parent.in2Weeks\" class=\"small \" role=\"button\">Zum Kalender<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/teaser-lane-with-buttons>\n\t\t<\/div>\n\t<\/upcoming-filtered>\n<\/section>\n\n\n\n<section class=\"block block-teaser col-3 has-bg\" style=\"--teaser-bg:#f2f2f2\">\n\t<lazy-component :fixed-min-height=\"400\">\n\t\n\t\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t<div class=\"col-xs-12 col-md-8\">\n\t\t\t\t\t\t<h4>Familienprogramm<\/h4>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-xs-12 col-md-4 start-xs end-md margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"row\"> <li class=\"col-xs-12 col-sm-6 col-md-4  teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"8667619579\" rawitem='{&quot;postId&quot;:86676,&quot;title&quot;:&quot;Heute rot, morgen tot&quot;,&quot;excerpt&quot;:&quot;&quot;,&quot;slug&quot;:&quot;heute-rot-morgen-tot&quot;,&quot;post_date&quot;:&quot;2023-06-14T08:19&quot;,&quot;type&quot;:&quot;event&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/termin\\\/schauspiel\\\/heute-rot-morgen-tot-86676\\\/&quot;,&quot;genre&quot;:[823],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Schauspiel&quot;,&quot;id&quot;:823,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;topic&quot;:[433],&quot;topic_details&quot;:[{&quot;text&quot;:&quot;Die Br\\u00fcder Humboldt&quot;,&quot;id&quot;:433,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;stakeholder&quot;:[382],&quot;stakeholder_details&quot;:[{&quot;text&quot;:&quot;Stiftung Humboldt Forum im Berliner Schloss&quot;,&quot;id&quot;:382,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;targetgroup&quot;:[454],&quot;targetgroup_details&quot;:[{&quot;text&quot;:&quot;Kinder und Familien&quot;,&quot;id&quot;:454,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;language&quot;:[384,868],&quot;language_details&quot;:[{&quot;text&quot;:&quot;Deutsch&quot;,&quot;id&quot;:384,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Russisch&quot;,&quot;id&quot;:868,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[510],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Schl\\u00fcterhof&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;hashtag&quot;:&quot;HumboldtForum&quot;,&quot;belongsto&quot;:[33827],&quot;shorturl&quot;:&quot;&quot;,&quot;times&quot;:[],&quot;planning&quot;:{&quot;price&quot;:&quot;4 EUR \\\/ erm\\u00e4\\u00dfigt 2 EUR&quot;,&quot;admission&quot;:&quot;15 Minuten vor Beginn&quot;,&quot;pause&quot;:&quot;&quot;,&quot;duration&quot;:&quot;30&quot;},&quot;subline&quot;:&quot;Geschichten, bei denen versucht wird, den Tod auszutricksen&quot;,&quot;additional_info&quot;:{&quot;icon&quot;:&quot;icon-alterfreigabe&quot;,&quot;text&quot;:&quot;4 bis 99+ Jahre&quot;},&quot;highlight_header&quot;:false,&quot;featured_images&quot;:[86681],&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:true,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;alert_text&quot;:&quot;DE\\\/RU&quot;,&quot;gomus_id&quot;:&quot;&quot;,&quot;hm_id&quot;:&quot;&quot;,&quot;tickettext&quot;:&quot;Bitte buchen Sie Ihr Ticket online vorab oder an der Kasse im Foyer.&quot;,&quot;infotext&quot;:&quot;&quot;},&quot;date&quot;:{&quot;NX&quot;:null,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202601041300&quot;,&quot;from_DATE&quot;:&quot;20260103 13:00&quot;,&quot;from&quot;:1767438000,&quot;to&quot;:1767531600,&quot;to_DATE&quot;:&quot;20260104 15:00&quot;,&quot;from_HRFSHORT&quot;:&quot; 3. Jan 2026&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Sa 03.01.2026&quot;,&quot;to_HRFSHORT&quot;:&quot; 4. Jan 2026&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 04.01.2026&quot;,&quot;from_HRF&quot;:&quot;Sa,  3. Januar 2026&quot;,&quot;to_HRF&quot;:&quot;So,  4. Januar 2026&quot;,&quot;from_to_HRF&quot;:&quot;Sa,  3. Januar \\u2013 So,  4. Januar 2026&quot;,&quot;from_to_HRFSHORT&quot;:&quot; 3. Jan \\u2013  4. Jan 2026&quot;},&quot;alert&quot;:&quot;DE\\\/RU&quot;,&quot;partof&quot;:[33827],&quot;marketing_topic&quot;:{&quot;title&quot;:&quot;Geschichtentheater&quot;,&quot;ID&quot;:33827,&quot;reason&quot;:&quot;sequence&quot;}}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/termin\/schauspiel\/heute-rot-morgen-tot-86676\/\" class=\"teaser teaser-event teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 teaser-event-image\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">DE\/RU<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a04007184154\" aria-labelledby=\"desc_media_6a04007184154\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00193095_un_endlich-300x225.jpg\",\"width\":300,\"height\":225,\"mime-type\":\"image\\\/jpeg\",\"filesize\":9188},\"large\":{\"file\":\"SHF_eb00193095_un_endlich-1024x768.jpg\",\"width\":1024,\"height\":768,\"mime-type\":\"image\\\/jpeg\",\"filesize\":62580},\"thumbnail\":{\"file\":\"SHF_eb00193095_un_endlich-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":4596},\"medium_large\":{\"file\":\"SHF_eb00193095_un_endlich-768x576.jpg\",\"width\":768,\"height\":576,\"mime-type\":\"image\\\/jpeg\",\"filesize\":39124},\"small\":{\"file\":\"SHF_eb00193095_un_endlich-440x330.jpg\",\"width\":440,\"height\":330,\"mime-type\":\"image\\\/jpeg\",\"filesize\":16231},\"semi\":{\"file\":\"SHF_eb00193095_un_endlich-580x435.jpg\",\"width\":580,\"height\":435,\"mime-type\":\"image\\\/jpeg\",\"filesize\":25513},\"mobile\":{\"file\":\"SHF_eb00193095_un_endlich-720x540.jpg\",\"width\":720,\"height\":540,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35579},\"hd\":{\"file\":\"SHF_eb00193095_un_endlich-1280x960.jpg\",\"width\":1280,\"height\":960,\"mime-type\":\"image\\\/jpeg\",\"filesize\":91546},\"full\":{\"file\":\"SHF_eb00193095_un_endlich-1920x1440.jpg\",\"width\":1920,\"height\":1440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":175822},\"1536x1536\":{\"file\":\"SHF_eb00193095_un_endlich-1536x1152.jpg\",\"width\":1536,\"height\":1152,\"mime-type\":\"image\\\/jpeg\",\"filesize\":121874},\"original\":{\"file\":\"SHF_eb00193095_un_endlich.jpg\",\"width\":2000,\"height\":1500}},\n\t\t\t\t\"alt\" : \"Eine Person \\u00f6ffnet eine beleuchtete T\\u00fcr, daneben steht \\\"ES IST DEINE ZEIT\\\". Dunkler Raum mit modernen Akzenten.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:75%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a04007184154\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a04007184154\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Besucherin in der Sonderausstellung &quot;un_endlich&quot;, Akt 3 Tod &#8211; Der finale Moment. Gibt es ein Licht am Ende des Tunnels?<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss, Foto: Alexander Schippel<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant clamp-2\">Geschichtentheater<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom\">Heute rot, morgen tot<\/strong>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"\">Geschichten, bei denen versucht wird, den Tod auszutricksen<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n<li class=\"col-xs-12 col-sm-6 col-md-4  teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"33522816\" rawitem='{&quot;postId&quot;:33522,&quot;title&quot;:&quot;St\\u00e4rke&quot;,&quot;excerpt&quot;:&quot;Auf der Insel Elephanta regiert ein guter M\\u00e4usek\\u00f6nig, der aber leider nicht gl\\u00fccklich ist. Er wei\\u00df nicht, wie ein Elefant aussieht: Ist er gro\\u00df oder klein, stark oder schwach, hat er Fl\\u00fcgel oder Beine? F\\u00fcnf tapfere M\\u00e4use begeben sich nun auf eine abenteuerliche Reise quer durch Indien, in der Hoffnung, dem K\\u00f6nig zu helfen. In Westafrika fragen sich die Tiere, wer denn wohl am St\\u00e4rksten ist. In einem Wettkampf soll dies nun gekl\\u00e4rt werden. Alle Tiere treffen sich und pr\\u00e4sentieren ihre St\\u00e4rken, laut umjubelt und beklatscht. Als der Mensch an der Reihe ist, wird es totenstill. \\u201cWar das St\\u00e4rke?\\u201d fragen sich die Tiere des Waldes \\u00e4ngstlich.&quot;,&quot;slug&quot;:&quot;staerke&quot;,&quot;post_date&quot;:&quot;2021-10-05T14:05&quot;,&quot;type&quot;:&quot;event&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/termin\\\/schauspiel\\\/staerke-33522\\\/&quot;,&quot;genre&quot;:[823],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Schauspiel&quot;,&quot;id&quot;:823,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;stakeholder&quot;:[382],&quot;stakeholder_details&quot;:[{&quot;text&quot;:&quot;Stiftung Humboldt Forum im Berliner Schloss&quot;,&quot;id&quot;:382,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;targetgroup&quot;:[454],&quot;targetgroup_details&quot;:[{&quot;text&quot;:&quot;Kinder und Familien&quot;,&quot;id&quot;:454,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;language&quot;:[384,671],&quot;language_details&quot;:[{&quot;text&quot;:&quot;Deutsch&quot;,&quot;id&quot;:384,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Deutsche Geb\\u00e4rdensprache&quot;,&quot;id&quot;:671,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;accessability&quot;:[921,430],&quot;accessability_details&quot;:[{&quot;text&quot;:&quot;Deutsche Geb\\u00e4rdensprache&quot;,&quot;id&quot;:921,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Rollstuhlgerecht&quot;,&quot;id&quot;:430,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[424,1772],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Saal 3, EG&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;hashtag&quot;:&quot;HumboldtForum&quot;,&quot;shorturl&quot;:&quot;&quot;,&quot;times&quot;:[],&quot;planning&quot;:{&quot;price&quot;:&quot;4 EUR, erm. 2 EUR&quot;,&quot;admission&quot;:&quot;&quot;,&quot;pause&quot;:&quot;&quot;,&quot;duration&quot;:&quot;30&quot;},&quot;subline&quot;:&quot;Eine Geschichte erz\\u00e4hlt in deutscher Geb\\u00e4rdensprache und deutscher Lautsprache von Jan Sell und Kathleen Rappolt&quot;,&quot;shorttext&quot;:&quot;Auf der Insel Elephanta regiert ein guter M\\u00e4usek\\u00f6nig, der aber leider nicht gl\\u00fccklich ist. Er wei\\u00df nicht, wie ein Elefant aussieht: Ist er gro\\u00df oder klein, stark oder schwach, hat er Fl\\u00fcgel oder Beine? F\\u00fcnf tapfere M\\u00e4use begeben sich nun auf eine abenteuerliche Reise quer durch Indien, in der Hoffnung, dem K\\u00f6nig zu helfen. In Westafrika fragen sich die Tiere, wer denn wohl am St\\u00e4rksten ist. In einem Wettkampf soll dies nun gekl\\u00e4rt werden. Alle Tiere treffen sich und pr\\u00e4sentieren ihre St\\u00e4rken, laut umjubelt und beklatscht. Als der Mensch an der Reihe ist, wird es totenstill. \\u201cWar das St\\u00e4rke?\\u201d fragen sich die Tiere des Waldes \\u00e4ngstlich.&quot;,&quot;additional_info&quot;:{&quot;icon&quot;:&quot;icon-alterfreigabe&quot;,&quot;text&quot;:&quot;4 bis 99+ Jahre&quot;},&quot;highlight_header&quot;:false,&quot;featured_images&quot;:[38134,38130,38128,38132],&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:true,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;belongsto&quot;:[33827],&quot;gomus_id&quot;:&quot;&quot;,&quot;hm_id&quot;:&quot;&quot;,&quot;alert_text&quot;:&quot;DGS&quot;},&quot;date&quot;:{&quot;NX&quot;:null,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202603221300&quot;,&quot;from_DATE&quot;:&quot;20260321 13:00&quot;,&quot;from&quot;:1774090800,&quot;to&quot;:1774184400,&quot;to_DATE&quot;:&quot;20260322 15:00&quot;,&quot;from_HRFSHORT&quot;:&quot;21. M\\u00e4r 2026&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Sa 21.03.2026&quot;,&quot;to_HRFSHORT&quot;:&quot;22. M\\u00e4r 2026&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 22.03.2026&quot;,&quot;from_HRF&quot;:&quot;Sa, 21. M\\u00e4rz 2026&quot;,&quot;to_HRF&quot;:&quot;So, 22. M\\u00e4rz 2026&quot;,&quot;from_to_HRF&quot;:&quot;Sa, 21. M\\u00e4rz \\u2013 So, 22. M\\u00e4rz 2026&quot;,&quot;from_to_HRFSHORT&quot;:&quot;21. M\\u00e4r \\u2013 22. M\\u00e4r 2026&quot;},&quot;alert&quot;:&quot;DGS&quot;,&quot;partof&quot;:[&quot;33827&quot;],&quot;marketing_topic&quot;:{&quot;title&quot;:&quot;Geschichtentheater&quot;,&quot;ID&quot;:&quot;33827&quot;,&quot;reason&quot;:&quot;sequence&quot;}}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/termin\/schauspiel\/staerke-33522\/\" class=\"teaser teaser-event teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 teaser-event-image\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">DGS<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a04007184ea2\" aria-labelledby=\"desc_media_6a04007184ea2\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00128243-300x237.jpg\",\"width\":300,\"height\":237,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"SHF_eb00128243-1024x809.jpg\",\"width\":1024,\"height\":809,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"SHF_eb00128243-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"SHF_eb00128243-768x607.jpg\",\"width\":768,\"height\":607,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"SHF_eb00128243-440x348.jpg\",\"width\":440,\"height\":348,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"SHF_eb00128243-580x458.jpg\",\"width\":580,\"height\":458,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"SHF_eb00128243-720x569.jpg\",\"width\":720,\"height\":569,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"SHF_eb00128243-1280x1012.jpg\",\"width\":1280,\"height\":1012,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"SHF_eb00128243-1536x1214.jpg\",\"width\":1536,\"height\":1214,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"SHF_eb00128243.jpg\",\"width\":1803,\"height\":1425}},\n\t\t\t\t\"alt\" : \"Zwei Schauspieler geben im Freien eine beeindruckende Darbietung, umgeben von S\\u00e4ulen und einem Hinweis zur Geschichte des Ortes.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:79.034941763727%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a04007184ea2\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a04007184ea2\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Kathleen Rappolt und Jan Sell<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Ragnhild M\u00f8rch<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant clamp-2\">Geschichtentheater<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom\">St\u00e4rke<\/strong>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"\">Eine Geschichte erz\u00e4hlt in deutscher Geb\u00e4rdensprache und deutscher Lautsprache von Jan Sell und Kathleen Rappolt<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n<\/ul>\n\t\t\t<\/div>\n\t\t\t\t<\/lazy-component>\n<\/section>\n\n\n\n<section class=\"block block-CTA block-CTA-long leftgradient\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/newsletter-2\/\" aria-label=\"Bleiben Sie auf dem Laufenden!\" class=\"teaser teaser-cta-wide \">\n\t\t\t\t\t\t<div class=\"teaser-image\">\n\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a04007187395\" aria-labelledby=\"desc_media_6a04007187395\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00061823-scaled-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":19186},\"large\":{\"file\":\"HF_eb00061823-scaled-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":138597},\"thumbnail\":{\"file\":\"HF_eb00061823-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8513},\"medium_large\":{\"file\":\"HF_eb00061823-scaled-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":86200},\"small\":{\"file\":\"HF_eb00061823-scaled-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35525},\"semi\":{\"file\":\"HF_eb00061823-scaled-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":55724},\"mobile\":{\"file\":\"HF_eb00061823-scaled-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":77971},\"hd\":{\"file\":\"HF_eb00061823-scaled-1280x854.jpg\",\"width\":1280,\"height\":854,\"mime-type\":\"image\\\/jpeg\",\"filesize\":202477},\"full\":{\"file\":\"HF_eb00061823-scaled-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":386736},\"1536x1536\":{\"file\":\"HF_eb00061823-scaled-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":266197},\"2048x2048\":{\"file\":\"HF_eb00061823-scaled-2048x1366.jpg\",\"width\":2048,\"height\":1366,\"mime-type\":\"image\\\/jpeg\",\"filesize\":430206},\"original\":{\"file\":\"HF_eb00061823-scaled.jpg\",\"width\":2560,\"height\":1707}},\n\t\t\t\t\"alt\" : \"Blick in das beleuchtete Foyer von der Galerie im ersten Stock mit Besuchenden, Infopoint und Medienturm\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"70\",\n\t\t\t\t\"crop\" : {\"top\":\"90.37\",\"left\":\"39.93\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.6796875%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a04007187395\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a04007187395\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Blick in das Foyer, November 2019.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ David von Becker<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"teaser-content \">\n\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"teaser-header\"><span class=\"h3\">Bleiben Sie auf dem Laufenden!<\/span><\/div>\n\t\t\t\t\t\t\t\t<div class=\"teaser-subline\"><span class=\"font-decoration\">Abonnieren Sie unseren Newsletter.<\/span><\/div>\t\t\t\t\t\t\t\t<button tabindex=\"-1\" class=\"border\">Hier klicken<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"template":"","genre":[845,393],"digital":[],"topic":[],"stakeholder":[382],"editorial":[],"editorialfilter":[],"targetgroup":[],"language":[],"accessability":[],"age":[],"school":[],"groupsize":[],"place":[510],"class_list":["post-145657","event-multi","type-event-multi","status-publish","hentry","genre-festival","genre-konzert","stakeholder-stiftung-humboldt-forum-im-berliner-schloss","place-schlueterhof"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-multi\/145657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-multi"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/types\/event-multi"}],"version-history":[{"count":12,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-multi\/145657\/revisions"}],"predecessor-version":[{"id":150828,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-multi\/145657\/revisions\/150828"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media?parent=145657"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/genre?post=145657"},{"taxonomy":"digital","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/digital?post=145657"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/topic?post=145657"},{"taxonomy":"stakeholder","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/stakeholder?post=145657"},{"taxonomy":"editorial","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorial?post=145657"},{"taxonomy":"editorialfilter","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorialfilter?post=145657"},{"taxonomy":"targetgroup","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/targetgroup?post=145657"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/language?post=145657"},{"taxonomy":"accessability","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/accessability?post=145657"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/age?post=145657"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/school?post=145657"},{"taxonomy":"groupsize","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/groupsize?post=145657"},{"taxonomy":"place","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/place?post=145657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}