{"id":119437,"date":"2024-01-11T15:51:12","date_gmt":"2024-01-11T14:51:12","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?post_type=event-publication&#038;p=119437"},"modified":"2025-09-19T13:40:28","modified_gmt":"2025-09-19T11:40:28","slug":"palast-der-republik-ein-erinnerungsort-neu-diskutiert","status":"publish","type":"event-publication","link":"https:\/\/www.humboldtforum.org\/de\/programm\/publikation\/publikation\/palast-der-republik-ein-erinnerungsort-neu-diskutiert-119437\/","title":{"rendered":"Palast der Republik. Ein Erinnerungsort neu diskutiert"},"content":{"rendered":"<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Die Stiftung Humboldt Forum im Berliner Schloss (damals noch Stiftung Berliner Schloss \u2013 Humboldt Forum) veranstaltete am 26. Februar 2016 gemeinsam mit dem Deutschen Historischen Museum ein Expert*innengespr\u00e4ch zum Thema \u201eDer Palast der Republik \u2013 Erinnerungsort und materielle Kultur.\u201c Die Veranstaltung wurde konzipiert und organisiert von Doris M\u00fcller-Toovey mit Unterst\u00fctzung von Andrea Rieder und Hanna Nogossek.<\/p>\n<p>Diese Publikation dokumentiert die Vortr\u00e4ge und Beitr\u00e4ge des Expertengespr\u00e4chs und ist als kostenloser Download verf\u00fcgbar.<\/p>\n<p><em>Palast der Republik. Ein Erinnerungsort neu diskutiert, 94 Seiten, Berlin 2017 <\/em><\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n\n<section class=\"block block-copy-quote\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t\t\t\t<figure class=\"col-xs-10 col-md-6 quote-copy\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-10 col-xs-offset-1 col-padding-remove\">\n\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-zitat quote-copy-icon  no-image\"><\/span>\n\t\t\t\t\t\t\t\t\t<blockquote class=\"quote-copy-headline Zitat\">Die Vielzahl an Expertenmeinungen mit unterschiedlichen Schwerpunktsetzungen ist hierbei erfreulich.[&#8230;] Die Beitr\u00e4ge [&#8230;] [sind] von hoher Qualit\u00e4t und bieten interessante Blickweisen auf seine Rezeptionsgeschichte.<\/blockquote>\n\t\t\t\t\t\t\t\t\t<figcaption class=\"quote-copy-subline Copyright\">der architekt, 28.04.2017<\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/figure>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-CTA block-CTA-long leftgradient\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/laufzeitangebot\/ausstellung\/hin-und-weg-der-palast-der-republik-ist-gegenwart-116558\/\" aria-label=\"Hin und weg. Der Palast der Republik ist Gegenwart\" class=\"teaser teaser-cta-wide \">\n\t\t\t\t\t\t<div class=\"teaser-image\">\n\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a5713841d26e\" aria-labelledby=\"desc_media_6a5713841d26e\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00217230-3-300x300.jpg\",\"width\":300,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23579},\"large\":{\"file\":\"SHF_eb00217230-3-1024x1024.jpg\",\"width\":1024,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":179595},\"thumbnail\":{\"file\":\"SHF_eb00217230-3-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7382},\"medium_large\":{\"file\":\"SHF_eb00217230-3-768x768.jpg\",\"width\":768,\"height\":768,\"mime-type\":\"image\\\/jpeg\",\"filesize\":110931},\"small\":{\"file\":\"SHF_eb00217230-3-440x440.jpg\",\"width\":440,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":44418},\"semi\":{\"file\":\"SHF_eb00217230-3-580x580.jpg\",\"width\":580,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":71526},\"mobile\":{\"file\":\"SHF_eb00217230-3-720x720.jpg\",\"width\":720,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":99742},\"hd\":{\"file\":\"SHF_eb00217230-3-1280x1280.jpg\",\"width\":1280,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":259734},\"full\":{\"file\":\"SHF_eb00217230-3-1920x1920.jpg\",\"width\":1920,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":512157},\"1536x1536\":{\"file\":\"SHF_eb00217230-3-1536x1536.jpg\",\"width\":1536,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":351402},\"2048x2048\":{\"file\":\"SHF_eb00217230-3-2048x2048.jpg\",\"width\":2048,\"height\":2048,\"mime-type\":\"image\\\/jpeg\",\"filesize\":576041},\"original\":{\"file\":\"SHF_eb00217230-3.jpg\",\"width\":3000,\"height\":3000}},\n\t\t\t\t\"alt\" : \"St\\u00e4dtische Innenansicht mit dekorativen Elementen und einem gro\\u00dfen Logo, lebhaft und in kr\\u00e4ftigen Farben dargestellt.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"100\",\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:100%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a5713841d26e\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a5713841d26e\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Visual der Ausstellung &quot;Hin und Weg. Der Palast der Republik ist Gegenwart&quot;<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss; bpk \/ Gerhard Kiesling<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"teaser-content \">\n\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t<div class=\"teaser-overline subline\">Geh\u00f6rt zu<\/div>\t\t\t\t\t\t\t\t<div class=\"teaser-header\"><span class=\"h3\">Hin und weg. Der Palast der Republik ist Gegenwart<\/span><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button tabindex=\"-1\" class=\"border\">Zum Programm<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"template":"","genre":[739],"digital":[],"topic":[],"stakeholder":[382],"editorial":[],"editorialfilter":[1385],"targetgroup":[],"language":[384],"accessability":[],"school":[],"class_list":["post-119437","event-publication","type-event-publication","status-publish","hentry","genre-publikation","stakeholder-stiftung-humboldt-forum-im-berliner-schloss","editorialfilter-palast-der-republik","language-deutsch"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-publication\/119437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-publication"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/types\/event-publication"}],"version-history":[{"count":12,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-publication\/119437\/revisions"}],"predecessor-version":[{"id":125008,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event-publication\/119437\/revisions\/125008"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media?parent=119437"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/genre?post=119437"},{"taxonomy":"digital","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/digital?post=119437"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/topic?post=119437"},{"taxonomy":"stakeholder","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/stakeholder?post=119437"},{"taxonomy":"editorial","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorial?post=119437"},{"taxonomy":"editorialfilter","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorialfilter?post=119437"},{"taxonomy":"targetgroup","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/targetgroup?post=119437"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/language?post=119437"},{"taxonomy":"accessability","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/accessability?post=119437"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/school?post=119437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}