{"id":100125,"date":"2023-09-13T14:34:57","date_gmt":"2023-09-13T12:34:57","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?post_type=event&#038;p=100125"},"modified":"2023-10-30T20:17:04","modified_gmt":"2023-10-30T19:17:04","slug":"kinderschminken","status":"publish","type":"event","link":"https:\/\/www.humboldtforum.org\/de\/programm\/termin\/workshop\/kinderschminken-100125\/","title":{"rendered":"Kinderschminken"},"content":{"rendered":"<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Kinderschminken darf auch beim mexikanischen Totenfest nicht fehlen! Skelett, Blume oder viele weitere Motive stehen f\u00fcr die Kinder zur Auswahl<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h4\">Beteiligte<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy block-no-margin\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Nina Wei\u00df, Maite Lamu\u00f1o, Adriana Barrera, Adriana El\u00edas, Ilona Maennchen, Irma Sandoval, Patricia Mart\u00ednez, Constanza Novillo, Klaus Trebe\u00df, Ebahly Tobias, B\u00e9la Wei\u00df, Amanda Fern\u00e1ndez, Asha Bhambry<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n\n<section class=\"block block-gallery\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box text-align-left\">\n\t\t\t\t\t<block-gallery inline-template>\n\t\t\t\t\t\t<div :class=\"{ firstLoaded: firstLoaded }\">\n\t\t\t\t\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\"images\" : [{\"id\":0,\"width\":2000,\"height\":1333,\"alt\":\"Ein M&auml;dchen erh&auml;lt w&auml;hrend eines Kunst-Events ein Gesichtsmalerei-Design auf die Stirn.\",\"title\":\"\",\"description\":\"\",\"label\":\"Kinderschminken beim mexikanischen Totenfest des Vereins Calaca e.V.\",\"copyright\":\"Alejandro Montoya\",\"path\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00202423-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":13958},\"large\":{\"file\":\"SHF_eb00202423-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":83040},\"thumbnail\":{\"file\":\"SHF_eb00202423-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6855},\"medium_large\":{\"file\":\"SHF_eb00202423-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":54173},\"small\":{\"file\":\"SHF_eb00202423-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":24383},\"semi\":{\"file\":\"SHF_eb00202423-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":36459},\"mobile\":{\"file\":\"SHF_eb00202423-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":49315},\"hd\":{\"file\":\"SHF_eb00202423-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\",\"filesize\":116378},\"full\":{\"file\":\"SHF_eb00202423-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":226534},\"1536x1536\":{\"file\":\"SHF_eb00202423-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":155308},\"original\":{\"file\":\"SHF_eb00202423.jpg\",\"width\":2000,\"height\":1333}}},{\"id\":1,\"width\":2000,\"height\":1333,\"alt\":\"M&auml;dchen erh&auml;lt Gesichtsmalerei, umgeben von anderen Kindern und Erwachsenen auf einer lebhaften Veranstaltung.\",\"title\":\"\",\"description\":\"\",\"label\":\"Kinderschminken beim mexikanischen Totenfest des Vereins Calaca e.V.\",\"copyright\":\"Alejandro Montoya\",\"path\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00202424-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":17383},\"large\":{\"file\":\"SHF_eb00202424-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":109204},\"thumbnail\":{\"file\":\"SHF_eb00202424-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7986},\"medium_large\":{\"file\":\"SHF_eb00202424-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":70790},\"small\":{\"file\":\"SHF_eb00202424-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":31001},\"semi\":{\"file\":\"SHF_eb00202424-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":47326},\"mobile\":{\"file\":\"SHF_eb00202424-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":64345},\"hd\":{\"file\":\"SHF_eb00202424-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\",\"filesize\":152461},\"full\":{\"file\":\"SHF_eb00202424-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":289416},\"1536x1536\":{\"file\":\"SHF_eb00202424-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":201940},\"original\":{\"file\":\"SHF_eb00202424.jpg\",\"width\":2000,\"height\":1333}}},{\"id\":2,\"width\":2000,\"height\":1333,\"alt\":\"M&auml;dchen erh&auml;lt Gesichtsmalerei von einer Frau, im Hintergrund buntes Dekor und Zubeh&ouml;r.\",\"title\":\"\",\"description\":\"\",\"label\":\"Kinderschminken beim mexikanischen Totenfest des Vereins Calaca e.V.\",\"copyright\":\"Alejandro Montoya\",\"path\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00202425-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":15401},\"large\":{\"file\":\"SHF_eb00202425-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":97075},\"thumbnail\":{\"file\":\"SHF_eb00202425-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7288},\"medium_large\":{\"file\":\"SHF_eb00202425-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":62280},\"small\":{\"file\":\"SHF_eb00202425-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":26991},\"semi\":{\"file\":\"SHF_eb00202425-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":41269},\"mobile\":{\"file\":\"SHF_eb00202425-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":56487},\"hd\":{\"file\":\"SHF_eb00202425-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\",\"filesize\":137535},\"full\":{\"file\":\"SHF_eb00202425-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":266994},\"1536x1536\":{\"file\":\"SHF_eb00202425-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":183656},\"original\":{\"file\":\"SHF_eb00202425.jpg\",\"width\":2000,\"height\":1333}}}]\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t<\/script>\n\n\t\t\t\t\t\t\t<swiper :options=\"options\" @slide-change=\"track\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" :key=\"image.id\" v-for=\"image in images\">\n\t\t\t\t\t\t\t\t\t<block-gallery-item inline-template :image=\"image\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"swiper-slide-image-wrapper\" ref=\"parent\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"width-container\" ref=\"container\" :style=\"style\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax-x=\"50%\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img :src=\"image.src\" :alt=\"image.alt\" v-if=\"image.id < 2\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" :data-src=\"image.src\" :alt=\"image.alt\" v-else>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/block-gallery-item>\n\n\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div v-if=\"image.label\" v-html=\"image.label\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div v-else-if=\"image.description\" v-html=\"image.description\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\" v-if=\"image.copyright\" v-html=\"'\u00a9 '+image.copyright\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"  slot=\"pagination\"><\/div>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-prev\" slot=\"button-prev\" aria-label=\"Vorheriges Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-next\" slot=\"button-next\" aria-label=\"N\u00e4chstes Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/swiper>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/block-gallery>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-teaser col-1 has-bg\" style=\"--teaser-bg:#f2f2f2\">\n\t<lazy-component :fixed-min-height=\"400\">\n\t\n\t\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t<div class=\"col-xs-12 col-sm-10 col-md-8 col-sm-offset-1 col-md-offset-2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-xs-12 col-sm-10 col-md-8 col-sm-offset-1 col-md-offset-2 start-xs end-md margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"row\">\n\t\t\t\n<li class=\"col-xs-12 teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"970407202\" rawitem='{&quot;postId&quot;:97040,&quot;title&quot;:&quot;Fiesta de D\\u00eda de Muertos&quot;,&quot;excerpt&quot;:&quot;&quot;,&quot;slug&quot;:&quot;fiesta-de-dia-de-muertos&quot;,&quot;post_date&quot;:&quot;2023-08-28T10:35&quot;,&quot;type&quot;:&quot;event-multi&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/event\\\/festival\\\/fiesta-de-dia-de-muertos-97040\\\/&quot;,&quot;genre&quot;:[845],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Festival&quot;,&quot;id&quot;:845,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;stakeholder&quot;:[382],&quot;stakeholder_details&quot;:[{&quot;text&quot;:&quot;Stiftung Humboldt Forum im Berliner Schloss&quot;,&quot;id&quot;:382,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;language&quot;:[384,386],&quot;language_details&quot;:[{&quot;text&quot;:&quot;Deutsch&quot;,&quot;id&quot;:384,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Spanisch&quot;,&quot;id&quot;:386,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;accessability&quot;:[430],&quot;accessability_details&quot;:[{&quot;text&quot;:&quot;Rollstuhlgerecht&quot;,&quot;id&quot;:430,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[957,1179,883],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Foyer, Saal 1, EG, Saal 2, EG&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;belongsto&quot;:[70155],&quot;shorturl&quot;:&quot;&quot;,&quot;planning&quot;:{&quot;price&quot;:&quot;Alle Angebote sind kostenfrei&quot;,&quot;admission&quot;:&quot;&quot;,&quot;pause&quot;:&quot;&quot;,&quot;duration&quot;:&quot;&quot;,&quot;status&quot;:&quot;JOIN&quot;,&quot;info&quot;:&quot;Eintritt frei&quot;,&quot;shop&quot;:&quot;&quot;,&quot;can_purchase&quot;:false},&quot;additional_info&quot;:{&quot;icon&quot;:&quot;0&quot;,&quot;text&quot;:&quot;&quot;},&quot;highlight_header&quot;:true,&quot;has_mobile_format&quot;:true,&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:true,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;highlight_header_image&quot;:101804,&quot;subline&quot;:&quot;Live-Musik, Tanz, Ofrenda, Markt&quot;,&quot;overwrite_date&quot;:&quot;1. bis 5. November 2023&quot;,&quot;announcement&quot;:&quot;1. bis 5. November 2023&quot;,&quot;times&quot;:[],&quot;highlight_header_image_mobile&quot;:101806,&quot;infotext&quot;:&quot;F\\u00fcr den Eintritt in Saal 1 und Saal 2 bitte alle Taschen, die gr\\u00f6\\u00dfer als DIN A4 sind, in der Garderobe oder den Schlie\\u00dffl\\u00e4chern abgeben.&quot;,&quot;tickettext&quot;:&quot;W\\u00e4hrend der Fiesta de D\\u00eda de Muertos hat die Ausstellung un_endlich vom 2. November bis 4. November 2023 bei kostenfreiem Eintritt bis 22:00 Uhr ge\\u00f6ffnet. Ein Zeitfensterticket ist nicht erforderlich. &quot;,&quot;redirect&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/event\\\/fest\\\/fiesta-de-dia-de-muertos-2-150620\\\/&quot;,&quot;events&quot;:[152947,152952,152963,152990,153003,153008,153037,153073,153081,153098,153112,153123,153651]},&quot;date&quot;:{&quot;NX&quot;:null,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202311051130&quot;,&quot;from_DATE&quot;:&quot;20231101 15:00&quot;,&quot;from&quot;:1698843600,&quot;to&quot;:1699183800,&quot;to_DATE&quot;:&quot;20231105 13:30&quot;,&quot;from_HRFSHORT&quot;:&quot; 1. Nov 2023&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Mi 01.11.2023&quot;,&quot;to_HRFSHORT&quot;:&quot; 5. Nov 2023&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 05.11.2023&quot;,&quot;from_HRF&quot;:&quot;Mi,  1. November 2023&quot;,&quot;to_HRF&quot;:&quot;So,  5. November 2023&quot;,&quot;from_to_HRF&quot;:&quot;Mi,  1. November \\u2013 So,  5. November 2023&quot;,&quot;from_to_HRFSHORT&quot;:&quot; 1. Nov \\u2013  5. Nov 2023&quot;},&quot;alert&quot;:&quot;Highlight&quot;,&quot;partof&quot;:[],&quot;marketing_topic&quot;:{&quot;title&quot;:&quot;un_endlich. Leben mit dem Tod&quot;,&quot;ID&quot;:70155,&quot;reason&quot;:&quot;belongsto&quot;}}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/event\/festival\/fiesta-de-dia-de-muertos-97040\/\" class=\"teaser teaser-event-multi teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-sm-6 col-md-5 col-sm-offset-1 col-md-offset-2 first-sm teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant clamp-2\">un_endlich. Leben mit dem Tod<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom h5\">Fiesta de D\u00eda de Muertos<\/strong>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"\">Live-Musik, Tanz, Ofrenda, Markt<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-sm-4 col-md-3 teaser-event-image bottom-xs first-xs\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">Highlight<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a050d3e0366d\" aria-labelledby=\"desc_media_6a050d3e0366d\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-176x300.jpg\",\"width\":176,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":11690},\"large\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-600x1024.jpg\",\"width\":600,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":87824},\"thumbnail\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7064},\"medium_large\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-768x1312.jpg\",\"width\":768,\"height\":1312,\"mime-type\":\"image\\\/jpeg\",\"filesize\":130131},\"small\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-258x440.jpg\",\"width\":258,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":22489},\"semi\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-340x580.jpg\",\"width\":340,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35016},\"mobile\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-422x720.jpg\",\"width\":422,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":49562},\"hd\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-749x1280.jpg\",\"width\":749,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":125206},\"full\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-1124x1920.jpg\",\"width\":1124,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":238708},\"1536x1536\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-899x1536.jpg\",\"width\":899,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":168246},\"2048x2048\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos-1199x2048.jpg\",\"width\":1199,\"height\":2048,\"mime-type\":\"image\\\/jpeg\",\"filesize\":262290},\"original\":{\"file\":\"SHF_eb00201644_Key-Visual-Dia-de-los-Muertos.jpg\",\"width\":1780,\"height\":3040}},\n\t\t\t\t\"alt\" : \"Bunt geschm\\u00fcckter Totenkopf mit Blumen und Kerze, umgeben von einem farbenfrohen Hintergrund und einem lila Rahmen.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:170.78651685393%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a050d3e0366d\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a050d3e0366d\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Getty Images \/ fergregory; iStockphoto \/ gadost , pullia, agcuesta<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t\t<\/lazy-component>\n<\/section>\n\n\n\n<section class=\"block block-CTA block-CTA-long leftgradient\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/newsletter-2\/\" aria-label=\"Bleiben Sie auf dem Laufenden!\" class=\"teaser teaser-cta-wide \">\n\t\t\t\t\t\t<div class=\"teaser-image\">\n\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a050d3e058ca\" aria-labelledby=\"desc_media_6a050d3e058ca\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00061823-scaled-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":19186},\"large\":{\"file\":\"HF_eb00061823-scaled-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":138597},\"thumbnail\":{\"file\":\"HF_eb00061823-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8513},\"medium_large\":{\"file\":\"HF_eb00061823-scaled-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":86200},\"small\":{\"file\":\"HF_eb00061823-scaled-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35525},\"semi\":{\"file\":\"HF_eb00061823-scaled-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":55724},\"mobile\":{\"file\":\"HF_eb00061823-scaled-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":77971},\"hd\":{\"file\":\"HF_eb00061823-scaled-1280x854.jpg\",\"width\":1280,\"height\":854,\"mime-type\":\"image\\\/jpeg\",\"filesize\":202477},\"full\":{\"file\":\"HF_eb00061823-scaled-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":386736},\"1536x1536\":{\"file\":\"HF_eb00061823-scaled-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":266197},\"2048x2048\":{\"file\":\"HF_eb00061823-scaled-2048x1366.jpg\",\"width\":2048,\"height\":1366,\"mime-type\":\"image\\\/jpeg\",\"filesize\":430206},\"original\":{\"file\":\"HF_eb00061823-scaled.jpg\",\"width\":2560,\"height\":1707}},\n\t\t\t\t\"alt\" : \"Blick in das beleuchtete Foyer von der Galerie im ersten Stock mit Besuchenden, Infopoint und Medienturm\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"70\",\n\t\t\t\t\"crop\" : {\"top\":\"90.37\",\"left\":\"39.93\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.6796875%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a050d3e058ca\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a050d3e058ca\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Blick in das Foyer, November 2019.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ David von Becker<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"teaser-content \">\n\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"teaser-header\"><span class=\"h3\">Bleiben Sie auf dem Laufenden!<\/span><\/div>\n\t\t\t\t\t\t\t\t<div class=\"teaser-subline\"><span class=\"font-decoration\">Abonnieren Sie unseren Newsletter.<\/span><\/div>\t\t\t\t\t\t\t\t<button tabindex=\"-1\" class=\"border\">Hier klicken<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"template":"","genre":[837],"digital":[],"topic":[],"stakeholder":[382],"editorial":[],"editorialfilter":[],"targetgroup":[454],"language":[422],"accessability":[430],"age":[],"school":[],"groupsize":[],"place":[957,1558,1179],"class_list":["post-100125","event","type-event","status-publish","has-post-thumbnail","hentry","genre-workshop","stakeholder-stiftung-humboldt-forum-im-berliner-schloss","targetgroup-kinder-und-familien","language-keine-sprachkenntnisse-erforderlich","accessability-rollstuhlgerecht","place-foyer","place-mechanische-arena-im-foyer","place-saal-1"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/100125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":12,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/100125\/revisions"}],"predecessor-version":[{"id":106717,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/100125\/revisions\/106717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media\/99866"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media?parent=100125"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/genre?post=100125"},{"taxonomy":"digital","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/digital?post=100125"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/topic?post=100125"},{"taxonomy":"stakeholder","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/stakeholder?post=100125"},{"taxonomy":"editorial","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorial?post=100125"},{"taxonomy":"editorialfilter","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorialfilter?post=100125"},{"taxonomy":"targetgroup","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/targetgroup?post=100125"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/language?post=100125"},{"taxonomy":"accessability","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/accessability?post=100125"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/age?post=100125"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/school?post=100125"},{"taxonomy":"groupsize","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/groupsize?post=100125"},{"taxonomy":"place","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/place?post=100125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}