{"id":128778,"date":"2024-05-03T12:08:45","date_gmt":"2024-05-03T10:08:45","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?post_type=event&#038;p=128778"},"modified":"2024-08-29T09:54:10","modified_gmt":"2024-08-29T07:54:10","slug":"heiner-mueller-quartett-material","status":"publish","type":"event","link":"https:\/\/www.humboldtforum.org\/de\/programm\/termin\/schauspiel\/heiner-mueller-quartett-material-128778\/","title":{"rendered":"Heiner M\u00fcller \u2013\u00a0Quartett. Material"},"content":{"rendered":"<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row margin-bottom-sixth\">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Quartett. Ein Krankenhausbett. Eine Frau. Ein Mann (ihr Pfleger). Ein Kartenspiel. Die fehlenden Karten zu suchen \u2013 m\u00f6gliche Aufgabe und Spielanordnung. Und eine Inszenierung im Theater im Palast, 1989, vor 35 Jahren, die zu denken aufgibt. \u2013 Die Machtk\u00e4mpfe von gestern sind ausgetragen, privat wie politisch, keine Sieger in Sicht, nur die Erinnerungen gehen noch um, die S\u00e4tze im Kopf, Klopfzeichen in der Kanalisation, dem eigenen K\u00f6rper. \u201eJetzt sind wir allein \/ Krebs mein Geliebter\u201c.<\/p>\n<p>Heiner M\u00fcllers bekanntestes St\u00fcck <em>Quartett<\/em> in einer szenischen Versuchsanordnung mit Corinna Harfouch und Oscar Olivo.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"row margin-bottom-sixth\">\n\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<read-more inline-template>\n\t\t\t\t\t\t\t<div class=\"copy margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t<div ref=\"body\" style=\"height:0;overflow: hidden;display: none;\">\n\t\t\t\t\t\t\t\t\t<div class=\"margin-bottom-sixth\"><p>Heiner M\u00fcllers \u201eQuartett\u201c (1981) wurde 1982 unter der Regie von B. K. Tragelehn in Bochum uraufgef\u00fchrt \u2013 seitdem ist es auch international M\u00fcllers meistgespieltes und bekanntestes Theaterst\u00fcck.<\/p>\n<p>Choderlos de Laclos\u2018 Briefroman \u201eGef\u00e4hrliche Liebschaften\u201c (1782) bildete die Vorlage f\u00fcr den Text, M\u00fcllers Intention beim Schreiben war es, \u201edie Struktur von Geschlechterbeziehungen freizulegen\u201c und \u201eVerdr\u00e4ngungen zu zerst\u00f6ren\u201c. Er selbst bezeichnete \u201eQuartett\u201c, \u201eZeitraum: Salon vor der Franz\u00f6sischen Revolution \/ Bunker nach dem dritten Weltkrieg\u201c, als Kom\u00f6die.<\/p>\n<p>In der DDR konnte das St\u00fcck erst im April 1989 im \u201etheater im palast\u201c unter der Regie von Bernd Peschke aufgef\u00fchrt werden. Ein halbes Jahr sp\u00e4ter, Anfang Oktober 1989, steht Heiner M\u00fcller selbst auf der B\u00fchne des \u201etip\u201c und liest die Rolle des Valmont, denn Regisseur und Hauptdarsteller hatten die DDR \u00fcber Ungarn in Richtung Bundesrepublik verlassen.<\/p>\n<p>\u201eQUARTETT ist ein Reflex auf das Problem des Terrorismus, mit einem Stoff, mit einem Material, das oberfl\u00e4chlich nichts damit zu tun hat. Die Vorlage, Laclos\u2019 \u201aGef\u00e4hrliche Liebschaften\u2018, habe ich nie ganz gelesen. Meine wesentliche Quelle war das Vorwort von Heinrich Mann zu seiner \u00dcbersetzung. Das Hauptproblem beim Schreiben von QUARTETT war, eine Dramaturgie zu finden f\u00fcr den Briefroman, und das ging schlie\u00dflich nur \u00fcber das Spiel, zwei spielen vier. Der Plan existierte seit den 50er Jahren. Nach MAUSER konnte ich es dann schreiben, beziehungsweise nach der MAUSER-Inszenierung von Christof Nel 1980 in K\u00f6ln [\u2026].<\/p>\n<p>Ich sa\u00df da in einer Villa bei Rom im obersten Stock. Angefangen hatte ich vorher schon, aber das letzte Drittel oder die zweite H\u00e4lfte ist da geschrieben worden, zum ersten Mal auf einer elektrischen Schreibmaschine. Das hatte Folgen f\u00fcr den Text. Er ist mehr ein Uhrwerk als andere Texte vorher. In den unteren R\u00e4umen wohnte meine Frau mit einem anderen Mann, der heftig in sie verliebt war. Sicher ging davon eine Energie aus. Ich hatte ein kleines Radio bei mir, im dritten Programm lief gerade eine Schubert-Serie. Und ich erinnere mich an ein Lied, das da in der Nacht besonders eindrucksvoll war, aus der \u201aSch\u00f6nen M\u00fcllerin\u2018, wo der Bach den Knaben zum Selbstmord einl\u00e4dt. \u201aUnd die Sterne da oben, wie sind sie so weit.\u2018\u201c<\/p>\n<p><em>(in: Heiner M\u00fcller: Krieg ohne Schlacht. Leben in zwei Diktaturen. Eine Autobiographie = Werke 9. Hg. von Frank H\u00f6rnigk, Frankfurt am Main 2005 S. 248-249)<\/em><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<a ref=\"toggleButton\" class=\"Button\" @click=\"toggle\">\n\t\t\t\t\t\t\t\t\t<span v-if=\"!active\">mehr lesen<\/span>\n\t\t\t\t\t\t\t\t\t<span v-else>weniger lesen<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/read-mode>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n\n<section class=\"block block-gallery\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box text-align-left\">\n\t\t\t\t\t<block-gallery inline-template>\n\t\t\t\t\t\t<div :class=\"{ firstLoaded: firstLoaded }\">\n\t\t\t\t\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\"images\" : [{\"id\":0,\"width\":2000,\"height\":1369,\"alt\":\"Szenische Darstellung mit zwei Personen, eine im Rollstuhl und eine stehend, auf einer B&uuml;hne mit Hintergrundbeleuchtung.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226106-300x205.jpg\",\"width\":300,\"height\":205,\"mime-type\":\"image\\\/jpeg\",\"filesize\":15841},\"large\":{\"file\":\"SHF_eb00226106-1024x701.jpg\",\"width\":1024,\"height\":701,\"mime-type\":\"image\\\/jpeg\",\"filesize\":101895},\"thumbnail\":{\"file\":\"SHF_eb00226106-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8032},\"medium_large\":{\"file\":\"SHF_eb00226106-768x526.jpg\",\"width\":768,\"height\":526,\"mime-type\":\"image\\\/jpeg\",\"filesize\":66320},\"small\":{\"file\":\"SHF_eb00226106-440x301.jpg\",\"width\":440,\"height\":301,\"mime-type\":\"image\\\/jpeg\",\"filesize\":28710},\"semi\":{\"file\":\"SHF_eb00226106-580x397.jpg\",\"width\":580,\"height\":397,\"mime-type\":\"image\\\/jpeg\",\"filesize\":43682},\"mobile\":{\"file\":\"SHF_eb00226106-720x493.jpg\",\"width\":720,\"height\":493,\"mime-type\":\"image\\\/jpeg\",\"filesize\":60400},\"hd\":{\"file\":\"SHF_eb00226106-1280x876.jpg\",\"width\":1280,\"height\":876,\"mime-type\":\"image\\\/jpeg\",\"filesize\":142682},\"full\":{\"file\":\"SHF_eb00226106-1920x1314.jpg\",\"width\":1920,\"height\":1314,\"mime-type\":\"image\\\/jpeg\",\"filesize\":276766},\"1536x1536\":{\"file\":\"SHF_eb00226106-1536x1051.jpg\",\"width\":1536,\"height\":1051,\"mime-type\":\"image\\\/jpeg\",\"filesize\":190195},\"original\":{\"file\":\"SHF_eb00226106.jpg\",\"width\":2000,\"height\":1369}}},{\"id\":1,\"width\":2000,\"height\":1343,\"alt\":\"Mann in blauer Kleidung steht neben Frau im blauen Kleid in einem Krankenhausflur.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226107-300x201.jpg\",\"width\":300,\"height\":201,\"mime-type\":\"image\\\/jpeg\",\"filesize\":14741},\"large\":{\"file\":\"SHF_eb00226107-1024x688.jpg\",\"width\":1024,\"height\":688,\"mime-type\":\"image\\\/jpeg\",\"filesize\":88949},\"thumbnail\":{\"file\":\"SHF_eb00226107-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7751},\"medium_large\":{\"file\":\"SHF_eb00226107-768x516.jpg\",\"width\":768,\"height\":516,\"mime-type\":\"image\\\/jpeg\",\"filesize\":57489},\"small\":{\"file\":\"SHF_eb00226107-440x295.jpg\",\"width\":440,\"height\":295,\"mime-type\":\"image\\\/jpeg\",\"filesize\":25837},\"semi\":{\"file\":\"SHF_eb00226107-580x389.jpg\",\"width\":580,\"height\":389,\"mime-type\":\"image\\\/jpeg\",\"filesize\":38713},\"mobile\":{\"file\":\"SHF_eb00226107-720x483.jpg\",\"width\":720,\"height\":483,\"mime-type\":\"image\\\/jpeg\",\"filesize\":52765},\"hd\":{\"file\":\"SHF_eb00226107-1280x860.jpg\",\"width\":1280,\"height\":860,\"mime-type\":\"image\\\/jpeg\",\"filesize\":126444},\"full\":{\"file\":\"SHF_eb00226107-1920x1289.jpg\",\"width\":1920,\"height\":1289,\"mime-type\":\"image\\\/jpeg\",\"filesize\":255729},\"1536x1536\":{\"file\":\"SHF_eb00226107-1536x1031.jpg\",\"width\":1536,\"height\":1031,\"mime-type\":\"image\\\/jpeg\",\"filesize\":170019},\"original\":{\"file\":\"SHF_eb00226107.jpg\",\"width\":2000,\"height\":1343}}},{\"id\":2,\"width\":2000,\"height\":1271,\"alt\":\"Eine Person liegt in einem Krankenhausbett, umgeben von Dunkelheit und schmalen Lichtstreifen.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226105-300x191.jpg\",\"width\":300,\"height\":191,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6752},\"large\":{\"file\":\"SHF_eb00226105-1024x651.jpg\",\"width\":1024,\"height\":651,\"mime-type\":\"image\\\/jpeg\",\"filesize\":39345},\"thumbnail\":{\"file\":\"SHF_eb00226105-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":3533},\"medium_large\":{\"file\":\"SHF_eb00226105-768x488.jpg\",\"width\":768,\"height\":488,\"mime-type\":\"image\\\/jpeg\",\"filesize\":25841},\"small\":{\"file\":\"SHF_eb00226105-440x280.jpg\",\"width\":440,\"height\":280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":11737},\"semi\":{\"file\":\"SHF_eb00226105-580x369.jpg\",\"width\":580,\"height\":369,\"mime-type\":\"image\\\/jpeg\",\"filesize\":17165},\"mobile\":{\"file\":\"SHF_eb00226105-720x458.jpg\",\"width\":720,\"height\":458,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23539},\"hd\":{\"file\":\"SHF_eb00226105-1280x813.jpg\",\"width\":1280,\"height\":813,\"mime-type\":\"image\\\/jpeg\",\"filesize\":55713},\"full\":{\"file\":\"SHF_eb00226105-1920x1220.jpg\",\"width\":1920,\"height\":1220,\"mime-type\":\"image\\\/jpeg\",\"filesize\":107402},\"1536x1536\":{\"file\":\"SHF_eb00226105-1536x976.jpg\",\"width\":1536,\"height\":976,\"mime-type\":\"image\\\/jpeg\",\"filesize\":74295},\"original\":{\"file\":\"SHF_eb00226105.jpg\",\"width\":2000,\"height\":1271}}},{\"id\":3,\"width\":1356,\"height\":2000,\"alt\":\"Frau im Krankenhausbett, umgeben von Schwarz-Wei&szlig;-Projektionen, die eine dramatische Stimmung schaffen.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226102-203x300.jpg\",\"width\":203,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":14264},\"large\":{\"file\":\"SHF_eb00226102-694x1024.jpg\",\"width\":694,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":74945},\"thumbnail\":{\"file\":\"SHF_eb00226102-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7110},\"medium_large\":{\"file\":\"SHF_eb00226102-768x1133.jpg\",\"width\":768,\"height\":1133,\"mime-type\":\"image\\\/jpeg\",\"filesize\":85693},\"small\":{\"file\":\"SHF_eb00226102-298x440.jpg\",\"width\":298,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23513},\"semi\":{\"file\":\"SHF_eb00226102-393x580.jpg\",\"width\":393,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":34429},\"mobile\":{\"file\":\"SHF_eb00226102-488x720.jpg\",\"width\":488,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":46062},\"hd\":{\"file\":\"SHF_eb00226102-868x1280.jpg\",\"width\":868,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":102410},\"full\":{\"file\":\"SHF_eb00226102-1302x1920.jpg\",\"width\":1302,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":189063},\"1536x1536\":{\"file\":\"SHF_eb00226102-1041x1536.jpg\",\"width\":1041,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":134386},\"original\":{\"file\":\"SHF_eb00226102.jpg\",\"width\":1356,\"height\":2000}}},{\"id\":4,\"width\":1524,\"height\":2000,\"alt\":\"Eine Person im Krankenhausbett sitzt vor einer beeindruckenden Schwarz-Wei&szlig;-Projektion.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226103-229x300.jpg\",\"width\":229,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":14070},\"large\":{\"file\":\"SHF_eb00226103-780x1024.jpg\",\"width\":780,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":80489},\"thumbnail\":{\"file\":\"SHF_eb00226103-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6794},\"medium_large\":{\"file\":\"SHF_eb00226103-768x1008.jpg\",\"width\":768,\"height\":1008,\"mime-type\":\"image\\\/jpeg\",\"filesize\":78523},\"small\":{\"file\":\"SHF_eb00226103-335x440.jpg\",\"width\":335,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":24074},\"semi\":{\"file\":\"SHF_eb00226103-442x580.jpg\",\"width\":442,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35729},\"mobile\":{\"file\":\"SHF_eb00226103-549x720.jpg\",\"width\":549,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":48693},\"hd\":{\"file\":\"SHF_eb00226103-975x1280.jpg\",\"width\":975,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":112105},\"full\":{\"file\":\"SHF_eb00226103-1463x1920.jpg\",\"width\":1463,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":221303},\"1536x1536\":{\"file\":\"SHF_eb00226103-1170x1536.jpg\",\"width\":1170,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":151125},\"original\":{\"file\":\"SHF_eb00226103.jpg\",\"width\":1524,\"height\":2000}}},{\"id\":5,\"width\":1351,\"height\":2000,\"alt\":\"Eine Figur in einem lila Kleid steht auf einer B&uuml;hne, umgeben von silbernen Ger&uuml;sten und blauen Lichtern.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"SHF_eb00226104-203x300.jpg\",\"width\":203,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":15002},\"large\":{\"file\":\"SHF_eb00226104-692x1024.jpg\",\"width\":692,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":94291},\"thumbnail\":{\"file\":\"SHF_eb00226104-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7427},\"medium_large\":{\"file\":\"SHF_eb00226104-768x1137.jpg\",\"width\":768,\"height\":1137,\"mime-type\":\"image\\\/jpeg\",\"filesize\":110794},\"small\":{\"file\":\"SHF_eb00226104-297x440.jpg\",\"width\":297,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":26232},\"semi\":{\"file\":\"SHF_eb00226104-392x580.jpg\",\"width\":392,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":39681},\"mobile\":{\"file\":\"SHF_eb00226104-486x720.jpg\",\"width\":486,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":55086},\"hd\":{\"file\":\"SHF_eb00226104-865x1280.jpg\",\"width\":865,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":134334},\"full\":{\"file\":\"SHF_eb00226104-1297x1920.jpg\",\"width\":1297,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":263532},\"1536x1536\":{\"file\":\"SHF_eb00226104-1038x1536.jpg\",\"width\":1038,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":179460},\"original\":{\"file\":\"SHF_eb00226104.jpg\",\"width\":1351,\"height\":2000}}},{\"id\":6,\"width\":2000,\"height\":1331,\"alt\":\"B&uuml;hnenauftritt mit einer Person im blauen Kost&uuml;m auf einem Ger&uuml;st, w&auml;hrend im Hintergrund ein Mann projiziert wird.\",\"title\":\"\",\"description\":\"Heiner M&uuml;ller &ndash; Quartett. Material. Mit Corinna Harfouch, Oscar Olivo u. a.\",\"label\":\"\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss, Foto: David von Becker\",\"path\":\"\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"VB_4139-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":12135},\"large\":{\"file\":\"VB_4139-1024x681.jpg\",\"width\":1024,\"height\":681,\"mime-type\":\"image\\\/jpeg\",\"filesize\":78452},\"thumbnail\":{\"file\":\"VB_4139-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":5949},\"medium_large\":{\"file\":\"VB_4139-768x511.jpg\",\"width\":768,\"height\":511,\"mime-type\":\"image\\\/jpeg\",\"filesize\":49929},\"small\":{\"file\":\"VB_4139-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":21701},\"semi\":{\"file\":\"VB_4139-580x386.jpg\",\"width\":580,\"height\":386,\"mime-type\":\"image\\\/jpeg\",\"filesize\":32977},\"mobile\":{\"file\":\"VB_4139-720x479.jpg\",\"width\":720,\"height\":479,\"mime-type\":\"image\\\/jpeg\",\"filesize\":45142},\"hd\":{\"file\":\"VB_4139-1280x852.jpg\",\"width\":1280,\"height\":852,\"mime-type\":\"image\\\/jpeg\",\"filesize\":112136},\"full\":{\"file\":\"VB_4139-1920x1278.jpg\",\"width\":1920,\"height\":1278,\"mime-type\":\"image\\\/jpeg\",\"filesize\":225753},\"1536x1536\":{\"file\":\"VB_4139-1536x1022.jpg\",\"width\":1536,\"height\":1022,\"mime-type\":\"image\\\/jpeg\",\"filesize\":151639},\"original\":{\"file\":\"VB_4139.jpg\",\"width\":2000,\"height\":1331}}}]\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t<\/script>\n\n\t\t\t\t\t\t\t<swiper :options=\"options\" @slide-change=\"track\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" :key=\"image.id\" v-for=\"image in images\">\n\t\t\t\t\t\t\t\t\t<block-gallery-item inline-template :image=\"image\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"swiper-slide-image-wrapper\" ref=\"parent\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"width-container\" ref=\"container\" :style=\"style\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax-x=\"50%\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img :src=\"image.src\" :alt=\"image.alt\" v-if=\"image.id < 2\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" :data-src=\"image.src\" :alt=\"image.alt\" v-else>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/block-gallery-item>\n\n\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div v-if=\"image.label\" v-html=\"image.label\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div v-else-if=\"image.description\" v-html=\"image.description\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\" v-if=\"image.copyright\" v-html=\"'\u00a9 '+image.copyright\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"  slot=\"pagination\"><\/div>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-prev\" slot=\"button-prev\" aria-label=\"Vorheriges Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-next\" slot=\"button-next\" aria-label=\"N\u00e4chstes Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/swiper>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/block-gallery>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h4\">Beteiligte<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p><strong>Es spielen:<\/strong> Corinna Harfouch und Oscar Olivo<br \/>\n<strong>Sound:<\/strong> Hannes Gwisdek<br \/>\n<strong>Video:<\/strong> Roman Kuskowski<br \/>\n<strong>Regie:<\/strong> Marcel Kohler \/ Corinna Harfouch<br \/>\n<strong>Dramaturgie:<\/strong> Kristin Schulz<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n\n<section class=\"block block-accordion\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t<block-accordion inline-template>\n\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Corinna Harfouch\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"CorinnaHarfouch\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab0076a\" id=\"acc_title_6a56d3ab0076c\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Corinna Harfouch<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab0076a\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Corinna Harfouch, geboren in Suhl, studierte 1978 bis 1981 Schauspiel an der Hochschule f\u00fcr Schauspielkunst \u201eErnst Busch\u201c in Berlin. Nach dem Studium wird sie von Ruth Berghaus an das Berliner Theater im Palast (TiP) geholt (1980 Rolle der Lucie in <em>Stella<\/em>, 1981 Julia in <em>Romeo und Julia<\/em>, Regie: Christoph Schroth). 1982 folgte ein Engagement am St\u00e4dtischen Theater in Karl-Marx-Stadt, 1983 am Berliner Ensemble. Sie arbeitete mit Heiner M\u00fcller zusammen (u.a. als Lady M. in <em>Macbeth<\/em> 1982, Volksb\u00fchne Berlin) und trat in dessen St\u00fccken auf (u.a. in <em>Germania Tod in Berlin<\/em>, 1989). Seit 1991 ist sie freie Schauspielerin und war u.a. in Inszenierungen von Fritz Marquardt (<em>Eyolf<\/em>, 1995), J\u00fcrgen Gosch (<em>Wer hat Angst vor Virginia Woolf<\/em>, 2004, <em>Die M\u00f6we<\/em>, 2008), Herbert Fritsch (<em>Die Physiker<\/em>, 2013; <em>King Arthur,<\/em> 2016), Jan Bosse (<em>Herbstsonate<\/em>, 2014), Stefan Kimmig (<em>Wassa Schelesnowa<\/em>, 2014), Anna Bergmann (<em>Persona<\/em>, 2018, <em>Birthday Candles<\/em>, 2022), Christian Weise (<em>Macbeth,<\/em> 2018; <em>Queen Lear,<\/em> 2022), Lily Sykes (<em>Orlando,<\/em> 2019; <em>Annette, ein Heldinnenepos<\/em>, 2022) zu erleben. F\u00fcr ihre Theaterarbeiten erhielt Corinna Harfouch zahlreiche Auszeichnungen (u.a. 1996 Gertrud-Eysoldt-Ring, 1997 Schauspielerin des Jahres \u2013 f\u00fcr ihre Darstellung des General Harras in <em>Des Teufels General<\/em>, Regie: Frank Castorf; Theaterpreis Berlin 2015). Sie hat in mehr als 80 Film- und Kinoproduktionen mitgewirkt, darunter in: <em>Treffen in Travers<\/em> (1989, Regie: Michael Gwisdek), <em>Das Versprechen<\/em> (1994, Regie: Margarethe von Trotta), <em>Sexy Sadie<\/em> (1996, Regie: Matthias Glasner), <em>Gef\u00e4hrliche Freundin <\/em>(1996, Regie: Hermine Huntgeburth), <em>Das Mambospiel<\/em> (1998, Regie: Michael Gwisdek), <em>Bibi Blocksberg<\/em> (2002, Regie: Hermine Huntgeburth), <em>Der Untergang<\/em> (2004, Regie: Oliver Hirschbiegel), <em>Im Winter ein Jahr<\/em> (2008, Regie: Caroline Link), <em>Whisky mit Wodka<\/em> (2009, Regie: Andreas Dresen), <em>This is love<\/em> (2009, Regie: Matthias Glasner), <em>Guilias Verschwinden<\/em> (2009, Regie: Christoph Schaub), <em>Finsterworld<\/em> (2013, Regie: Frauke Finsterwalder), <em>Wer hat eigentlich die Liebe erfunden? (<\/em>2018, Regie: Kerstin Polte), <em>Lara<\/em> (2019, Regie: Jan-Ole Gerster), <em>Alles in bester Ordnung<\/em> (2021, Regie: Natja Brunckhorst), <em>Das M\u00e4dchen mit den goldenen H\u00e4nden (<\/em>2022, Regie: Katharina Marie Schubert), <em>Was man von hier aus sehen kann <\/em>(2022, Regie: Aron Lehmann), <em>Der Junge dem die Welt geh\u00f6rt<\/em> (2024, Regie: Robert Gwisdek), <em>Sterben<\/em> (2024, Regie: Matthias Glasner). Auch f\u00fcr ihre Filmarbeiten wurde Corinna Harfouch mit zahlreichen Preisen geehrt, zuletzt erhielt sie den Deutschen Filmpreis 2024 f\u00fcr die Beste weibliche Hauptrolle in Matthias Glasners <em>Sterben<\/em>.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Oscar Olivo\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"OscarOlivo\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab00f8e\" id=\"acc_title_6a56d3ab00f8f\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Oscar Olivo<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab00f8e\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Oscar Olivo, geboren 1981 in New York. 2003 Bachelor of Arts\/Theater an der Columbia University New York und 2008 Diplom an der Hochschule f\u00fcr Schauspielkunst Ernst Busch in Berlin, Abteilung Puppenspielkunst. Seitdem als Schauspieler und Puppenspieler zu Gast in diversen Produktionen, u. a. am Nationaltheater Mannheim, St. Ann&#8217;s Warehouse, St. P\u00f6lten Festspielhaus, am Staatstheater Stuttgart und am Schauspielhaus Graz. 2009\/10-2015\/16 war er festes Ensemblemitglied am Schauspiel Hannover. Danach gastierte er an verschiedenen Theatern, u. a. am Deutschen Nationaltheater Weimar, Staatstheater Augsburg, Staatstheater Darmstadt und am Maxim-Gorki-Theater Berlin (mit Tom K\u00fchnel, J\u00f6rn Hintzer, Jakob H\u00fcfner, Hans-Werner Kroesinger, Christian Weise und Yael Ronen). Am Schauspiel Hannover arbeitete er unter der Regie von Lily Sykes in <em>Orlando<\/em> (2019) sowie in <em>Annette, ein Heldinnenepos<\/em> (2022) mit Corinna Harfouch zusammen.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Marcel Kohler\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"MarcelKohler\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab011df\" id=\"acc_title_6a56d3ab011e1\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Marcel Kohler<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab011df\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Marcel Kohler, geboren 1991 in Mainz, studierte Schauspiel an der Hochschule f\u00fcr Schauspielkunst \u00bbErnst\u00a0<span class=\"w-term-highlight\">Busch<\/span>\u00ab in Berlin (2011 bis 2015). Er war Stipendiat der Studienstiftung des Deutschen Volkes. Bereits w\u00e4hrend des Studiums \u00fcbernahm er erste Rollen am Deutschen Theater Berlin, wo er von 2015-2023\u00a0<span class=\"w-term-highlight\">fest<\/span>\u00a0engagiert war. Zur Spielzeit 2023\/2024 wechselte er in das Ensemble der Schaub\u00fchne Berlin. Wiederkehrende Auftritte bei den Salzburger Festspielen. Er wurde mehrfach ausgezeichnet. Unter anderem erhielt er den Daphne-Preis, den O. E. Hasse-Preis, den Alfred\u2011Kerr\u2011Darstellerpreis f\u00fcr die beste Leistung eines jungen Schauspielers im Rahmen des Theatertreffens der Berliner Festspiele und wurde Nachwuchsschauspieler der Jahres 2016.<\/p>\n<p>Marcel Kohler arbeitet regelm\u00e4\u00dfig als Regisseur und B\u00fchnenbildner, beispielsweise am Nationaltheater Weimar, am Deutschen Theater Berlin und am Theater Heidelberg. Seine Inszenierungen wurden unter anderem beim \u201eFaust Preis\u201c in einer Retrospektive ausgezeichnet und erhielten 2021 den \u201eDr. Otto-Kasten-Preis\u201c der Intendant*innengruppe. Zudem wurden sie zu renommierten Festivals wie den Ruhrfestspielen, den M\u00fclheimer Theatertagen, Fringe Festival Beijing\/China, Gogol-Festival Kyiv\/Ukraine, Festival di Spoleto\/Italien oder dem Fiesad-Festival Rabbat\/Marokko eingeladen.<\/p>\n<p>Eine enge Zusammenarbeit verbindet Marcel Kohler mit der Schauspielerin Corinna Harfouch. Mit ihr inszenierte er zwei Monologe.<\/p>\n<p>Marcel Kohler ist Initiator und Gr\u00fcndungsmitglied des &#8222;Neuen K\u00fcnstlertheaters\u201c.<\/p>\n<p>Zuletzt erhielt er 2023 den \u201eKunstpreis Berlin\u201c der Akademie der K\u00fcnste.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Kristin Schulz\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"KristinSchulz\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab013cb\" id=\"acc_title_6a56d3ab013cd\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Kristin Schulz<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab013cb\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Kristin Schulz, *1975 in Jena, Autorin und Literaturwissenschaftlerin, lebt in Berlin. Sie ver\u00f6ffentlichte Prosa (u.a.\u00a0<em>Das Elsterneinmaleins,<\/em>\u00a02005) und Lyrik (u.a.\u00a0<em>Gesammelte Fehlm\u00e4rchen,<\/em>\u00a02014;\u00a0<em>Angewandte Verh\u00e4ltnisse,<\/em>\u00a02019). Zuletzt erschien:\u00a0<em>Hundert Arten auf den Wolf zu kommen<\/em>\u00a0(mit Illustrationen von Helge Leiberg, 2021, ausgezeichnet als Bilderbuch des Monats von der Deutschen Akademie f\u00fcr Kinder und Jugendliteratur). Sie leitet das \u201eHeiner M\u00fcller Archiv \/ Transitraum\u201c an der Humboldt-Universit\u00e4t zu Berlin und arbeitet auch als Herausgeberin, u.a. von Thomas Brasch und Heiner M\u00fcllers (u.a.\u00a0<em>M\u00fcller MP3<\/em>,<em>\u00a0<\/em>Alexander Verlag Berlin, Deutscher H\u00f6rbuchpreis 2012; Heiner M\u00fcllers:\u00a0<em>Warten auf der Gegenschr\u00e4ge<\/em>. Gesammelte Gedichte 2014).<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Roman Kuskowski\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"RomanKuskowski\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab0154b\" id=\"acc_title_6a56d3ab0154d\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Roman Kuskowski<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab0154b\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Roman Kuskowskiarbeitet seit \u00fcber 15 Jahren im Theater- und Opernkontext als visueller K\u00fcnstler und Techniker. Seine Leidenschaft f\u00fcr alle Formen von bewegten Pixeln, von klassischer Kameraarbeit und Videokonzeption \u00fcber 3D bis hin zu generativem Bewegtbild, zeichnet seine Arbeiten in verschiedensten Kontexten aus.<\/p>\n<p>Seit 2016 erforscht Roman die M\u00f6glichkeiten von KI im k\u00fcnstlerischen Kontext und dar\u00fcber hinaus. Er ist davon \u00fcberzeugt, dass die Verschmelzung von Kreativit\u00e4t und Technologie neue Horizonte er\u00f6ffnet und unsere Vorstellung von Kunst revolutioniert.<\/p>\n<p>Roman sieht es als Aufgabe, die Gesellschaft \u00fcber die weitreichenden Auswirkungen von KI aufzukl\u00e4ren und die Diskussion voranzutreiben.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Hannes Gwisdek\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"HannesGwisdek\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a56d3ab01766\" id=\"acc_title_6a56d3ab01768\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Hannes Gwisdek<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a56d3ab01766\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Hannes Gwisdek\u00a0alias Shaban lebt und leibt in Berlin. Dort hat er sein Studio, sein Hauptquartier, von wo aus er unter anderem f\u00fcr Theater, Filme, Stummfilmabende und den Hip Hop Act \u201eK\u00e4ptn Peng\u201c komponiert, produziert und experimentiert, u.a. f\u00fcr\u00a0<em>Die K\u00e4nguru<\/em>\u00a0<em>Verschw\u00f6rung<\/em>, Soundtrack Kino, Regie: M. U. Kling, 2022;\u00a0<em>Birthday Candles<\/em>, Deutsches Theater Berlin, Regie: A. Bergmann 2022; Sukini, Album\u00a0<em>Schmetterlingskacke<\/em>, Universal 2019;\u00a0<em>Hundert Songs<\/em>, Die Staatstheater Stuttgart, Regie: R. Schimmelpfennig; 2019; D!E G\u00e4NG, Album 2, Oettinger 2019;\u00a0<em>Wer hat eigentlich die Liebe erfunden<\/em>, Soundtrack, Regie: Kerstin Polte 2018;\u00a0<em>Persona<\/em>\u00a0Stadsteater Malm\u00f6\/ DT Berlin, Regie: A. Bergmann 2018 (eingeladen zum Berliner Theatertreffen); K\u00e4ptn Peng und die Tentakel von Delphi, Album\u00a0<em>Das nullte Kapitel;<\/em>\u00a0Kreismusik 2017; Pavlidis, Album Identitetris, Kreismusik 2016;\u00a0<em>Der Herzerlfresser<\/em>, Burgtheater (Akademie) Wien, Regie: A. Wiegold 2016;\u00a0<em>Terror,<\/em>\u00a0Schauspielhaus Hamburg \u2013 Regie: J. Bochow &amp; R. Thiele 2016;\u00a0<em>Fr\u00e4ulein Julie<\/em>, Theater in der Josefstadt, Regie: A. Bergmann 2015 (nominiert f\u00fcr Nestroy, beste Regie);\u00a0<em>Der Auftrag,<\/em>\u00a0Staatstheater Hannover, Regie: T. K\u00fchnel &amp; J. Kuttner 2015).<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/block-accordion>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"block block-headline block-no-margin \" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h6\">Partner<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-logos\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-sm-8 col-sm-offset-2\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<div class=\"row  middle-xs\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col-xs-4 col-sm-3 col-sm-2\">\n\t\t\t\t\t\t\t<div class=\"box margin-sixth-top\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" alt=\"Heiner M\u00fcller Archiv\" src=\"https:\/\/www.humboldtforum.org\/wp-content\/uploads\/2024\/05\/SHF_eb00224391.jpg\" style=\"display: inline-block; width: 100%\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"block block-teaser col-1 has-bg\" style=\"--teaser-bg:#f2f2f2\">\n\t<lazy-component :fixed-min-height=\"400\">\n\t\n\t\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t<div class=\"row bottom-xs\">\n\t\t\t\t\t<div class=\"col-xs-12 col-sm-10 col-md-8 col-sm-offset-1 col-md-offset-2\">\n\t\t\t\t\t\t<h4>geh\u00f6rt zu<\/h4>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"col-xs-12 col-sm-10 col-md-8 col-sm-offset-1 col-md-offset-2 start-xs end-md margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"row\">\n\t\t\t\n<li class=\"col-xs-12 teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"12636414524\" rawitem='{&quot;postId&quot;:126364,&quot;title&quot;:&quot;Transformiert euch!&quot;,&quot;excerpt&quot;:&quot;&quot;,&quot;slug&quot;:&quot;transformiert-euch&quot;,&quot;post_date&quot;:&quot;2024-03-15T15:10&quot;,&quot;type&quot;:&quot;event-multi&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/event\\\/thementag\\\/transformiert-euch-126364\\\/&quot;,&quot;genre&quot;:[820],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Thementag&quot;,&quot;id&quot;:820,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;stakeholder&quot;:[382],&quot;stakeholder_details&quot;:[{&quot;text&quot;:&quot;Stiftung Humboldt Forum im Berliner Schloss&quot;,&quot;id&quot;:382,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;language&quot;:[384],&quot;language_details&quot;:[{&quot;text&quot;:&quot;Deutsch&quot;,&quot;id&quot;:384,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[957,1558,1179,883],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Foyer, Saal 1, EG, Saal 2, EG&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;belongsto&quot;:[116558],&quot;shorturl&quot;:&quot;&quot;,&quot;times&quot;:[],&quot;planning&quot;:{&quot;price&quot;:&quot;Viele Angebote kostenfrei&quot;,&quot;admission&quot;:&quot;&quot;,&quot;pause&quot;:&quot;&quot;,&quot;duration&quot;:&quot;&quot;,&quot;status&quot;:&quot;BUY&quot;,&quot;info&quot;:&quot;&quot;,&quot;shop&quot;:&quot;&quot;,&quot;can_purchase&quot;:false},&quot;tickettext&quot;:&quot;F\\u00fcr einzelne Veranstaltungen sind Tickets erforderlich. Die Preise sind bei den jeweiligen Programmangeboten vermerkt.&quot;,&quot;additional_info&quot;:{&quot;icon&quot;:&quot;icon-bullet_active&quot;,&quot;text&quot;:&quot;W\\u00e4hrend der Thementage: 50% Erm\\u00e4\\u00dfigung auf das Tagesticket f\\u00fcr die Ausstellung \\&quot;Hin und Weg. Der Palast der Republik ist Gegenwart\\&quot;&quot;},&quot;highlight_header&quot;:true,&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:true,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;has_mobile_format&quot;:true,&quot;highlight_header_image&quot;:135112,&quot;events&quot;:{&quot;0&quot;:133562,&quot;1&quot;:133564,&quot;2&quot;:133574,&quot;3&quot;:133584,&quot;4&quot;:133585,&quot;5&quot;:133614,&quot;6&quot;:133626,&quot;7&quot;:133743,&quot;8&quot;:133765,&quot;9&quot;:128778,&quot;10&quot;:135618,&quot;11&quot;:135651,&quot;12&quot;:135670,&quot;13&quot;:136013,&quot;14&quot;:136448,&quot;15&quot;:136563,&quot;19&quot;:137470,&quot;20&quot;:137497,&quot;21&quot;:137593,&quot;22&quot;:137649,&quot;23&quot;:137835,&quot;24&quot;:137839},&quot;highlight_header_image_mobile&quot;:135115,&quot;subline&quot;:&quot;\\u00dcber die Zeit nach 1989 sprechen&quot;},&quot;date&quot;:{&quot;NX&quot;:null,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202410060700&quot;,&quot;from_DATE&quot;:&quot;20241003 15:00&quot;,&quot;from&quot;:1727953200,&quot;to&quot;:1728198000,&quot;to_DATE&quot;:&quot;20241006 11:00&quot;,&quot;from_HRFSHORT&quot;:&quot; 3. Okt 2024&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Do 03.10.2024&quot;,&quot;to_HRFSHORT&quot;:&quot; 6. Okt 2024&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 06.10.2024&quot;,&quot;from_HRF&quot;:&quot;Do,  3. Oktober 2024&quot;,&quot;to_HRF&quot;:&quot;So,  6. Oktober 2024&quot;,&quot;from_to_HRF&quot;:&quot;Do,  3. Oktober \\u2013 So,  6. Oktober 2024&quot;,&quot;from_to_HRFSHORT&quot;:&quot; 3. Okt \\u2013  6. Okt 2024&quot;},&quot;alert&quot;:&quot;Highlight&quot;,&quot;partof&quot;:[],&quot;marketing_topic&quot;:{&quot;title&quot;:&quot;Hin und weg. Der Palast der Republik ist Gegenwart&quot;,&quot;ID&quot;:116558,&quot;reason&quot;:&quot;belongsto&quot;}}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/event\/thementag\/transformiert-euch-126364\/\" class=\"teaser teaser-event-multi teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-sm-6 col-md-5 col-sm-offset-1 col-md-offset-2 first-sm teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant clamp-2\">Hin und weg. Der Palast der Republik ist Gegenwart<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom h5\">Transformiert euch!<\/strong>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"\">\u00dcber die Zeit nach 1989 sprechen<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-sm-4 col-md-3 teaser-event-image bottom-xs first-xs\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">Highlight<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56d3ab38e65\" aria-labelledby=\"desc_media_6a56d3ab38e65\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00228711-176x300.jpg\",\"width\":176,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":16764},\"large\":{\"file\":\"SHF_eb00228711-600x1024.jpg\",\"width\":600,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":140024},\"thumbnail\":{\"file\":\"SHF_eb00228711-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8837},\"medium_large\":{\"file\":\"SHF_eb00228711-768x1312.jpg\",\"width\":768,\"height\":1312,\"mime-type\":\"image\\\/jpeg\",\"filesize\":211010},\"small\":{\"file\":\"SHF_eb00228711-258x440.jpg\",\"width\":258,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":33278},\"semi\":{\"file\":\"SHF_eb00228711-340x580.jpg\",\"width\":340,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":53974},\"mobile\":{\"file\":\"SHF_eb00228711-422x720.jpg\",\"width\":422,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":77287},\"hd\":{\"file\":\"SHF_eb00228711-749x1280.jpg\",\"width\":749,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":203401},\"full\":{\"file\":\"SHF_eb00228711-1124x1920.jpg\",\"width\":1124,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":393586},\"1536x1536\":{\"file\":\"SHF_eb00228711-899x1536.jpg\",\"width\":899,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":275356},\"original\":{\"file\":\"SHF_eb00228711.jpg\",\"width\":1171,\"height\":2000}},\n\t\t\t\t\"alt\" : \"Graffiti eines Autos, das aus einer zerbrochenen Wand bricht, mit bunten Farben und betonten Details.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:170.79419299744%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56d3ab38e65\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a56d3ab38e65\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Keyvisual Thementag &#8211; East Side Gallery Berlin: &quot;Test The Best&quot; von Birgit Kinder <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss, Foto: picture alliance \/ Hubert Link<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n\n<li class=\"col-xs-12 teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"1263579161\" rawitem='{&quot;postId&quot;:126357,&quot;title&quot;:&quot;Ohne Ende Palast&quot;,&quot;excerpt&quot;:&quot;&quot;,&quot;slug&quot;:&quot;ohne-ende-palast&quot;,&quot;post_date&quot;:&quot;2024-03-15T14:42&quot;,&quot;type&quot;:&quot;event-multi&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/event\\\/gespraech\\\/ohne-ende-palast-126357\\\/&quot;,&quot;genre&quot;:[1078,820],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Gespr\\u00e4ch&quot;,&quot;id&quot;:1078,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Thementag&quot;,&quot;id&quot;:820,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;stakeholder&quot;:[382],&quot;stakeholder_details&quot;:[{&quot;text&quot;:&quot;Stiftung Humboldt Forum im Berliner Schloss&quot;,&quot;id&quot;:382,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[957,1558,1179,883,510],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Foyer, Saal 1, EG, Saal 2, EG, Schl\\u00fcterhof&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;belongsto&quot;:[116558],&quot;shorturl&quot;:&quot;ohne-ende-plast&quot;,&quot;times&quot;:[],&quot;planning&quot;:{&quot;price&quot;:&quot;&quot;,&quot;admission&quot;:&quot;&quot;,&quot;pause&quot;:&quot;&quot;,&quot;duration&quot;:&quot;&quot;,&quot;status&quot;:&quot;BUY&quot;,&quot;info&quot;:&quot;&quot;,&quot;shop&quot;:&quot;&quot;,&quot;can_purchase&quot;:false},&quot;tickettext&quot;:&quot;Einzelne Programmpunkte kostenpflichtig&quot;,&quot;additional_info&quot;:{&quot;icon&quot;:&quot;icon-uhr&quot;,&quot;text&quot;:&quot;Am Samstag, den 15.6.2024 ist die Ausstellung \\&quot;Hin und weg. Der Palast der Republik ist Gegenwart\\&quot; bis 21:00 ge\\u00f6ffnet&quot;},&quot;highlight_header&quot;:true,&quot;featured_images&quot;:[126353],&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:false,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;has_mobile_format&quot;:true,&quot;highlight_header_image&quot;:129413,&quot;events&quot;:[126300,128458,128778,128786,129213,129239,129594,130924],&quot;subline&quot;:&quot;Erinnerungen an den Palast der Republik&quot;,&quot;highlight_header_image_mobile&quot;:129415},&quot;date&quot;:{&quot;NX&quot;:null,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202406160700&quot;,&quot;from_DATE&quot;:&quot;20240615 11:00&quot;,&quot;from&quot;:1718434800,&quot;to&quot;:1718521200,&quot;to_DATE&quot;:&quot;20240616 11:00&quot;,&quot;from_HRFSHORT&quot;:&quot;15. Jun 2024&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Sa 15.06.2024&quot;,&quot;to_HRFSHORT&quot;:&quot;16. Jun 2024&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 16.06.2024&quot;,&quot;from_HRF&quot;:&quot;Sa, 15. Juni 2024&quot;,&quot;to_HRF&quot;:&quot;So, 16. Juni 2024&quot;,&quot;from_to_HRF&quot;:&quot;Sa, 15. Juni \\u2013 So, 16. Juni 2024&quot;,&quot;from_to_HRFSHORT&quot;:&quot;15. Jun \\u2013 16. Jun 2024&quot;},&quot;alert&quot;:&quot;Highlight&quot;,&quot;partof&quot;:[],&quot;marketing_topic&quot;:{&quot;title&quot;:&quot;Hin und weg. Der Palast der Republik ist Gegenwart&quot;,&quot;ID&quot;:116558,&quot;reason&quot;:&quot;belongsto&quot;}}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/event\/gespraech\/ohne-ende-palast-126357\/\" class=\"teaser teaser-event-multi teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-sm-6 col-md-5 col-sm-offset-1 col-md-offset-2 first-sm teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant clamp-2\">Hin und weg. Der Palast der Republik ist Gegenwart<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom h5\">Ohne Ende Palast<\/strong>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"\">Erinnerungen an den Palast der Republik<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-sm-4 col-md-3 teaser-event-image bottom-xs first-xs\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">Highlight<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56d3ab395a8\" aria-labelledby=\"desc_media_6a56d3ab395a8\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-176x300.jpg\",\"width\":176,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":4230},\"large\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-600x1024.jpg\",\"width\":600,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23580},\"thumbnail\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":3026},\"medium_large\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-768x1312.jpg\",\"width\":768,\"height\":1312,\"mime-type\":\"image\\\/jpeg\",\"filesize\":34908},\"small\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-258x440.jpg\",\"width\":258,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7004},\"semi\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-340x580.jpg\",\"width\":340,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":10084},\"mobile\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-422x720.jpg\",\"width\":422,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":13858},\"hd\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-749x1280.jpg\",\"width\":749,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":33583},\"full\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-1124x1920.jpg\",\"width\":1124,\"height\":1920,\"mime-type\":\"image\\\/jpeg\",\"filesize\":66347},\"1536x1536\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-899x1536.jpg\",\"width\":899,\"height\":1536,\"mime-type\":\"image\\\/jpeg\",\"filesize\":45494},\"2048x2048\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px-1199x2048.jpg\",\"width\":1199,\"height\":2048,\"mime-type\":\"image\\\/jpeg\",\"filesize\":73944},\"original\":{\"file\":\"PdR_ThemenWE_1_Webteaser_hoch_1780x3040px.jpg\",\"width\":1780,\"height\":3040}},\n\t\t\t\t\"alt\" : \"Teekanne mit passender Tasse und Untertasse im stilvollen Design und in orangefarbener Farbgebung.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"43.41\",\"left\":\"49.53\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:170.78651685393%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56d3ab395a8\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a56d3ab395a8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss, Foto: Sebastian Eggler<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n\n<li class=\"col-xs-12 teaser-wrapper col-padding-remove\">\n\t<calendarteaser key=\"1165587414\" rawitem='{&quot;postId&quot;:116558,&quot;title&quot;:&quot;Hin und weg. Der Palast der Republik ist Gegenwart&quot;,&quot;excerpt&quot;:&quot;&quot;,&quot;slug&quot;:&quot;hin-und-weg-der-palast-der-republik-ist-gegenwart&quot;,&quot;post_date&quot;:&quot;2023-12-18T15:27&quot;,&quot;type&quot;:&quot;event-period&quot;,&quot;permalink&quot;:&quot;https:\\\/\\\/www.humboldtforum.org\\\/de\\\/programm\\\/laufzeitangebot\\\/ausstellung\\\/hin-und-weg-der-palast-der-republik-ist-gegenwart-116558\\\/&quot;,&quot;genre&quot;:[391,879],&quot;genre_details&quot;:[{&quot;text&quot;:&quot;Ausstellung&quot;,&quot;id&quot;:391,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Programm&quot;,&quot;id&quot;:879,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;language&quot;:[384,385],&quot;language_details&quot;:[{&quot;text&quot;:&quot;Deutsch&quot;,&quot;id&quot;:384,&quot;icon&quot;:null,&quot;parent&quot;:0},{&quot;text&quot;:&quot;Englisch&quot;,&quot;id&quot;:385,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;accessability&quot;:[430],&quot;accessability_details&quot;:[{&quot;text&quot;:&quot;Rollstuhlgerecht&quot;,&quot;id&quot;:430,&quot;icon&quot;:null,&quot;parent&quot;:0}],&quot;place&quot;:[1391],&quot;place_details&quot;:{&quot;place&quot;:&quot;Humboldt Forum&quot;,&quot;map&quot;:&quot;Humboldt Forum, Schlossplatz, Berlin&quot;,&quot;room&quot;:&quot;Sonderausstellung 1+2, EG&quot;},&quot;icon_overwrite&quot;:&quot;&quot;,&quot;acf&quot;:{&quot;noindex&quot;:false,&quot;keywords&quot;:&quot;&quot;,&quot;shorturl&quot;:&quot;pdr&quot;,&quot;planning&quot;:{&quot;price&quot;:&quot;12 \\u20ac \\\/ 6 \\u20ac&quot;,&quot;status&quot;:&quot;BUY&quot;,&quot;info&quot;:&quot;&quot;,&quot;shop&quot;:&quot;https:\\\/\\\/tickets.humboldtforum.org\\\/#\\\/tickets\\\/time?museum_id=1&amp;exhibition_id=16&amp;group=day&amp;date=2024-05-17&quot;,&quot;can_purchase&quot;:true},&quot;use_opening_hours_of_the_house&quot;:false,&quot;periods&quot;:[{&quot;label&quot;:&quot;&quot;,&quot;dates&quot;:[{&quot;start&quot;:&quot;202405170000&quot;,&quot;end&quot;:&quot;202502160000&quot;,&quot;has_end&quot;:true,&quot;start_HRFSHORT&quot;:&quot;17.05.24&quot;,&quot;start_HRFSHORT_WD&quot;:&quot;Fr 17.05.2024&quot;,&quot;end_HRFSHORT&quot;:&quot;16.02.25&quot;}],&quot;monday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;tuesday&quot;:[{&quot;start&quot;:null,&quot;end&quot;:null,&quot;closed&quot;:true}],&quot;wednesday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;thursday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;friday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;saturday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;sunday&quot;:[{&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;18:30&quot;,&quot;closed&quot;:false}],&quot;info&quot;:&quot;&quot;,&quot;description&quot;:&quot;&quot;}],&quot;display_as_single&quot;:false,&quot;additional_info&quot;:{&quot;icon&quot;:&quot;icon-plus&quot;,&quot;text&quot;:&quot;02.02.2025 - Freier Eintritt zur Ausstellung&quot;},&quot;highlight_header&quot;:true,&quot;use_video_in_teasers&quot;:false,&quot;hyphenation&quot;:true,&quot;tipp&quot;:false,&quot;joker&quot;:false,&quot;live&quot;:false,&quot;hide_event_in_program&quot;:false,&quot;featured_images&quot;:[116564],&quot;highlight_header_image&quot;:121963,&quot;has_mobile_format&quot;:true,&quot;highlight_header_image_mobile&quot;:121972,&quot;events&quot;:{&quot;0&quot;:122077,&quot;1&quot;:124724,&quot;2&quot;:125238,&quot;3&quot;:125248,&quot;4&quot;:125394,&quot;5&quot;:125416,&quot;6&quot;:125424,&quot;7&quot;:125439,&quot;8&quot;:125447,&quot;9&quot;:125456,&quot;10&quot;:125462,&quot;11&quot;:126357,&quot;12&quot;:126364,&quot;13&quot;:126372,&quot;15&quot;:117014,&quot;17&quot;:127794,&quot;18&quot;:127824,&quot;19&quot;:128041,&quot;20&quot;:129239,&quot;21&quot;:129315,&quot;22&quot;:128832,&quot;23&quot;:86151,&quot;24&quot;:132018,&quot;25&quot;:132493,&quot;27&quot;:133564,&quot;28&quot;:134436,&quot;29&quot;:134443,&quot;30&quot;:135781,&quot;31&quot;:136013,&quot;32&quot;:136448,&quot;33&quot;:136563,&quot;34&quot;:137470,&quot;35&quot;:137497,&quot;36&quot;:137593,&quot;37&quot;:137649,&quot;38&quot;:137835,&quot;39&quot;:137839,&quot;40&quot;:139385,&quot;41&quot;:139582,&quot;42&quot;:140153,&quot;43&quot;:141223,&quot;44&quot;:141278,&quot;45&quot;:141282,&quot;46&quot;:141371,&quot;47&quot;:141393},&quot;video&quot;:124298,&quot;tickettext&quot;:&quot;Tagesticket erforderlich&quot;,&quot;infotext&quot;:&quot;Letzter Einlass 17:30 Uhr&quot;,&quot;period_exception&quot;:[{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202412240000&quot;,&quot;closed&quot;:true,&quot;start&quot;:null,&quot;end&quot;:null,&quot;date_HRFSHORT&quot;:&quot;24.12.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202412250000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;12:00&quot;,&quot;end&quot;:&quot;18:00&quot;,&quot;date_HRFSHORT&quot;:&quot;25.12.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202412260000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;12:00&quot;,&quot;end&quot;:&quot;18:00&quot;,&quot;date_HRFSHORT&quot;:&quot;26.12.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202412310000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;16:30&quot;,&quot;date_HRFSHORT&quot;:&quot;31.12.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202501010000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;12:00&quot;,&quot;end&quot;:&quot;18:00&quot;,&quot;date_HRFSHORT&quot;:&quot;01.01.25&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202410030000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;21:00&quot;,&quot;date_HRFSHORT&quot;:&quot;03.10.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202410040000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;21:00&quot;,&quot;date_HRFSHORT&quot;:&quot;04.10.24&quot;},{&quot;label&quot;:&quot;&quot;,&quot;date&quot;:&quot;202410050000&quot;,&quot;closed&quot;:false,&quot;start&quot;:&quot;10:30&quot;,&quot;end&quot;:&quot;21:00&quot;,&quot;date_HRFSHORT&quot;:&quot;05.10.24&quot;}]},&quot;period_list&quot;:&quot;&quot;,&quot;period_exception&quot;:&quot;&quot;,&quot;date&quot;:{&quot;infinite&quot;:false,&quot;from_DATE&quot;:202405170000,&quot;from&quot;:1715941800,&quot;from_TIME&quot;:&quot;10:30&quot;,&quot;to&quot;:1739730600,&quot;to_DATE&quot;:202502160000,&quot;to_TIME&quot;:&quot;18:30&quot;,&quot;from_HRFSHORT&quot;:&quot;17. Mai 2024&quot;,&quot;from_HRFSHORT_WD&quot;:&quot;Fr 17.05.2024&quot;,&quot;from_HRF&quot;:&quot;Fr, 17. Mai 2024&quot;,&quot;to_HRF&quot;:&quot;So, 16. Februar 2025&quot;,&quot;to_HRFSHORT&quot;:&quot;16. Feb 2025&quot;,&quot;to_HRFSHORT_WD&quot;:&quot;So 16.02.2025&quot;,&quot;from_to_HRF&quot;:&quot;Fr, 17. Mai 2024 \\u2013 So, 16. Februar 2025&quot;,&quot;from_to_HRFSHORT&quot;:&quot;17. Mai 2024 \\u2013 16. Feb 2025&quot;,&quot;NXX&quot;:null,&quot;NLAST&quot;:&quot;202502161830&quot;},&quot;alert&quot;:&quot;Highlight&quot;,&quot;partof&quot;:[],&quot;marketing_topic&quot;:&quot;&quot;}' inline-template>\n\t<a href=\"https:\/\/www.humboldtforum.org\/de\/programm\/laufzeitangebot\/ausstellung\/hin-und-weg-der-palast-der-republik-ist-gegenwart-116558\/\" class=\"teaser teaser-event-period teaser-event-standard\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-sm-6 col-md-5 col-sm-offset-1 col-md-offset-2 first-sm teaser-event-text Infos\">\n\t\t\t\t<div class=\"teaser-event-standard-text\">\n\t\t\t\t\t<div class=\"margin-bottom-atom\">\n\t\t\t\t\t\t<div class=\"subline clamp-1\" v-html=\"maingenre\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t<strong class=\"margin-bottom-atom h5\">Hin und weg. Der Palast der Republik ist Gegenwart<\/strong>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"teaser-bottom border-bottom\">\n\t\t\t\t<calendardateline :rawitem='item' :show-icon=\"true\"><\/calendardateline>\n\t\t\t\t\t<hr>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-sm-4 col-md-3 teaser-event-image bottom-xs first-xs\">\n\t\t\t\t<div class=\"teaser-image teaser-image-no-alternate\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"alert\">Highlight<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56d3ab39c96\" aria-labelledby=\"desc_media_6a56d3ab39c96\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00216226-176x300.jpg\",\"width\":176,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":15787},\"large\":{\"file\":\"SHF_eb00216226-599x1024.jpg\",\"width\":599,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":106669},\"thumbnail\":{\"file\":\"SHF_eb00216226-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8255},\"medium_large\":{\"file\":\"SHF_eb00216226-768x1312.jpg\",\"width\":768,\"height\":1312,\"mime-type\":\"image\\\/jpeg\",\"filesize\":157569},\"small\":{\"file\":\"SHF_eb00216226-258x440.jpg\",\"width\":258,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":29161},\"semi\":{\"file\":\"SHF_eb00216226-339x580.jpg\",\"width\":339,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":44726},\"mobile\":{\"file\":\"SHF_eb00216226-421x720.jpg\",\"width\":421,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":61905},\"hd\":{\"file\":\"SHF_eb00216226-749x1280.jpg\",\"width\":749,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":151325},\"original\":{\"file\":\"SHF_eb00216226.jpg\",\"width\":878,\"height\":1500}},\n\t\t\t\t\"alt\" : \"Modernes Design mit gro\\u00dfem Symbol in der Mitte, stylischen Lampen und zwei Personen im Vordergrund.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"31.60\",\"left\":\"49.69\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:170.84282460137%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56d3ab39c96\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a56d3ab39c96\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss, Foto: bpk \/ Gerhard Kiesling<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n\t<\/calendarteaser>\n<\/li>\n\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t\t<\/lazy-component>\n<\/section>\n\n\n\n\n\n<section class=\"block block-CTA block-CTA-long leftgradient\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/newsletter-2\/\" aria-label=\"Bleiben Sie auf dem Laufenden!\" class=\"teaser teaser-cta-wide \">\n\t\t\t\t\t\t<div class=\"teaser-image\">\n\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56d3ab3c26f\" aria-labelledby=\"desc_media_6a56d3ab3c26f\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00061823-scaled-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":19186},\"large\":{\"file\":\"HF_eb00061823-scaled-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":138597},\"thumbnail\":{\"file\":\"HF_eb00061823-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8513},\"medium_large\":{\"file\":\"HF_eb00061823-scaled-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":86200},\"small\":{\"file\":\"HF_eb00061823-scaled-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":35525},\"semi\":{\"file\":\"HF_eb00061823-scaled-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":55724},\"mobile\":{\"file\":\"HF_eb00061823-scaled-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":77971},\"hd\":{\"file\":\"HF_eb00061823-scaled-1280x854.jpg\",\"width\":1280,\"height\":854,\"mime-type\":\"image\\\/jpeg\",\"filesize\":202477},\"full\":{\"file\":\"HF_eb00061823-scaled-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":386736},\"1536x1536\":{\"file\":\"HF_eb00061823-scaled-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":266197},\"2048x2048\":{\"file\":\"HF_eb00061823-scaled-2048x1366.jpg\",\"width\":2048,\"height\":1366,\"mime-type\":\"image\\\/jpeg\",\"filesize\":430206},\"original\":{\"file\":\"HF_eb00061823-scaled.jpg\",\"width\":2560,\"height\":1707}},\n\t\t\t\t\"alt\" : \"Blick in das beleuchtete Foyer von der Galerie im ersten Stock mit Besuchenden, Infopoint und Medienturm\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"70\",\n\t\t\t\t\"crop\" : {\"top\":\"90.37\",\"left\":\"39.93\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.6796875%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56d3ab3c26f\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a56d3ab3c26f\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Blick in das Foyer, November 2019.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ David von Becker<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"teaser-content \">\n\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"teaser-header\"><span class=\"h3\">Bleiben Sie auf dem Laufenden!<\/span><\/div>\n\t\t\t\t\t\t\t\t<div class=\"teaser-subline\"><span class=\"font-decoration\">Abonnieren Sie unseren Newsletter.<\/span><\/div>\t\t\t\t\t\t\t\t<button tabindex=\"-1\" class=\"border\">Hier klicken<\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"template":"","genre":[823],"digital":[],"topic":[],"stakeholder":[382],"editorial":[],"editorialfilter":[],"targetgroup":[383],"language":[384],"accessability":[],"age":[],"school":[],"groupsize":[],"place":[883],"class_list":["post-128778","event","type-event","status-publish","hentry","genre-schauspiel","stakeholder-stiftung-humboldt-forum-im-berliner-schloss","targetgroup-erwachsene","language-deutsch","place-saal-2-eg"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/128778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/types\/event"}],"version-history":[{"count":11,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/128778\/revisions"}],"predecessor-version":[{"id":133862,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/event\/128778\/revisions\/133862"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media?parent=128778"}],"wp:term":[{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/genre?post=128778"},{"taxonomy":"digital","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/digital?post=128778"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/topic?post=128778"},{"taxonomy":"stakeholder","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/stakeholder?post=128778"},{"taxonomy":"editorial","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorial?post=128778"},{"taxonomy":"editorialfilter","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/editorialfilter?post=128778"},{"taxonomy":"targetgroup","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/targetgroup?post=128778"},{"taxonomy":"language","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/language?post=128778"},{"taxonomy":"accessability","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/accessability?post=128778"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/age?post=128778"},{"taxonomy":"school","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/school?post=128778"},{"taxonomy":"groupsize","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/groupsize?post=128778"},{"taxonomy":"place","embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/place?post=128778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}