{"id":2711,"date":"2020-04-29T15:19:22","date_gmt":"2020-04-29T13:19:22","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?page_id=2711"},"modified":"2026-08-12T16:43:28","modified_gmt":"2026-08-12T14:43:28","slug":"rekonstruktion","status":"publish","type":"page","link":"https:\/\/www.humboldtforum.org\/de\/architektur\/rekonstruktion\/","title":{"rendered":"Rekonstruktion"},"content":{"rendered":"<section class=\"block block-header-headline hyph-disable\" >\n    <div class=\"container-fluid\">\n        <div class=\"row\">\n\t\t\t\n                            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                    <div class=\"box\">\n                        <h1>Rekonstruktion<\/h1>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-header\" >\n\t<block-header inline-template>\n\t\t<figure role=\"group\" aria-labelledby=\"desc_m_6a9888790aa87\">\n\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes_d\" : {\"medium\":{\"file\":\"HF_eb00031350-1-scaled-300x203.jpg\",\"width\":300,\"height\":203,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031350-1-scaled-1024x692.jpg\",\"width\":1024,\"height\":692,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031350-1-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031350-1-scaled-768x519.jpg\",\"width\":768,\"height\":519,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031350-1-scaled-440x297.jpg\",\"width\":440,\"height\":297,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031350-1-scaled-580x392.jpg\",\"width\":580,\"height\":392,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031350-1-scaled-720x487.jpg\",\"width\":720,\"height\":487,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031350-1-scaled-1280x865.jpg\",\"width\":1280,\"height\":865,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031350-1-scaled-1920x1298.jpg\",\"width\":1920,\"height\":1298,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031350-1-scaled-1536x1038.jpg\",\"width\":1536,\"height\":1038,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031350-1-scaled-2048x1384.jpg\",\"width\":2048,\"height\":1384,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031350-1-scaled.jpg\",\"width\":2560,\"height\":1730}},\n\t\t\t\t\"alt_d\" : \"Steinbildhauer beim Bearbeiten eines L\\u00f6wenkopfs an der Fassade\",\n\t\t\t\t\"path_d\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"autoplay_d\" : null,\n\t\t\t\t\"crop_d\" : {\"top\":\"48.43\",\"left\":\"47.79\"},\n\t\t\t\t\"background_d\" : true,\n\t\t\t\t\"scale_d\" : 2,\n\n\t\t\t\t\"sizes_m\" : {\"medium\":{\"file\":\"HF_eb00020326-169x300.jpg\",\"width\":169,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00020326-576x1024.jpg\",\"width\":576,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00020326-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00020326-768x1366.jpg\",\"width\":768,\"height\":1366,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00020326-247x440.jpg\",\"width\":247,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00020326-326x580.jpg\",\"width\":326,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00020326-405x720.jpg\",\"width\":405,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00020326-720x1280.jpg\",\"width\":720,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"}},\n\t\t\t\t\"alt_m\" : \"Ein Bildhauer arbeitet am Tonmodell eines befl\\u00fcgelten L\\u00f6wen\",\n\t\t\t\t\"path_m\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"autoplay_m\" : null,\n\t\t\t\t\"crop_m\" : {\"top\":\"23.49\",\"left\":\"50.01\"},\n\t\t\t\t\"background_m\" : true,\n\t\t\t\t\"scale_m\" : 2,\n\n\t\t\t\t\"has_mobile_format\" : true,\n\t\t\t\t\"has_ad\" : false,\n\t\t\t\t\"audio_description_yt\" : null\t\t\t\t}\n\t\t\t<\/script>\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:67.578125%;\" v-if=\"sizes\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t<lazy-media :inline=\"true\" :scale=\"scale\" :alt=\"alt\" :sizes=\"sizes\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_m_6a9888790aa87\"><\/lazy-media>\n\t\t\t\t<button class=\"autoplay-audio-description-btn icon-background icon-audio-describtions\" @click=\"audioDescriptionPlay\" v-if=\"hasAudioDescription\" aria-label=\"Audiodeskription aufrufen\"><\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny insignificant\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_m_6a9888790aa87\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t<div>500 L&ouml;wenk&ouml;pfe schm&uuml;cken die Fassade &ndash; allesamt einzigartig, jeder einzeln per Hand gemei&szlig;elt.<\/div>\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Rolf Schulten<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t<\/block-header>\n<\/section>\n\n<section class=\"block block-headline block-no-margin  hyph-disable\" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h2\">Barock heute<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p class=\"p1\"><span class=\"s1\">Der Deutsche Bundestag beschloss 2002, das im Zweiten Weltkrieg stark besch\u00e4digte und 1950 gesprengte Berliner Schloss \u00e4u\u00dferlich wieder aufzubauen. Drei der barocken Au\u00dfenfassaden samt der Kuppel und drei der Fassaden des historischen Schl\u00fcterhofes sollten detailgetreu rekonstruiert werden, um das historische Stadtbild um den Lustgarten zu erg\u00e4nzen und die herausragende k\u00fcnstlerische Gestaltung der barocken Baumeister Andreas Schl\u00fcter und Johann Friedrich von Eosander zu w\u00fcrdigen.<\/span><\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-standard-image\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-10 col-md-6 col-xs-offset-1 col-md-offset-3\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a9888790fcf4\" aria-labelledby=\"desc_media_6a9888790fcf4\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-227x300.jpg\",\"width\":227,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-775x1024.jpg\",\"width\":775,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-768x1014.jpg\",\"width\":768,\"height\":1014,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-333x440.jpg\",\"width\":333,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-439x580.jpg\",\"width\":439,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-545x720.jpg\",\"width\":545,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-969x1280.jpg\",\"width\":969,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-1454x1920.jpg\",\"width\":1454,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-1163x1536.jpg\",\"width\":1163,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled-1550x2048.jpg\",\"width\":1550,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"Detail_Portal_4__Mai_2019-scaled.jpg\",\"width\":1514,\"height\":2000}},\n\t\t\t\t\"alt\" : \"Hermenpilaster und Adlerkartusche des rekonstruierten barocken Portals V\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"35.36\",\"left\":\"49.68\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:132.10039630119%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a9888790fcf4\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"\" id=\"desc_media_6a9888790fcf4\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Alle ca. 2.800 fig&uuml;rlichen Darstellungen an der rekonstruierten Fassade sind Unikate.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Stephan Falk<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><h5>Wir danken allen Spender*innen!<\/h5>\n<p>Die handwerklich und k\u00fcnstlerisch \u00fcberzeugende Rekonstruktion der barocken Fassaden wurde durch ein breites zivilgesell\u00adschaftliches Engagement, allein durch Spenden, erm\u00f6glicht. In mehreren Portalen des Humboldt Forums wird der zahlreichen Spender*innen aus ganz Deutschland und aller Welt namentlich gedankt. Die aktive Unterst\u00fctzung vom \u201eF\u00f6rderverein Berliner Schloss e.V.\u201c war f\u00fcr den Erfolg der Spendenaktion entscheidend und ma\u00dfgeblich. Mit der Aufstellung von 19 Balustradenfiguren wurde im Sommer 2025 die letzte vom F\u00f6rderverein finanzierte Rekonstruktionsma\u00dfnahme umgesetzt. Der Stiftungsrat der Stiftung Humboldt Forum im Berliner Schloss, der sich aus Vertreter*innen des Bundes, des Landes und der beteiligten Institutionen zusammensetzt, hatte diese 2023 als letzte Ma\u00dfnahme beschlossen. Mit der Rekonstruktion der Schlossfassaden fand die Zusammenarbeit mit dem F\u00f6rderverein ihr planm\u00e4\u00dfiges Ende.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-media\">\n\t\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-12\">\n\t\t\t\t<h5>Dank des Bundespr\u00e4sidenten<\/h5>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-12\">\n\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a98887912061\" aria-labelledby=\"desc_media_6a98887912061\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-300x169.jpg\",\"width\":300,\"height\":169,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-1024x576.jpg\",\"width\":1024,\"height\":576,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-768x432.jpg\",\"width\":768,\"height\":432,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-440x248.jpg\",\"width\":440,\"height\":248,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-580x326.jpg\",\"width\":580,\"height\":326,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-720x405.jpg\",\"width\":720,\"height\":405,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-1280x720.jpg\",\"width\":1280,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"Bundespra\\u0308sident_Steinmeier-1536x864.jpg\",\"width\":1536,\"height\":864,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"Bundespra\\u0308sident_Steinmeier.jpg\",\"width\":1920,\"height\":1080}},\n\t\t\t\t\"alt\" : \"Mann mit Brille im Anzug steht vor einer Fahne und einem Gem\\u00e4lde in einem eleganten Raum.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/\",\n\t\t\t\t\"video\" : \"https:\\\/\\\/www.humboldtforum.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/BuPra\\u0308_Dankesrede-Humboldtforum_1.mp4\",\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"91\",\n\t\t\t\t\"crop\" : {\"top\":\"32.02\",\"left\":\"47.91\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:56.25%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a98887912061\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><div class=\"page\" title=\"Page 4\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<h5>Handwerkliche Pr\u00e4zision<\/h5>\n<p>Bei der Neuerschaffung der Fassaden erbrachten Bildhauer*innen, Gipsformer*innen und Stuckateur*innen Meisterleistungen: Auf Grundlage erhaltener Fragmente, historischer Fotos und der Rekonstruktionspl\u00e4ne von Stuhlemmer Architekten schufen sie u\u0308ber 2.800 Figuren und rund 23.000 Sandsteinelemente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-media\">\n\t\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-10 col-md-6 col-xs-offset-1 col-md-offset-3\">\n\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a98887913f84\" aria-labelledby=\"desc_media_6a98887913f84\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"Schlossbauhuette_short_cover-300x169.jpg\",\"width\":300,\"height\":169,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"Schlossbauhuette_short_cover-1024x576.jpg\",\"width\":1024,\"height\":576,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"Schlossbauhuette_short_cover-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"Schlossbauhuette_short_cover-768x432.jpg\",\"width\":768,\"height\":432,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"Schlossbauhuette_short_cover-440x248.jpg\",\"width\":440,\"height\":248,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"Schlossbauhuette_short_cover-580x326.jpg\",\"width\":580,\"height\":326,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"Schlossbauhuette_short_cover-720x405.jpg\",\"width\":720,\"height\":405,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"Schlossbauhuette_short_cover-1280x720.jpg\",\"width\":1280,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"Schlossbauhuette_short_cover-1920x1081.jpg\",\"width\":1920,\"height\":1081,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"Schlossbauhuette_short_cover-1536x865.jpg\",\"width\":1536,\"height\":865,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"Schlossbauhuette_short_cover-2048x1153.jpg\",\"width\":2048,\"height\":1153,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"Schlossbauhuette_short_cover.jpg\",\"width\":2546,\"height\":1433}},\n\t\t\t\t\"alt\" : \"Detailaufnahme einer Hand, die mit einem Werkzeug an einer Skulptur oder Wand arbeitet.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : \"https:\\\/\\\/www.humboldtforum.org\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Schlossbauhuette_short.mp4\",\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : \"100\",\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:56.284367635507%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a98887913f84\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-standard-two-images \">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-4\">\n\t\t\t\t<div class=\"box first-image\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-20,20]}}'>\n\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a98887916572\" aria-labelledby=\"desc_media_6a98887916572\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00094560-scaled-244x300.jpg\",\"width\":244,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00094560-scaled-833x1024.jpg\",\"width\":833,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00094560-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00094560-scaled-768x944.jpg\",\"width\":768,\"height\":944,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00094560-scaled-358x440.jpg\",\"width\":358,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00094560-scaled-472x580.jpg\",\"width\":472,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00094560-scaled-586x720.jpg\",\"width\":586,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00094560-scaled-1041x1280.jpg\",\"width\":1041,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00094560-scaled-1562x1920.jpg\",\"width\":1562,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00094560-scaled-1249x1536.jpg\",\"width\":1249,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00094560-scaled-1666x2048.jpg\",\"width\":1666,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00094560-scaled.jpg\",\"width\":2082,\"height\":2560}},\n\t\t\t\t\"alt\" : \"Mit Staub \\u00fcberzogene Bildhauerwerkzeuge und Schutzbrille\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"94.12\",\"left\":\"50.00\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:122.95869356388%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a98887916572\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_media_6a98887916572\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Bildhauer-Werkzeuge in der Schlossbauh&uuml;tte.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ David von Becker<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"copy\">\n\t\t\t\t\t<p class=\"Moderation\">Erhaltene originale Fassadenfragmente und historische Unterlagen sowie Fotografien erm\u00f6glichen eine originalgetreue Rekonstruktion des Schlu\u0308ter&#8217;schen Barock.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-xs-12 col-md-8 second-image\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a9888791663a\" aria-labelledby=\"desc_media_6a9888791663a\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00031310_Galerie-scaled-240x300.jpg\",\"width\":240,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031310_Galerie-scaled-819x1024.jpg\",\"width\":819,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031310_Galerie-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031310_Galerie-scaled-768x960.jpg\",\"width\":768,\"height\":960,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031310_Galerie-scaled-352x440.jpg\",\"width\":352,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031310_Galerie-scaled-464x580.jpg\",\"width\":464,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031310_Galerie-scaled-576x720.jpg\",\"width\":576,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031310_Galerie-scaled-1024x1280.jpg\",\"width\":1024,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031310_Galerie-scaled-1536x1920.jpg\",\"width\":1536,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031310_Galerie-scaled-1229x1536.jpg\",\"width\":1229,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031310_Galerie-scaled-1638x2048.jpg\",\"width\":1638,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031310_Galerie-scaled.jpg\",\"width\":2048,\"height\":2560}},\n\t\t\t\t\"alt\" : \"Bildhauer Jake Oakley bei Spachtelarbeiten an einem Tonmodell\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"50.00\",\"left\":\"50.00\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:125%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a9888791663a\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_media_6a9888791663a\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Der Bildhauer Jake Oakley bei Arbeiten an einem Tonmodell, 2013.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Rolf Schulten<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><h5>Vom Steinbruch zur Skulptur<\/h5>\n<p class=\"p1\"><span class=\"s1\">5,80 Meter hoch, 7,30 Meter breit, rund 56 Tonnen schwer \u2013 die gro\u00dfe Eckkartusche ist wohl das k\u00fcnstlerisch und bildhauerisch anspruchsvollste der rekonstruierten Schmuckelemente. Die Fertigstellung der Kartusche hat insgesamt f\u00fcnf Jahre gedauert und steht beispielhaft f\u00fcr die Anfertigung der Sandstein-Elemente der rekonstruierten Barockfassaden.<\/span><\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n\n<section class=\"block block-gallery\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row center-xs\">\n\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t<div class=\"box text-align-left\">\n\t\t\t\t\t<block-gallery inline-template>\n\t\t\t\t\t\t<div :class=\"{ firstLoaded: firstLoaded }\">\n\t\t\t\t\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t\t\t\"images\" : [{\"id\":0,\"width\":1644,\"height\":2138,\"alt\":\"Die gro&szlig;e Wappenkartusche an der Lustgartenfassade\",\"title\":\"\",\"description\":\"\",\"label\":\"Die gro&szlig;e Wappenkartusche an der n&ouml;rdlichen Lustgartenfassade.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Stephan Falk\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00054948-1-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00054948-1-787x1024.jpg\",\"width\":787,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00054948-1-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00054948-1-768x999.jpg\",\"width\":768,\"height\":999,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00054948-1-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00054948-1-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00054948-1-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00054948-1-984x1280.jpg\",\"width\":984,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00054948-1-1476x1920.jpg\",\"width\":1476,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00054948-1-1181x1536.jpg\",\"width\":1181,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00054948-1-1575x2048.jpg\",\"width\":1575,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00054948-1.jpg\",\"width\":1644,\"height\":2138}}},{\"id\":1,\"width\":2560,\"height\":1969,\"alt\":\"Blick in die Bildhauer-Werkstatt, ein Steinbildhauer arbeitet am Tonmodell der Eckkartusche\",\"title\":\"\",\"description\":\"\",\"label\":\"Vor den Steinarbeiten begannen 2012 die Arbeiten an ersten Modellen. Hier wird ein Tonmodell der Eckkartusche im Ma&szlig;stab 1:3 angefertigt.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031400-scaled-300x231.jpg\",\"width\":300,\"height\":231,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031400-scaled-1024x788.jpg\",\"width\":1024,\"height\":788,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031400-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031400-scaled-768x591.jpg\",\"width\":768,\"height\":591,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031400-scaled-440x338.jpg\",\"width\":440,\"height\":338,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031400-scaled-580x446.jpg\",\"width\":580,\"height\":446,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031400-scaled-720x554.jpg\",\"width\":720,\"height\":554,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031400-scaled-1280x985.jpg\",\"width\":1280,\"height\":985,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031400-scaled-1920x1477.jpg\",\"width\":1920,\"height\":1477,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031400-scaled-1536x1181.jpg\",\"width\":1536,\"height\":1181,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031400-scaled-2048x1575.jpg\",\"width\":2048,\"height\":1575,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031400-scaled.jpg\",\"width\":2560,\"height\":1969}}},{\"id\":2,\"width\":1538,\"height\":2000,\"alt\":\"Begutachtung des Gipsmodells der Eckkartusche in Originalgr&ouml;&szlig;e\",\"title\":\"\",\"description\":\"\",\"label\":\"Eine Expertenkommission begleitet die Arbeiten von der Planung bis zu den fertigen Steinelementen. Hier begutachtet die Expertenkommission das fertige Gipsmodell in Originalgr&ouml;&szlig;e.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031434-scaled-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031434-scaled-788x1024.jpg\",\"width\":788,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031434-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031434-scaled-768x999.jpg\",\"width\":768,\"height\":999,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031434-scaled-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031434-scaled-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031434-scaled-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031434-scaled-985x1280.jpg\",\"width\":985,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031434-scaled-1477x1920.jpg\",\"width\":1477,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031434-scaled-1181x1536.jpg\",\"width\":1181,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031434-scaled-1575x2048.jpg\",\"width\":1575,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031434-scaled.jpg\",\"width\":1538,\"height\":2000}}},{\"id\":3,\"width\":2000,\"height\":1539,\"alt\":\"Im Steinbruch werden von einer Baumaschine Sprengl&ouml;cher in den Sandstein gebohrt\",\"title\":\"\",\"description\":\"\",\"label\":\"Der Sandstein f&uuml;r die Eckkartusche stammt aus Sachsen, hier werden im Steinbruch Sprengl&ouml;cher gebohrt.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031368-1-scaled-300x231.jpg\",\"width\":300,\"height\":231,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031368-1-scaled-1024x788.jpg\",\"width\":1024,\"height\":788,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031368-1-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031368-1-scaled-768x591.jpg\",\"width\":768,\"height\":591,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031368-1-scaled-440x339.jpg\",\"width\":440,\"height\":339,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031368-1-scaled-580x446.jpg\",\"width\":580,\"height\":446,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031368-1-scaled-720x554.jpg\",\"width\":720,\"height\":554,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031368-1-scaled-1280x985.jpg\",\"width\":1280,\"height\":985,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031368-1-scaled-1920x1478.jpg\",\"width\":1920,\"height\":1478,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031368-1-scaled-1536x1182.jpg\",\"width\":1536,\"height\":1182,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031368-1-scaled-2048x1576.jpg\",\"width\":2048,\"height\":1576,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031368-1-scaled.jpg\",\"width\":2000,\"height\":1539}}},{\"id\":4,\"width\":1810,\"height\":2353,\"alt\":\"Ein Steinbildhauer arbeitet an einem Puttenkopf mit Hammer und Meisel\",\"title\":\"\",\"description\":\"\",\"label\":\"Nachdem der Sandsteinblock grob ausgefr&auml;st wurde, arbeiten Steinbildhauer die Schmuckelemente fein aus.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031362-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031362-788x1024.jpg\",\"width\":788,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031362-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031362-768x998.jpg\",\"width\":768,\"height\":998,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031362-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031362-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031362-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031362-985x1280.jpg\",\"width\":985,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031362-1477x1920.jpg\",\"width\":1477,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031362-1182x1536.jpg\",\"width\":1182,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031362-1575x2048.jpg\",\"width\":1575,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031362.jpg\",\"width\":1810,\"height\":2353}}},{\"id\":5,\"width\":2560,\"height\":1969,\"alt\":\"Der Sandsteinblock mit einem herausgearbeiteten Putto wird von einem Baukran hochgezogen\",\"title\":\"\",\"description\":\"\",\"label\":\"Die einzelnen Steinelemente sind teils tonnenschwer und werden mit einem Baukran angehoben ...\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031492-scaled-300x231.jpg\",\"width\":300,\"height\":231,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031492-scaled-1024x788.jpg\",\"width\":1024,\"height\":788,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031492-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031492-scaled-768x591.jpg\",\"width\":768,\"height\":591,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031492-scaled-440x338.jpg\",\"width\":440,\"height\":338,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031492-scaled-580x446.jpg\",\"width\":580,\"height\":446,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031492-scaled-720x554.jpg\",\"width\":720,\"height\":554,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031492-scaled-1280x985.jpg\",\"width\":1280,\"height\":985,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031492-scaled-1920x1477.jpg\",\"width\":1920,\"height\":1477,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031492-scaled-1536x1181.jpg\",\"width\":1536,\"height\":1181,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031492-scaled-2048x1575.jpg\",\"width\":2048,\"height\":1575,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031492-scaled.jpg\",\"width\":2560,\"height\":1969}}},{\"id\":6,\"width\":1969,\"height\":2560,\"alt\":\"Der Sandsteinblock mit dem Wappenschild K&ouml;nig Friedrich I. &gt;FR&lt; wird von einem Kran und Bauarbeitern unterhalb der Kuppel eingesetzt\",\"title\":\"\",\"description\":\"\",\"label\":\"... und in etwa 30 Meter H&ouml;he an der Fassade angebracht.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Stephan Falk\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00028980-scaled-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00028980-scaled-788x1024.jpg\",\"width\":788,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00028980-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00028980-scaled-768x999.jpg\",\"width\":768,\"height\":999,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00028980-scaled-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00028980-scaled-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00028980-scaled-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00028980-scaled-985x1280.jpg\",\"width\":985,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00028980-scaled-1477x1920.jpg\",\"width\":1477,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00028980-scaled-1181x1536.jpg\",\"width\":1181,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00028980-scaled-1575x2048.jpg\",\"width\":1575,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00028980-scaled.jpg\",\"width\":1969,\"height\":2560}}},{\"id\":7,\"width\":2560,\"height\":1730,\"alt\":\"Die Hand einer gefl&uuml;gelten Frauenfigur, einer Fama, wird von zwei Helfern vor Ort richtig platziert\",\"title\":\"\",\"description\":\"\",\"label\":\"Das Zusammensetzen der Elemente ist wahre Pr&auml;zisionsarbeit.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Rolf Schulten\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031475-scaled-300x203.jpg\",\"width\":300,\"height\":203,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00031475-scaled-1024x692.jpg\",\"width\":1024,\"height\":692,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031475-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031475-scaled-768x519.jpg\",\"width\":768,\"height\":519,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031475-scaled-440x297.jpg\",\"width\":440,\"height\":297,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031475-scaled-580x392.jpg\",\"width\":580,\"height\":392,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031475-scaled-720x487.jpg\",\"width\":720,\"height\":487,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00031475-scaled-1280x865.jpg\",\"width\":1280,\"height\":865,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00031475-scaled-1920x1298.jpg\",\"width\":1920,\"height\":1298,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00031475-scaled-1536x1038.jpg\",\"width\":1536,\"height\":1038,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00031475-scaled-2048x1384.jpg\",\"width\":2048,\"height\":1384,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031475-scaled.jpg\",\"width\":2560,\"height\":1730}}},{\"id\":8,\"width\":1969,\"height\":2560,\"alt\":\"Die Eckkartusche ist vollst&auml;ndig eingesetzt und verfugt\",\"title\":\"\",\"description\":\"\",\"label\":\"Mit der Verfugung der einzelnen Elemente ist die Eckkartusche nun fast fertig.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00017291-scaled-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00017291-scaled-788x1024.jpg\",\"width\":788,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00017291-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00017291-scaled-768x999.jpg\",\"width\":768,\"height\":999,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00017291-scaled-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00017291-scaled-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00017291-scaled-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00017291-scaled-985x1280.jpg\",\"width\":985,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00017291-scaled-1477x1920.jpg\",\"width\":1477,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00017291-scaled-1181x1536.jpg\",\"width\":1181,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00017291-scaled-1575x2048.jpg\",\"width\":1575,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00017291-scaled.jpg\",\"width\":1969,\"height\":2560}}},{\"id\":9,\"width\":852,\"height\":655,\"alt\":\"Die Initialen der Eckkartusche werden vor Ort vergoldet\",\"title\":\"\",\"description\":\"\",\"label\":\"Zuletzt werden die Initialen der Eckkartusche vergoldet.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Stephan Falk\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00031462-300x231.jpg\",\"width\":300,\"height\":231,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00031462-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00031462-768x590.jpg\",\"width\":768,\"height\":590,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00031462-440x338.jpg\",\"width\":440,\"height\":338,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00031462-580x446.jpg\",\"width\":580,\"height\":446,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00031462-720x554.jpg\",\"width\":720,\"height\":554,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00031462.jpg\",\"width\":852,\"height\":655}}},{\"id\":10,\"width\":1968,\"height\":2560,\"alt\":\"Die fertig angebrachte Eckkartusche aus der Ferne gesehen\",\"title\":\"\",\"description\":\"\",\"label\":\"Seit dem Abbau der Fassadenger&uuml;ste im Fr&uuml;hjahr 2019 ist die Eckkartusche vom Lustgarten aus weithin sichtbar.\",\"copyright\":\"Stiftung Humboldt Forum im Berliner Schloss \\\/ Stephan Falk\",\"path\":\"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\"sizes\":{\"medium\":{\"file\":\"HF_eb00054938-scaled-231x300.jpg\",\"width\":231,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00054938-scaled-787x1024.jpg\",\"width\":787,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00054938-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00054938-scaled-768x999.jpg\",\"width\":768,\"height\":999,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00054938-scaled-338x440.jpg\",\"width\":338,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00054938-scaled-446x580.jpg\",\"width\":446,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00054938-scaled-554x720.jpg\",\"width\":554,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00054938-scaled-984x1280.jpg\",\"width\":984,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00054938-scaled-1476x1920.jpg\",\"width\":1476,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00054938-scaled-1181x1536.jpg\",\"width\":1181,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00054938-scaled-1574x2048.jpg\",\"width\":1574,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00054938-scaled.jpg\",\"width\":1968,\"height\":2560}}}]\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t<\/script>\n\n\t\t\t\t\t\t\t<swiper :options=\"options\" @slide-change=\"track\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" :key=\"image.id\" v-for=\"image in images\">\n\t\t\t\t\t\t\t\t\t<block-gallery-item inline-template :image=\"image\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"swiper-slide-image-wrapper\" ref=\"parent\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"width-container\" ref=\"container\" :style=\"style\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div data-swiper-parallax-x=\"50%\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img :src=\"image.src\" :alt=\"image.alt\" v-if=\"image.id < 2\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" :data-src=\"image.src\" :alt=\"image.alt\" v-else>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/block-gallery-item>\n\n\t\t\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t<div v-if=\"image.label\" v-html=\"image.label\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div v-else-if=\"image.description\" v-html=\"image.description\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\" v-if=\"image.copyright\" v-html=\"'\u00a9 '+image.copyright\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"  slot=\"pagination\"><\/div>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-prev\" slot=\"button-prev\" aria-label=\"Vorheriges Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t\t\t<button class=\"icon-round swiper-button-next\" slot=\"button-next\" aria-label=\"N\u00e4chstes Bild\">\n\t\t\t\t\t\t\t\t\t<span class=\"icon-next\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/swiper>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/block-gallery>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>Die ganze Entstehungsgeschichte der Eckkartusche k\u00f6nnen Sie in unserem Bildband <em><a href=\"https:\/\/www.humboldtforum.org\/de\/publikationen\/\">Barock in Arbeit. Die Kunst der Rekonstruktion<\/a> \u00a0<\/em>nachlesen.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><h5>Die Schlossbauh\u00fctte<\/h5>\n<p class=\"p1\"><span class=\"s1\">Zentrum der Rekonstruktion der barocken Fassade war f\u00fcr \u00fcber zehn Jahre die 2011 gegr\u00fcndete Schlossbauh\u00fctte in Berlin-Spandau. St\u00fcck f\u00fcr St\u00fcck haben hier Bildhauer*innen, Gipsformer*innen und Stuckateur*innen die teils kolossalen Schmuckelemente modelliert, als Gipsabguss hergestellt und anschlie\u00dfend im traditionellen Punktierverfahren in Sandstein gehauen.<\/span><\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-header\" >\n\t<block-header inline-template>\n\t\t<figure role=\"group\" aria-labelledby=\"desc_m_6a9888791f462\">\n\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes_d\" : {\"medium\":{\"file\":\"Schlossbauhuette_DvB__8_-300x191.jpg\",\"width\":300,\"height\":191,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"Schlossbauhuette_DvB__8_-1024x653.jpg\",\"width\":1024,\"height\":653,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"Schlossbauhuette_DvB__8_-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"Schlossbauhuette_DvB__8_-768x490.jpg\",\"width\":768,\"height\":490,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"Schlossbauhuette_DvB__8_-440x281.jpg\",\"width\":440,\"height\":281,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"Schlossbauhuette_DvB__8_-580x370.jpg\",\"width\":580,\"height\":370,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"Schlossbauhuette_DvB__8_-720x459.jpg\",\"width\":720,\"height\":459,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"Schlossbauhuette_DvB__8_-1280x816.jpg\",\"width\":1280,\"height\":816,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"Schlossbauhuette_DvB__8_-1920x1224.jpg\",\"width\":1920,\"height\":1224,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"Schlossbauhuette_DvB__8_-1536x979.jpg\",\"width\":1536,\"height\":979,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"Schlossbauhuette_DvB__8_-2048x1306.jpg\",\"width\":2048,\"height\":1306,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"Schlossbauhuette_DvB__8_.jpg\",\"width\":2560,\"height\":1632}},\n\t\t\t\t\"alt_d\" : \"Blick in die Schlossbauh\\u00fctte mit Sandstein Elementen auf dem Boden\",\n\t\t\t\t\"path_d\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/\",\n\t\t\t\t\"autoplay_d\" : null,\n\t\t\t\t\"crop_d\" : null,\n\t\t\t\t\"background_d\" : true,\n\t\t\t\t\"scale_d\" : 1,\n\n\t\t\t\t\"sizes_m\" : {\"medium\":{\"file\":\"HF_eb00090787-1-scaled-169x300.jpg\",\"width\":169,\"height\":300,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00090787-1-scaled-576x1024.jpg\",\"width\":576,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00090787-1-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00090787-1-scaled-768x1365.jpg\",\"width\":768,\"height\":1365,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00090787-1-scaled-248x440.jpg\",\"width\":248,\"height\":440,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00090787-1-scaled-326x580.jpg\",\"width\":326,\"height\":580,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00090787-1-scaled-405x720.jpg\",\"width\":405,\"height\":720,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00090787-1-scaled-720x1280.jpg\",\"width\":720,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00090787-1-scaled-1080x1920.jpg\",\"width\":1080,\"height\":1920,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00090787-1-scaled-864x1536.jpg\",\"width\":864,\"height\":1536,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00090787-1-scaled-1152x2048.jpg\",\"width\":1152,\"height\":2048,\"mime-type\":\"image\\\/jpeg\"}},\n\t\t\t\t\"alt_m\" : \"Gibsabg\\u00fcsse von Kolossalfiguren in der Schlossbauh\\u00fctte\",\n\t\t\t\t\"path_m\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"autoplay_m\" : null,\n\t\t\t\t\"crop_m\" : {\"top\":\"23.68\",\"left\":\"50.00\"},\n\t\t\t\t\"background_m\" : true,\n\t\t\t\t\"scale_m\" : 2,\n\n\t\t\t\t\"has_mobile_format\" : true,\n\t\t\t\t\"has_ad\" : false,\n\t\t\t\t\"audio_description_yt\" : null\t\t\t\t}\n\t\t\t<\/script>\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:63.75%;\" v-if=\"sizes\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t<lazy-media :inline=\"true\" :scale=\"scale\" :alt=\"alt\" :sizes=\"sizes\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_m_6a9888791f462\"><\/lazy-media>\n\t\t\t\t<button class=\"autoplay-audio-description-btn icon-background icon-audio-describtions\" @click=\"audioDescriptionPlay\" v-if=\"hasAudioDescription\" aria-label=\"Audiodeskription aufrufen\"><\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny insignificant\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Bildinfo<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_m_6a9888791f462\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ David von Becker<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t<\/block-header>\n<\/section>\n\n\n<section class=\"block block-accordion\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t<block-accordion inline-template>\n\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<block-accordion-item inline-template item-headline=\"Mehr zur Schlossbauh\u00fctte\">\n\t\t\t\t\t\t\t\t<div ref=\"item\" data-id=\"MehrzurSchlossbauhtte\" class=\"block-accordion-item vue-initialize\" aria-expanded=\"false\" :aria-expanded=\"active ? 'true' : 'false'\">\n\t\t\t\t\t\t\t\t\t<button class=\"accordion-button-with-icon block-accordion-item-head\" :class=\"{'button-active': active}\" ref=\"head\" aria-controls=\"acc_6a98887927584\" id=\"acc_title_6a98887927585\" @click=\"toggle\" @keydown=\"key\">\n\t\t\t\t\t\t\t\t\t<div><span class=\"button-label\">Mehr zur Schlossbauh\u00fctte<\/span><\/div><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span>\n\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t<div ref=\"body\" class=\"block-accordion-item-content\" id=\"acc_6a98887927584\" role=\"region\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wrapper copy\">\n\t\t\t\t\t\t\t\t\t\t\t<p>Im Sommer 2011 gr\u00fcndete die <a href=\"https:\/\/www.humboldtforum.org\/de\/stiftung-humboldt-forum-im-berliner-schloss\/\">Stiftung Humboldt Forum im Berliner Schloss<\/a> die Schlossbauh\u00fctte mit der Struktur einer klassischen Bauh\u00fctte. Den hierf\u00fcr n\u00f6tigen Raum fand man in einer ehemaligen KFZ-Reparaturhalle der Alliierten in Berlin-Spandau.<\/p>\n<p>Heute hat sich die Bauh\u00fctte zu einem Sammlungsdepot zur Geschichte des Ortes gewandelt. Neben historischen Fragmenten des Schlosses und arch\u00e4ologischen Funden bilden die Modelle, Gipse und Abg\u00fcsse, die die Grundlage der Rekonstruktion darstellten, heute einen wertvollen Schatz. Sie dokumentieren eindrucksvoll die Leistung der Handwerker*innen und K\u00fcnstler*innen bei der Fassadenrekonstruktion f\u00fcr die Zukunft.<\/p>\n<h6><strong>Moderne Handwerkstechnik<\/strong><\/h6>\n<p>Neben den traditionellen Handwerkstechniken finden auch moderne Verfahren und Materialien bei der Modellerstellung Anwendung. So wurden beispielsweise die Teile des am Staatsratsgeb\u00e4ude erhaltenen Portals IV f\u00fcr die Duplizierung mittels 3D-Printing als Modell f\u00fcr die Steinbildhauer gefertigt.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-xs-9 col-md-9\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a98887927bb1\" aria-labelledby=\"desc_media_6a98887927bb1\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"HF_eb00090765-scaled-300x201.jpg\",\"width\":300,\"height\":201,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"HF_eb00090765-scaled-1024x684.jpg\",\"width\":1024,\"height\":684,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"HF_eb00090765-scaled-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"HF_eb00090765-scaled-768x513.jpg\",\"width\":768,\"height\":513,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"HF_eb00090765-scaled-440x294.jpg\",\"width\":440,\"height\":294,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"HF_eb00090765-scaled-580x388.jpg\",\"width\":580,\"height\":388,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"HF_eb00090765-scaled-720x481.jpg\",\"width\":720,\"height\":481,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"HF_eb00090765-scaled-1280x856.jpg\",\"width\":1280,\"height\":856,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"HF_eb00090765-scaled-1920x1283.jpg\",\"width\":1920,\"height\":1283,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"HF_eb00090765-scaled-1536x1027.jpg\",\"width\":1536,\"height\":1027,\"mime-type\":\"image\\\/jpeg\"},\"2048x2048\":{\"file\":\"HF_eb00090765-scaled-2048x1369.jpg\",\"width\":2048,\"height\":1369,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"HF_eb00090765-scaled.jpg\",\"width\":2560,\"height\":1711}},\n\t\t\t\t\"alt\" : \"Skulpturenwerkstatt mit wei\\u00dfen Statuen, Holzboxen und Materialien f\\u00fcr kunsthandwerkliche Arbeiten.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"31.27\",\"left\":\"68.39\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 2\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.8359375%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a98887927bb1\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"\" id=\"desc_media_6a98887927bb1\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Gipsabg&uuml;sse der Kolossalfiguren nach den Originalskulpturen vom Risalit des Gro&szlig;en Treppenhauses im Schl&uuml;terhof.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 SHF \/ David von Becker<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/block-accordion-item>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/block-accordion>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section class=\"block block-teaser col-lane33 \" style=\"\">\n\t\t\t\t\t\t<teaser-lane-with-buttons inline-template tracking-label=\"Ort entdecken\">\n\t\t\t\t<div>\n\t\t\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t\t<div class=\"row middle-xs\">\n\t\t\t\t\t\t\t<div class=\"col-xs-10 col-sm-8\">\n\t\t\t\t\t\t\t\t<h3 class=\"h4 topline\">Ort entdecken<\/h3>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-xs-2 col-sm-4 end-xs margin-bottom-sixth\">\n\t\t\t\t\t\t\t\t<teaser-lane-buttons :visible_prev=\"visible_prev\" :visible_next=\"visible_next\" @prev=\"prev\" @next=\"next\"><\/teaser-lane-buttons>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"teaser-lane-wrapper\">\n\t\t\t\t\t\t<ul class=\"teaser-lane\">\n\t\t\t\t\t\t<li class=\"teaser-lane-slide col-xs-9 col-sm-4 col-padding-remove\">\n\t<div class=\"box\">\n\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/architektur\/\" class=\"teaser teaser-page\">\n\t\t\t<div class=\"teaser-image teaser-image-full footer-gradient\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a98887929a2c\" aria-labelledby=\"desc_media_6a98887929a2c\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00043999-300x209.jpg\",\"width\":300,\"height\":209,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"SHF_eb00043999-1024x712.jpg\",\"width\":1024,\"height\":712,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"SHF_eb00043999-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"SHF_eb00043999-768x534.jpg\",\"width\":768,\"height\":534,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"SHF_eb00043999-440x306.jpg\",\"width\":440,\"height\":306,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"SHF_eb00043999-580x403.jpg\",\"width\":580,\"height\":403,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"SHF_eb00043999-720x501.jpg\",\"width\":720,\"height\":501,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"SHF_eb00043999-1280x890.jpg\",\"width\":1280,\"height\":890,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"SHF_eb00043999-1920x1335.jpg\",\"width\":1920,\"height\":1335,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"SHF_eb00043999-1536x1068.jpg\",\"width\":1536,\"height\":1068,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"SHF_eb00043999.jpg\",\"width\":2000,\"height\":1391}},\n\t\t\t\t\"alt\" : \"Ecke, bei der die moderne auf die barock gestaltete Fassade des Humboldt Forums trifft\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"38.21\",\"left\":\"50.31\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 4\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:69.55%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a98887929a2c\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a98887929a2c\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Moderne trifft Rekonstruktion<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 SHF \/ Stephan Falk<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t\t<div class=\"teaser-header\"><div>\n\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"\">Architektur<\/h4>\n\t\t\t\t\t\t<p class=\"clamp-2 Teaser-copy-small margin-bottom-sixth\">Moderne und Barock<\/p><div class=\"Button ButtonSmall\">Mehr erfahren<\/div>\t\t\t<\/div><\/div>\n\t\t<\/a>\n\t<\/div>\n<\/li><li class=\"teaser-lane-slide col-xs-9 col-sm-4 col-padding-remove\">\n\t<div class=\"box\">\n\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/architektur\/geschichte\/\" class=\"teaser teaser-page\">\n\t\t\t<div class=\"teaser-image teaser-image-full footer-gradient\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a9888792a5ec\" aria-labelledby=\"desc_media_6a9888792a5ec\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00020197-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"SHF_eb00020197-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"SHF_eb00020197-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"SHF_eb00020197-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"SHF_eb00020197-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"SHF_eb00020197-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"SHF_eb00020197-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"SHF_eb00020197-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"SHF_eb00020197-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"SHF_eb00020197-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"SHF_eb00020197.jpg\",\"width\":2000,\"height\":1333}},\n\t\t\t\t\"alt\" : \"Arch\\u00e4ologische Ausgrabung in Berlin, im Hintergrund der Fernsehturm und historische Geb\\u00e4ude sichtbar.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"55.00\",\"left\":\"45.00\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 4\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.65%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a9888792a5ec\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a9888792a5ec\">\n\t\t\t\t\t\t\t\t\t\t\t<div>Ausgrabungen auf dem Schlossareal, 2009.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Steffen Jaenicke<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t\t<div class=\"teaser-header\"><div>\n\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"\">Geschichte<\/h4>\n\t\t\t\t\t\t<p class=\"clamp-2 Teaser-copy-small margin-bottom-sixth\">Vom Mittelalter bis heute \u2013 800 Jahre Geschichte des Ortes<\/p><div class=\"Button ButtonSmall\">Mehr erfahren<\/div>\t\t\t<\/div><\/div>\n\t\t<\/a>\n\t<\/div>\n<\/li><li class=\"teaser-lane-slide col-xs-9 col-sm-4 col-padding-remove\">\n\t<div class=\"box\">\n\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/architektur\/stadtraum\/\" class=\"teaser teaser-page\">\n\t\t\t<div class=\"teaser-image teaser-image-full footer-gradient\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a9888792b1ce\" aria-labelledby=\"desc_media_6a9888792b1ce\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00104189-300x203.jpg\",\"width\":300,\"height\":203,\"mime-type\":\"image\\\/jpeg\"},\"large\":{\"file\":\"SHF_eb00104189-1024x692.jpg\",\"width\":1024,\"height\":692,\"mime-type\":\"image\\\/jpeg\"},\"thumbnail\":{\"file\":\"SHF_eb00104189-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\"},\"medium_large\":{\"file\":\"SHF_eb00104189-768x519.jpg\",\"width\":768,\"height\":519,\"mime-type\":\"image\\\/jpeg\"},\"small\":{\"file\":\"SHF_eb00104189-440x297.jpg\",\"width\":440,\"height\":297,\"mime-type\":\"image\\\/jpeg\"},\"semi\":{\"file\":\"SHF_eb00104189-580x392.jpg\",\"width\":580,\"height\":392,\"mime-type\":\"image\\\/jpeg\"},\"mobile\":{\"file\":\"SHF_eb00104189-720x486.jpg\",\"width\":720,\"height\":486,\"mime-type\":\"image\\\/jpeg\"},\"hd\":{\"file\":\"SHF_eb00104189-1280x865.jpg\",\"width\":1280,\"height\":865,\"mime-type\":\"image\\\/jpeg\"},\"full\":{\"file\":\"SHF_eb00104189-1920x1297.jpg\",\"width\":1920,\"height\":1297,\"mime-type\":\"image\\\/jpeg\"},\"1536x1536\":{\"file\":\"SHF_eb00104189-1536x1038.jpg\",\"width\":1536,\"height\":1038,\"mime-type\":\"image\\\/jpeg\"},\"original\":{\"file\":\"SHF_eb00104189.jpg\",\"width\":2000,\"height\":1351}},\n\t\t\t\t\"alt\" : \"Historisches Geb\\u00e4ude mit Kuppel und Statue, Berliner Fernsehturm im Hintergrund, umgeben von einem Platz.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Video abspielen\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : {\"top\":\"25.00\",\"left\":\"50.00\"},\n\t\t\t\t\"background\" : true,\n\t\t\t\t\"scale\" : 4\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:67.55%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a9888792b1ce\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"sr-only\" ref=\"body\" id=\"desc_media_6a9888792b1ce\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss \/ Christoph Musiol<\/div>\n\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n\t\t\t<\/div>\n\t\t\t<div class=\"teaser-header\"><div>\n\t\t\t\t\n\t\t\t\t\t\t<h4 class=\"\">Stadtr\u00e4ume<\/h4>\n\t\t\t\t\t\t<p class=\"clamp-2 Teaser-copy-small margin-bottom-sixth\">Neue st\u00e4dtische Erlebnisr\u00e4ume<\/p><div class=\"Button ButtonSmall\">Mehr erfahren<\/div>\t\t\t<\/div><\/div>\n\t\t<\/a>\n\t<\/div>\n<\/li><li class=\"teaser-lane-slide col-xs-9 col-sm-4 col-padding-remove\">\n\t<div class=\"box\">\n\t\t<a href=\"https:\/\/www.humboldtforum.org\/de\/architektur\/kunst-am-bau\/\" class=\"teaser teaser-page\">\n\t\t\t<div class=\"teaser-image teaser-image-full footer-gradient\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"teaser-header\"><div>\n\t\t\t\t\n\t\t\t\t\t\t<span class=\"h4 \">Kunst am Bau<\/span>\n\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t<\/a>\n\t<\/div>\n<\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/teaser-lane-with-buttons>\n\t\t\t<\/section>","protected":false},"excerpt":{"rendered":"<p>Drei der barocken Au\u00dfenfassaden des Berliner Schlosses samt der Kuppel und drei der Fassaden des historischen Schl\u00fcterhofes wurden detailgetreu rekonstruiert.<\/p>\n","protected":false},"author":30,"featured_media":2862,"parent":674,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"page-location.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2711","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/pages\/2711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/comments?post=2711"}],"version-history":[{"count":11,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/pages\/2711\/revisions"}],"predecessor-version":[{"id":169969,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/pages\/2711\/revisions\/169969"}],"up":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/pages\/674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media\/2862"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/de\/wp-json\/wp\/v2\/media?parent=2711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}