{"id":45215,"date":"2022-07-04T08:30:00","date_gmt":"2022-07-04T06:30:00","guid":{"rendered":"https:\/\/www.humboldtforum.org\/?post_type=pressstatement&#038;p=45215"},"modified":"2022-07-28T13:30:16","modified_gmt":"2022-07-28T11:30:16","slug":"durchluften-open-air-in-the-schluter-courtyard","status":"publish","type":"pressstatement","link":"https:\/\/www.humboldtforum.org\/en\/presse\/mitteilungen\/durchluften-open-air-in-the-schluter-courtyard\/","title":{"rendered":"Durchl\u00fcften &#8211; Open Air in the Schl\u00fcter Courtyard"},"content":{"rendered":"<section class=\"block block-header\" >\n\t<block-header inline-template>\n\t\t<figure role=\"group\" aria-labelledby=\"desc_m_6a56f29cdbb76\">\n\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes_d\" : {\"medium\":{\"file\":\"SHF_eb00137761-300x180.jpg\",\"width\":300,\"height\":180,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7907},\"large\":{\"file\":\"SHF_eb00137761-1024x614.jpg\",\"width\":1024,\"height\":614,\"mime-type\":\"image\\\/jpeg\",\"filesize\":45399},\"thumbnail\":{\"file\":\"SHF_eb00137761-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":5648},\"medium_large\":{\"file\":\"SHF_eb00137761-768x460.jpg\",\"width\":768,\"height\":460,\"mime-type\":\"image\\\/jpeg\",\"filesize\":29677},\"small\":{\"file\":\"SHF_eb00137761-440x264.jpg\",\"width\":440,\"height\":264,\"mime-type\":\"image\\\/jpeg\",\"filesize\":13409},\"semi\":{\"file\":\"SHF_eb00137761-580x348.jpg\",\"width\":580,\"height\":348,\"mime-type\":\"image\\\/jpeg\",\"filesize\":19702},\"mobile\":{\"file\":\"SHF_eb00137761-720x431.jpg\",\"width\":720,\"height\":431,\"mime-type\":\"image\\\/jpeg\",\"filesize\":27012},\"original\":{\"file\":\"SHF_eb00137761.jpg\",\"width\":1280,\"height\":767}},\n\t\t\t\t\"alt_d\" : \"Six people and a dog joyfully jump in a light blue sky with clouds, surrounded by a white square.\",\n\t\t\t\t\"path_d\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"autoplay_d\" : null,\n\t\t\t\t\"crop_d\" : null,\n\t\t\t\t\"background_d\" : true,\n\t\t\t\t\"scale_d\" : 1,\n\n\t\t\t\t\"sizes_m\" : [],\n\t\t\t\t\"alt_m\" : null,\n\t\t\t\t\"path_m\" : null,\n\t\t\t\t\"autoplay_m\" : null,\n\t\t\t\t\"crop_m\" : null,\n\t\t\t\t\"background_m\" : true,\n\t\t\t\t\"scale_m\" : 1,\n\n\t\t\t\t\"has_mobile_format\" : false,\n\t\t\t\t\"has_ad\" : false,\n\t\t\t\t\"audio_description_yt\" : null\t\t\t\t}\n\t\t\t<\/script>\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:59.921875%;\" v-if=\"sizes\" data-motion-parallax='{\"child\":\".image-wrapper\",\"mask\":\".lazy-media\",\"tween\":{\"yPercent\": [-15,15]}}'>\n\t\t\t\t<lazy-media :inline=\"true\" :scale=\"scale\" :alt=\"alt\" :sizes=\"sizes\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_m_6a56f29cdbb76\"><\/lazy-media>\n\t\t\t\t<button class=\"autoplay-audio-description-btn icon-background icon-audio-describtions\" @click=\"audioDescriptionPlay\" v-if=\"hasAudioDescription\" aria-label=\"Audiodeskription aufrufen\"><\/button>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"lazy-media-info-container-fluid\">\n\t\t\t\t<div class=\"lazy-media-info-row end-xs\">\n\t\t\t\t\t<div class=\"lazy-media-info-col\">\n\t\t\t\t\t\t<div class=\"lazy-media-info\" aria-expanded=\"false\" :aria-expanded=\"isOpen ? 'true' : 'false'\">\n\t\t\t\t\t\t\t<button class=\"lazy-media-info-head button-tiny insignificant\" :class=\"{'button-active': isOpen}\" @click=\"toggle\" ref=\"head\"><span class=\"button-label insignificant\">Image info<\/span><\/button>\n\t\t\t\t\t\t\t<figcaption class=\"lazy-media-info-body\" ref=\"body\" id=\"desc_m_6a56f29cdbb76\">\n\t\t\t\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t<div>Durchl&uuml;ften 2022<\/div>\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Stiftung Humboldt Forum im Berliner Schloss; Getty Images \/ Jose A. Bernat Bacete; Kerstin Benz Fotografie; Angelo Cavalli; Tom Werner; Erik Von Weber; Westend61<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t<div class=\"lazy-media-info-head-border\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/figure>\n\t<\/block-header>\n<\/section>\n\n<section class=\"block block-header-headline hyph-disable\" >\n    <div class=\"container-fluid\">\n        <div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<div class=\"subline\">PRESS RELEASE | 04. July 2022<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n                            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                    <div class=\"box\">\n                        <h1>Durchl\u00fcften &#8211; Open Air in the Schl\u00fcter Courtyard<\/h1>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n\n<section class=\"block block-copy\" >\n    <div class=\"container-fluid\">\n\t\t<div class=\"row \">\n            <div class=\"col-xs-12 col-md-offset-2 col-md-8\">\n                <div class=\"box\">\n                    <div class=\"copy\"><p>The second edition of our open air summer festival will take place in the Schl\u00fcter Courtyard over a series of four weekends this summer, with free entry. Between 28 July and 20 August, there will be an alternating programme of 12 international music events and family activities. This year, the focus will be on civil and artistic protest. Further highlights include: the German premiere of City Horses as part of the Dance in August event, and the films, This Is Not A Burial, it&#8217;s a Resurrection by Jeremiah Lemohang Mosese, and Love, D-Mark and Death by Cem Kaya, as well as talks with the Norient-Panel and the Syrian Cassette Archive.<\/p>\n<\/div>\n                <\/div>\n            <\/div>\n\t\t<\/div>\n\t\t    <\/div>\n<\/section>\n\n<section class=\"block block-headline block-no-margin  hyph-disable\" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h3\">PDF<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n\n<section class=\"block block-press-image-select\">\n\t\t\t<div class=\"container-fluid\">\n\t\t\t\t\t\t\t<div class=\"row pdf-row\">\n\t\t\t\t\t<div class=\"block-press-item col-xs-12\">\n\t\t\t\t\t\t<div class=\"box pdf-row-box\">\n\t\t\t\t\t\t\t<h5>Airing Out &#8211; Open Air in the Schl\u00fcterhof<\/h5>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"subline insignificant\">Press Release I Stiftung Humboldt Forum im Berliner Schloss I 8 July 2021<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pdf-row-icons\">\n\t\t\t\t\t\t\t\t<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"46626\",\n\"type\" : \"pdf\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Airing Out - Open Air in the Schl\\u00fcterhof\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.humboldtforum.org\/wp-content\/uploads\/2022\/07\/20220624_PM_Durchlueften_EN.pdf\" target=\"_blank\" role=\"button\" class=\"button-with-icon\"><span class=\"button-icon icon-download\" aria-hidden=\"true\"><\/span><span class=\"button-label\">Download<\/span><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n<section class=\"block block-headline block-no-margin  hyph-disable\" >\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-xs-12\">\n\t\t\t\t\t<div class=\"box\">\n\t\t\t\t\t\t<h2 class=\".h3\">Bilder<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n\n\n<section class=\"block block-press-image-select\">\n\t\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce6645\" aria-labelledby=\"desc_media_6a56f29ce6645\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136586-1-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":23495},\"large\":{\"file\":\"SHF_eb00136586-1-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":184546},\"thumbnail\":{\"file\":\"SHF_eb00136586-1-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":10030},\"medium_large\":{\"file\":\"SHF_eb00136586-1-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":116117},\"small\":{\"file\":\"SHF_eb00136586-1-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":44997},\"semi\":{\"file\":\"SHF_eb00136586-1-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":72834},\"mobile\":{\"file\":\"SHF_eb00136586-1-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":104117},\"original\":{\"file\":\"SHF_eb00136586-1.jpg\",\"width\":1280,\"height\":853}},\n\t\t\t\t\"alt\" : \"Four musicians pose against a colorful background, one playing a self-made instrument.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.640625%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce6645\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce6645\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Bab L&#039; Bluz<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Bab L&#8217; Bluz<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45224\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Bab L' Bluz\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce69e2\" aria-labelledby=\"desc_media_6a56f29ce69e2\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00137863-2-300x284.jpg\",\"width\":300,\"height\":284,\"mime-type\":\"image\\\/jpeg\",\"filesize\":20719},\"large\":{\"file\":\"SHF_eb00137863-2-1024x969.jpg\",\"width\":1024,\"height\":969,\"mime-type\":\"image\\\/jpeg\",\"filesize\":144509},\"thumbnail\":{\"file\":\"SHF_eb00137863-2-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7151},\"medium_large\":{\"file\":\"SHF_eb00137863-2-768x727.jpg\",\"width\":768,\"height\":727,\"mime-type\":\"image\\\/jpeg\",\"filesize\":92726},\"small\":{\"file\":\"SHF_eb00137863-2-440x416.jpg\",\"width\":440,\"height\":416,\"mime-type\":\"image\\\/jpeg\",\"filesize\":38114},\"semi\":{\"file\":\"SHF_eb00137863-2-580x549.jpg\",\"width\":580,\"height\":549,\"mime-type\":\"image\\\/jpeg\",\"filesize\":59762},\"mobile\":{\"file\":\"SHF_eb00137863-2-720x681.jpg\",\"width\":720,\"height\":681,\"mime-type\":\"image\\\/jpeg\",\"filesize\":83594},\"original\":{\"file\":\"SHF_eb00137863-2.jpg\",\"width\":1280,\"height\":1211}},\n\t\t\t\t\"alt\" : \"A man with a guitar sits in a modern room, surrounded by plants and a bookshelf, reflecting the city life outside.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:94.609375%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce69e2\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce69e2\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Lucas Santtana<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Flora Negri<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45234\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Lucas Santtana\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce6cc9\" aria-labelledby=\"desc_media_6a56f29ce6cc9\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136600-1-199x300.jpg\",\"width\":199,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":12753},\"large\":{\"file\":\"SHF_eb00136600-1-679x1024.jpg\",\"width\":679,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":91947},\"thumbnail\":{\"file\":\"SHF_eb00136600-1-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":6586},\"medium_large\":{\"file\":\"SHF_eb00136600-1-768x1158.jpg\",\"width\":768,\"height\":1158,\"mime-type\":\"image\\\/jpeg\",\"filesize\":116211},\"small\":{\"file\":\"SHF_eb00136600-1-292x440.jpg\",\"width\":292,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":22147},\"semi\":{\"file\":\"SHF_eb00136600-1-385x580.jpg\",\"width\":385,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":34260},\"mobile\":{\"file\":\"SHF_eb00136600-1-478x720.jpg\",\"width\":478,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":48221},\"original\":{\"file\":\"SHF_eb00136600-1.jpg\",\"width\":849,\"height\":1280}},\n\t\t\t\t\"alt\" : \"A man with braids and a faux fur collar poses thoughtfully against a picturesque background.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:150.765606596%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce6cc9\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce6cc9\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Noah Slee<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Noah Slee<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45232\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Noah Slee\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce6f34\" aria-labelledby=\"desc_media_6a56f29ce6f34\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136593-1-300x300.jpg\",\"width\":300,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":11799},\"large\":{\"file\":\"SHF_eb00136593-1-1022x1024.jpg\",\"width\":1022,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":88696},\"thumbnail\":{\"file\":\"SHF_eb00136593-1-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":4585},\"medium_large\":{\"file\":\"SHF_eb00136593-1-768x769.jpg\",\"width\":768,\"height\":769,\"mime-type\":\"image\\\/jpeg\",\"filesize\":51770},\"small\":{\"file\":\"SHF_eb00136593-1-440x440.jpg\",\"width\":440,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":21155},\"semi\":{\"file\":\"SHF_eb00136593-1-580x580.jpg\",\"width\":580,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":32981},\"mobile\":{\"file\":\"SHF_eb00136593-1-720x720.jpg\",\"width\":720,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":46184},\"original\":{\"file\":\"SHF_eb00136593-1.jpg\",\"width\":1278,\"height\":1280}},\n\t\t\t\t\"alt\" : \"Five people stand on stairs, posing for a photo in a monochrome style.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:100.15649452269%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce6f34\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce6f34\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Ozan Ata Canani &amp; Karaba<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Sebastian Kempff<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45230\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Ozan Ata Canani & Karaba\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce7194\" aria-labelledby=\"desc_media_6a56f29ce7194\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136592-213x300.jpg\",\"width\":213,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":16498},\"large\":{\"file\":\"SHF_eb00136592-726x1024.jpg\",\"width\":726,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":94743},\"thumbnail\":{\"file\":\"SHF_eb00136592-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":7046},\"medium_large\":{\"file\":\"SHF_eb00136592-768x1083.jpg\",\"width\":768,\"height\":1083,\"mime-type\":\"image\\\/jpeg\",\"filesize\":104610},\"small\":{\"file\":\"SHF_eb00136592-312x440.jpg\",\"width\":312,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":28844},\"semi\":{\"file\":\"SHF_eb00136592-411x580.jpg\",\"width\":411,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":42484},\"mobile\":{\"file\":\"SHF_eb00136592-511x720.jpg\",\"width\":511,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":56594},\"original\":{\"file\":\"SHF_eb00136592.jpg\",\"width\":908,\"height\":1280}},\n\t\t\t\t\"alt\" : \"Movie poster featuring a cube and geometric symbols on a red background, title: \\\"Ask Mark \\u00d6l\\u00fcm.\\\"\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:140.96916299559%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce7194\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce7194\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Poster for the documentary film &quot;A\u015fk, Mark ve &Ouml;l&uuml;m. Love, Deutschmarks and Death&quot; (2022) from Cem Kaya<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Cem Kaya<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45228\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Poster for the documentary film \\\"A\\u015fk, Mark ve \\u00d6l\\u00fcm. Love, Deutschmarks and Death\\\" (2022) from Cem Kaya\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce73f6\" aria-labelledby=\"desc_media_6a56f29ce73f6\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136591-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":21002},\"large\":{\"file\":\"SHF_eb00136591-1024x682.jpg\",\"width\":1024,\"height\":682,\"mime-type\":\"image\\\/jpeg\",\"filesize\":170051},\"thumbnail\":{\"file\":\"SHF_eb00136591-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":8469},\"medium_large\":{\"file\":\"SHF_eb00136591-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":108090},\"small\":{\"file\":\"SHF_eb00136591-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":42042},\"semi\":{\"file\":\"SHF_eb00136591-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":68769},\"mobile\":{\"file\":\"SHF_eb00136591-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":97193},\"original\":{\"file\":\"SHF_eb00136591.jpg\",\"width\":1280,\"height\":853}},\n\t\t\t\t\"alt\" : \"A group of five people stands in a greenhouse with plants, visible through transparent glass panes.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.640625%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce73f6\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce73f6\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Ganna Gryniva and Band <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Dovile Sermokas<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45226\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Ganna Gryniva and Band \"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce75f2\" aria-labelledby=\"desc_media_6a56f29ce75f2\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136583-3-199x300.jpg\",\"width\":199,\"height\":300,\"mime-type\":\"image\\\/jpeg\",\"filesize\":5856},\"large\":{\"file\":\"SHF_eb00136583-3-678x1024.jpg\",\"width\":678,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":40465},\"thumbnail\":{\"file\":\"SHF_eb00136583-3-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":3643},\"medium_large\":{\"file\":\"SHF_eb00136583-3-768x1159.jpg\",\"width\":768,\"height\":1159,\"mime-type\":\"image\\\/jpeg\",\"filesize\":51462},\"small\":{\"file\":\"SHF_eb00136583-3-292x440.jpg\",\"width\":292,\"height\":440,\"mime-type\":\"image\\\/jpeg\",\"filesize\":10000},\"semi\":{\"file\":\"SHF_eb00136583-3-384x580.jpg\",\"width\":384,\"height\":580,\"mime-type\":\"image\\\/jpeg\",\"filesize\":14689},\"mobile\":{\"file\":\"SHF_eb00136583-3-477x720.jpg\",\"width\":477,\"height\":720,\"mime-type\":\"image\\\/jpeg\",\"filesize\":20834},\"original\":{\"file\":\"SHF_eb00136583-3.jpg\",\"width\":848,\"height\":1280}},\n\t\t\t\t\"alt\" : \"Person with folded hands and dark clothing in front of a softly lit red background.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:150.94339622642%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce75f2\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce75f2\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>L.A. Salami alias Lookman Adekunle Salami<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Yukitaka Amemiya<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45222\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"L.A. Salami alias Lookman Adekunle Salami\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"block-press-item col-xs-6 col-md-3\">\n\t\t\t\t<div class=\"box\">\n\t\t\t\t\n\t<lazy-media-inline inline-template>\n\t\t<figure itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"lazy-media-inline \" role=\"group\" id=\"media_6a56f29ce782f\" aria-labelledby=\"desc_media_6a56f29ce782f\">\n\t\t\t<script type=\"application\/json\" ref=\"data\">\n\t\t\t\t{\n\t\t\t\t\"sizes\" : {\"medium\":{\"file\":\"SHF_eb00136588-300x200.jpg\",\"width\":300,\"height\":200,\"mime-type\":\"image\\\/jpeg\",\"filesize\":11292},\"large\":{\"file\":\"SHF_eb00136588-1024x683.jpg\",\"width\":1024,\"height\":683,\"mime-type\":\"image\\\/jpeg\",\"filesize\":66636},\"thumbnail\":{\"file\":\"SHF_eb00136588-150x150.jpg\",\"width\":150,\"height\":150,\"mime-type\":\"image\\\/jpeg\",\"filesize\":5769},\"medium_large\":{\"file\":\"SHF_eb00136588-768x512.jpg\",\"width\":768,\"height\":512,\"mime-type\":\"image\\\/jpeg\",\"filesize\":43206},\"small\":{\"file\":\"SHF_eb00136588-440x293.jpg\",\"width\":440,\"height\":293,\"mime-type\":\"image\\\/jpeg\",\"filesize\":19447},\"semi\":{\"file\":\"SHF_eb00136588-580x387.jpg\",\"width\":580,\"height\":387,\"mime-type\":\"image\\\/jpeg\",\"filesize\":29074},\"mobile\":{\"file\":\"SHF_eb00136588-720x480.jpg\",\"width\":720,\"height\":480,\"mime-type\":\"image\\\/jpeg\",\"filesize\":39199},\"hd\":{\"file\":\"SHF_eb00136588-1280x853.jpg\",\"width\":1280,\"height\":853,\"mime-type\":\"image\\\/jpeg\",\"filesize\":94444},\"full\":{\"file\":\"SHF_eb00136588-1920x1280.jpg\",\"width\":1920,\"height\":1280,\"mime-type\":\"image\\\/jpeg\",\"filesize\":185565},\"1536x1536\":{\"file\":\"SHF_eb00136588-1536x1024.jpg\",\"width\":1536,\"height\":1024,\"mime-type\":\"image\\\/jpeg\",\"filesize\":125986},\"2048x2048\":{\"file\":\"SHF_eb00136588-2048x1365.jpg\",\"width\":2048,\"height\":1365,\"mime-type\":\"image\\\/jpeg\",\"filesize\":208476},\"original\":{\"file\":\"SHF_eb00136588.jpg\",\"width\":3000,\"height\":2000}},\n\t\t\t\t\"alt\" : \"Woman in colorful headdress and white dress against a historic backdrop of red rooftops.\",\n\t\t\t\t\"path\" : \"\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/\",\n\t\t\t\t\"video\" : null,\n\t\t\t\t\"autoplay\" : null,\n\t\t\t\t\"youtube\" : null,\n\t\t\t\t\"youtubelabel\" : \"Play video\",\n\t\t\t\t\"brightness\" : 100,\n\t\t\t\t\"crop\" : null,\n\t\t\t\t\"background\" : false,\n\t\t\t\t\"scale\" : 1\t\t\t\t}\n\t\t\t<\/script>\n\n\t\t\t<div class=\"height-container\" style=\"padding-bottom:66.666666666667%;\" v-if=\"sizes\">\n\t\t\t\t\t\t\t\t<lazy-media :inline=\"true\" :alt=\"alt\" :sizes=\"sizes\" :scale=\"scale\" :brightness=\"brightness\" :path=\"path\" :video=\"video\" :autoplay=\"autoplay\" :youtube=\"youtube\" :crop=\"crop\" :youtubelabel=\"youtubelabel\" :background=\"background\" media-id=\"desc_media_6a56f29ce782f\"><\/lazy-media>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<figcaption class=\"lazy-info-margin-exception\" id=\"desc_media_6a56f29ce782f\">\n\t\t\t\t\t<div class=\"lazy-media-info-body-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>Ganna Gryniva<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"insignificant\">\u00a9 Tanya Vilchynska<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t<\/figure>\n\t<\/lazy-media-inline>\n<press-shopping-cart-inline inline-template>\n\t<div class=\"press-shopping-cart-inline\"  v-bind:class=\"{ 'isNotSelected': !isSelected, 'isSelected': isSelected }\">\n\t\t<script type=\"application\/json\" ref=\"data\">\n{\n\"id\" : \"45910\",\n\"type\" : \"image\",\n\"snackbar_added\" : \"Added to downloads\",\n\"snackbar_removed\" : \"Deleted from download basket\",\n\"snackbar_link\" : \"https:\/\/www.humboldtforum.org\/en\/press\/download\/\",\n\"additional_data\" : null,\n\"name\" : \"Ganna Gryniva\"}\n\t\t<\/script>\n\t\t<div class=\"vue-initialize\" ref=\"item\">\n\t\t\t<button class=\"button-with-icon\" :class=\"{hidden:isSelected}\" @click=\"add\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add to downloads<\/span><\/button>\n\t\t\t<button class=\"button-with-icon rem\" :class=\"{hidden:!isSelected}\" @click=\"remove\"><span class=\"button-icon icon-close\" aria-hidden=\"true\"><\/span><span class=\"button-label\">remove from downloads<\/span><\/button>\n\t\t<\/div>\n\t<\/div>\n<\/press-shopping-cart-inline>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/section>\n\n\n\n\n\n<section class=\"block block-button\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"block-press-item col-xs\">\n\t\t\t\t<div class=\"box center-xs\">\n\t\t\t\t\t<block-press-download-button inline-template>\n\t\t\t\t\t\t<button class=\"button-with-icon border\" @click=\"addAll\"><span class=\"button-icon icon-plus\" aria-hidden=\"true\"><\/span><span class=\"button-label\">add all to downloads<\/span><\/button>\n\t\t\t\t\t<\/block-press-download-button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>The second edition of our open air summer festival will take place in the Schl\u00fcter Courtyard over a series of four weekends this summer, with free entry<\/p>\n","protected":false},"featured_media":45245,"template":"","class_list":["post-45215","pressstatement","type-pressstatement","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/pressstatement\/45215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/pressstatement"}],"about":[{"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/types\/pressstatement"}],"version-history":[{"count":3,"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/pressstatement\/45215\/revisions"}],"predecessor-version":[{"id":46634,"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/pressstatement\/45215\/revisions\/46634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/media\/45245"}],"wp:attachment":[{"href":"https:\/\/www.humboldtforum.org\/en\/wp-json\/wp\/v2\/media?parent=45215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}